{"id":12,"count":42,"description":"","link":"https:\/\/www.time2plug.com\/page\/category\/hotels\/","name":"H\u00f4tels","slug":"hotels","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archives des H\u00f4tels | Time2plug<\/title>\n<meta name=\"description\" content=\"Retrouvez toutes les informations n\u00e9cessaires \u00e0 l&#039;installation, la gestion et la maintenance des bornes de recharge pour votre h\u00f4tel.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.time2plug.com\/page\/category\/hotels\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des H\u00f4tels | Time2plug\" \/>\n<meta property=\"og:description\" content=\"Retrouvez toutes les informations n\u00e9cessaires \u00e0 l&#039;installation, la gestion et la maintenance des bornes de recharge pour votre h\u00f4tel.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.time2plug.com\/page\/category\/hotels\/\" \/>\n<meta property=\"og:site_name\" content=\"Time2plug\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/04\/T2P-Blanc_Background-Orange.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/category\\\/hotels\\\/\",\"url\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/category\\\/hotels\\\/\",\"name\":\"Archives des H\u00f4tels | Time2plug\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/#website\"},\"description\":\"Retrouvez toutes les informations n\u00e9cessaires \u00e0 l'installation, la gestion et la maintenance des bornes de recharge pour votre h\u00f4tel.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/category\\\/hotels\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/category\\\/hotels\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"H\u00f4tels\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/#website\",\"url\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/\",\"name\":\"Time2plug\",\"description\":\"Installation et gestion de bornes recharge pour voitures \u00e9lectriques\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/#organization\"},\"alternateName\":\"Bornes de recharge pour voitures \u00e9lectriques\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/#organization\",\"name\":\"Time2plug\",\"alternateName\":\"Bornes de recharge pour voitures \u00e9lectriques\",\"url\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/T2P-Blanc_Background-Orange.png\",\"contentUrl\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/T2P-Blanc_Background-Orange.png\",\"width\":300,\"height\":300,\"caption\":\"Time2plug\"},\"image\":{\"@id\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/time2plug\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des H\u00f4tels | Time2plug","description":"Retrouvez toutes les informations n\u00e9cessaires \u00e0 l'installation, la gestion et la maintenance des bornes de recharge pour votre h\u00f4tel.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.time2plug.com\/page\/category\/hotels\/","og_locale":"fr_FR","og_type":"article","og_title":"Archives des H\u00f4tels | Time2plug","og_description":"Retrouvez toutes les informations n\u00e9cessaires \u00e0 l'installation, la gestion et la maintenance des bornes de recharge pour votre h\u00f4tel.","og_url":"https:\/\/www.time2plug.com\/page\/category\/hotels\/","og_site_name":"Time2plug","og_image":[{"width":300,"height":300,"url":"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/04\/T2P-Blanc_Background-Orange.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.time2plug.com\/page\/category\/hotels\/","url":"https:\/\/www.time2plug.com\/page\/category\/hotels\/","name":"Archives des H\u00f4tels | Time2plug","isPartOf":{"@id":"https:\/\/www.time2plug.com\/page\/#website"},"description":"Retrouvez toutes les informations n\u00e9cessaires \u00e0 l'installation, la gestion et la maintenance des bornes de recharge pour votre h\u00f4tel.","breadcrumb":{"@id":"https:\/\/www.time2plug.com\/page\/category\/hotels\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.time2plug.com\/page\/category\/hotels\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.time2plug.com\/page\/"},{"@type":"ListItem","position":2,"name":"H\u00f4tels"}]},{"@type":"WebSite","@id":"https:\/\/www.time2plug.com\/page\/#website","url":"https:\/\/www.time2plug.com\/page\/","name":"Time2plug","description":"Installation et gestion de bornes recharge pour voitures \u00e9lectriques","publisher":{"@id":"https:\/\/www.time2plug.com\/page\/#organization"},"alternateName":"Bornes de recharge pour voitures \u00e9lectriques","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.time2plug.com\/page\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.time2plug.com\/page\/#organization","name":"Time2plug","alternateName":"Bornes de recharge pour voitures \u00e9lectriques","url":"https:\/\/www.time2plug.com\/page\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.time2plug.com\/page\/#\/schema\/logo\/image\/","url":"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/04\/T2P-Blanc_Background-Orange.png","contentUrl":"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/04\/T2P-Blanc_Background-Orange.png","width":300,"height":300,"caption":"Time2plug"},"image":{"@id":"https:\/\/www.time2plug.com\/page\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/time2plug\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.time2plug.com\/page\/wp-json\/wp\/v2\/categories\/12","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.time2plug.com\/page\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.time2plug.com\/page\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.time2plug.com\/page\/wp-json\/wp\/v2\/posts?categories=12"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}