{"id":12685,"date":"2024-06-24T15:28:17","date_gmt":"2024-06-24T13:28:17","guid":{"rendered":"https:\/\/www.time2plug.com\/page\/?page_id=12685"},"modified":"2025-02-27T14:36:57","modified_gmt":"2025-02-27T13:36:57","slug":"devenir-un-installateur-partenaire","status":"publish","type":"page","link":"https:\/\/www.time2plug.com\/page\/devenir-un-installateur-partenaire\/","title":{"rendered":"Devenir un installateur partenaire"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"12685\" class=\"elementor elementor-12685\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<header class=\"elementor-section elementor-top-section elementor-element elementor-element-2b69ac0 elementor-section-height-min-height elementor-hidden-mobile elementor-section-full_width elementor-section-stretched elementor-section-items-bottom elementor-section-height-default\" data-id=\"2b69ac0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_start&quot;:0,&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;shape_divider_bottom&quot;:&quot;mountains&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" opacity=\"0.33\" d=\"M473,67.3c-203.9,88.3-263.1-34-320.3,0C66,119.1,0,59.7,0,59.7V0h1000v59.7 c0,0-62.1,26.1-94.9,29.3c-32.8,3.3-62.8-12.3-75.8-22.1C806,49.6,745.3,8.7,694.9,4.7S492.4,59,473,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" opacity=\"0.66\" d=\"M734,67.3c-45.5,0-77.2-23.2-129.1-39.1c-28.6-8.7-150.3-10.1-254,39.1 s-91.7-34.4-149.2,0C115.7,118.3,0,39.8,0,39.8V0h1000v36.5c0,0-28.2-18.5-92.1-18.5C810.2,18.1,775.7,67.3,734,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M766.1,28.9c-200-57.5-266,65.5-395.1,19.5C242,1.8,242,5.4,184.8,20.6C128,35.8,132.3,44.9,89.9,52.5C28.6,63.7,0,0,0,0 h1000c0,0-9.9,40.9-83.6,48.1S829.6,47,766.1,28.9z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-be6585d\" data-id=\"be6585d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f91214d elementor-widget elementor-widget-heading\" data-id=\"f91214d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Devenir un installateur partenaire <\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c1ca254 elementor-hidden-tablet elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default\" data-id=\"c1ca254\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4167b83\" data-id=\"4167b83\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/header>\n\t\t\t\t<header class=\"elementor-section elementor-top-section elementor-element elementor-element-dae57d6 elementor-section-height-full elementor-section-full_width elementor-section-stretched elementor-section-items-bottom elementor-hidden-desktop elementor-hidden-tablet elementor-section-height-default\" data-id=\"dae57d6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_start&quot;:0,&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;shape_divider_bottom&quot;:&quot;mountains&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" opacity=\"0.33\" d=\"M473,67.3c-203.9,88.3-263.1-34-320.3,0C66,119.1,0,59.7,0,59.7V0h1000v59.7 c0,0-62.1,26.1-94.9,29.3c-32.8,3.3-62.8-12.3-75.8-22.1C806,49.6,745.3,8.7,694.9,4.7S492.4,59,473,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" opacity=\"0.66\" d=\"M734,67.3c-45.5,0-77.2-23.2-129.1-39.1c-28.6-8.7-150.3-10.1-254,39.1 s-91.7-34.4-149.2,0C115.7,118.3,0,39.8,0,39.8V0h1000v36.5c0,0-28.2-18.5-92.1-18.5C810.2,18.1,775.7,67.3,734,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M766.1,28.9c-200-57.5-266,65.5-395.1,19.5C242,1.8,242,5.4,184.8,20.6C128,35.8,132.3,44.9,89.9,52.5C28.6,63.7,0,0,0,0 h1000c0,0-9.9,40.9-83.6,48.1S829.6,47,766.1,28.9z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c221f4e\" data-id=\"c221f4e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4fd660a elementor-widget elementor-widget-heading\" data-id=\"4fd660a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Devenir un installateur partenaire <\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e7f8bad elementor-hidden-tablet elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default\" data-id=\"e7f8bad\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-38f0c12\" data-id=\"38f0c12\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/header>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5ca5914 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"5ca5914\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-16bfb18\" data-id=\"16bfb18\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ebcccf4 elementor-widget elementor-widget-breadcrumbs\" data-id=\"ebcccf4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<nav id=\"breadcrumbs\"><span><span><a href=\"https:\/\/www.time2plug.com\/page\/\">Accueil<\/a><\/span><\/span><\/nav>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8b7c8cc elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"8b7c8cc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c2a00f3\" data-id=\"c2a00f3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-340784f elementor-widget elementor-widget-heading\" data-id=\"340784f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"color:#061360\">Pourquoi choisir Time2plug<\/span> comme partenaire ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<main class=\"elementor-section elementor-top-section elementor-element elementor-element-20057ba elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"20057ba\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<article class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1fe1508\" data-id=\"1fe1508\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-08ca82b elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"08ca82b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"far fa-handshake\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cd4d63b elementor-widget elementor-widget-heading\" data-id=\"cd4d63b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Des projets cl\u00e9 en main<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a0e941 elementor-widget elementor-widget-text-editor\" data-id=\"5a0e941\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Recevez des projets pr\u00eats \u00e0 \u00eatre install\u00e9s, sans les complications administratives. Ainsi concentrez-vous uniquement sur l&rsquo;installation et la qualit\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c163ae0\" data-id=\"c163ae0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7de44e7 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"7de44e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"far fa-building\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b074f1 elementor-widget elementor-widget-heading\" data-id=\"8b074f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">D\u00e9velopper votre entreprise<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b2dc50 elementor-widget elementor-widget-text-editor\" data-id=\"3b2dc50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Acc\u00e9dez \u00e0 de nouvelles opportunit\u00e9s de croissance et augmentez vos revenus gr\u00e2ce \u00e0 un flux constant de projets et \u00e0 une visibilit\u00e9 renforc\u00e9e.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8f92860\" data-id=\"8f92860\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-83a0a48 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"83a0a48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"far fa-calendar-alt\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb446b2 elementor-widget elementor-widget-heading\" data-id=\"bb446b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Accompagnement au quotidien<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c258bd9 elementor-widget elementor-widget-text-editor\" data-id=\"c258bd9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>B\u00e9n\u00e9ficiez d&rsquo;un soutien personnalis\u00e9 \u00e0 chaque \u00e9tape. Car notre \u00e9quipe est l\u00e0 pour vous aider avec des conseils techniques et commerciaux adapt\u00e9s.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t\t<\/div>\n\t\t<\/main>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-03348f7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"03348f7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e31a60a\" data-id=\"e31a60a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f48f0a elementor-align-center elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"0f48f0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.time2plug.com\/page\/formulaire-partenariat-installateur\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Devenir partenaire<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-034a560 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"034a560\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aa895da\" data-id=\"aa895da\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9256647 elementor-widget elementor-widget-heading\" data-id=\"9256647\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"color:#061360\">Comment devenir <\/span>un installateur partenaire ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<main class=\"elementor-section elementor-top-section elementor-element elementor-element-fc80de1 elementor-section-content-middle elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"fc80de1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<article class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-aabc247\" data-id=\"aabc247\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;animation&quot;:&quot;none&quot;,&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1406488 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"1406488\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"etude\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"800\" height=\"800\" viewBox=\"0 0 800 800\" fill=\"none\"><g clip-path=\"url(#clip0_1427_3523)\"><path d=\"M801 288C801 459.333 801 630.167 801 801C534.333 801 267.667 801 1 801C1 534.333 1 267.667 1 1C267.667 1 534.333 1 801 1C801 96.5 801 192 801 288ZM298.06 737.529C218.054 712.694 154.063 665.781 107.435 596.34C60.2398 526.055 41.4293 448.165 49.8096 363.827C54.0151 321.503 65.8802 281.376 84.8621 243.37C102.796 207.462 126.312 175.627 155.204 147.73C191.913 112.287 234.228 85.9607 282.334 68.9341C328.781 52.4946 376.577 46.2209 425.694 49.8151C459.753 52.3074 492.727 59.6281 524.653 71.7806C549.468 81.2262 572.912 93.2797 594.947 108.08C597.888 110.056 600.857 110.966 603.138 107.434C605.342 104.021 603.666 101.509 600.578 99.5881C595.353 96.3375 590.253 92.874 584.934 89.7862C491.788 35.7117 393.173 23.9118 290.625 55.6763C202.166 83.0765 134.459 138.375 87.1249 218.125C59.6963 264.338 43.9536 314.455 39.2033 367.925C34.9274 416.055 39.6893 463.336 54.4539 509.442C79.4628 587.538 125.53 650.421 192.635 697.378C257.371 742.677 329.629 763.983 408.717 762.207C462.648 760.996 513.741 748.392 561.821 724.15C619.359 695.139 666.223 653.794 701.61 599.849C750.484 525.344 769.065 443.519 758.575 355.262C751.156 292.848 727.975 236.42 690.87 185.716C687.434 181.021 683.721 176.526 680.067 171.996C677.939 169.359 674.801 168.706 672.755 171.126C671.509 172.6 672.11 175.783 672.229 178.181C672.269 178.994 673.367 179.759 673.992 180.539C702.629 216.263 723.682 255.999 736.697 299.902C753.53 356.679 756.127 414.169 743.972 472.129C728.17 547.476 691.602 611.127 634.204 662.417C567.228 722.266 488.361 751.807 398.683 752.387C364.716 752.606 331.416 747.395 298.06 737.529ZM336.5 557.995C300.005 557.995 263.511 558.028 227.017 557.98C211.323 557.959 201.875 544.199 207.375 529.001C212.224 529.001 217.206 529.002 222.189 529.001C232.706 528.997 237.003 524.697 237.003 514.146C237.005 447.489 237.006 380.832 236.987 314.175C236.987 312.186 237.011 310.142 236.588 308.219C235.486 303.201 231.749 300.161 226.727 299.875C221.268 299.565 217.917 301.67 216.237 307.079C215.417 309.719 215.05 312.604 215.045 315.38C214.929 377.369 214.892 439.358 214.84 501.347C214.838 503.116 214.84 504.884 214.84 506.999C208.056 506.999 201.913 506.943 195.772 507.013C188.418 507.097 184.177 511.118 184.015 518.327C183.869 524.82 183.766 531.328 184.04 537.813C184.372 545.693 186.113 553.273 190.286 560.126C199.39 575.077 213.287 580.215 230.085 580.202C340.069 580.116 450.053 580.164 560.037 580.15C564.367 580.15 568.704 580.084 573.026 579.847C599.282 578.404 614.86 562.224 615.337 535.896C615.43 530.741 615.101 525.575 615.289 520.426C615.621 511.297 611.79 507.059 602.752 507.012C596.658 506.98 590.563 507.006 584.162 507.006C584.162 504.487 584.162 502.677 584.162 500.867C584.162 439.209 584.164 377.552 584.155 315.894C584.155 313.729 584.21 311.547 583.965 309.404C583.312 303.666 578.825 299.801 573.074 299.849C566.062 299.908 562.156 304.742 562.154 313.621C562.143 380.728 562.158 447.835 562.174 514.941C562.177 524.978 566 528.87 576.012 528.993C581.624 529.062 587.236 529.005 592.774 529.005C594.8 549.218 586.875 558.138 567.448 558.12C557.789 558.112 548.13 557.999 538.471 557.998C471.48 557.987 404.49 557.994 336.5 557.995ZM372.5 220.998C369 220.998 365.501 220.998 362.001 220.998C340.003 220.997 318.005 221.023 296.007 220.987C276.397 220.954 258.283 234.488 259.746 257.724C260.215 265.18 259.503 272.705 259.519 280.197C259.591 313.855 259.722 347.512 259.85 381.169C259.915 398.267 271.129 411.316 288.043 413.98C291.941 414.594 295.86 415.076 300.138 415.67C300.138 426.306 300.136 436.623 300.138 446.94C300.139 456.317 303.298 462.08 309.741 464.467C316.308 466.901 322.753 464.714 328.685 457.883C339.047 445.949 349.525 434.108 359.6 421.936C363.741 416.932 368.117 414.631 374.889 414.68C417.853 414.995 460.82 414.897 503.786 414.787C517.238 414.752 528.591 410.183 535.739 398.011C539.654 391.346 540.561 383.923 540.538 376.346C540.418 337.355 540.255 298.365 540.172 259.374C540.119 234.438 526.823 221.007 501.988 221.001C459.159 220.991 416.329 220.998 372.5 220.998ZM255.447 508.625C249.853 512.792 248.505 517.888 251.632 523.264C254.689 528.519 259.895 528.965 265.124 528.977C292.285 529.035 319.447 529.048 346.609 528.953C350.242 528.94 352.944 529.824 355.072 532.99C359.104 538.989 364.942 541.469 372.17 541.418C390.666 541.287 409.163 541.336 427.66 541.394C434.459 541.415 440.032 539.059 443.937 533.399C446.237 530.065 449.147 528.893 453.243 528.917C480.737 529.078 508.233 529.04 535.728 528.976C544.352 528.956 549.302 524.673 549.252 517.641C549.204 510.883 544.331 507.001 535.853 507.001C503.859 506.999 471.865 507.002 439.87 507.013C432.277 507.016 429.503 509.16 426.957 516.227C426.511 517.463 424.669 519.017 423.456 519.031C407.636 519.21 391.811 519.203 375.991 519.009C374.678 518.993 372.718 517.564 372.193 516.315C368.921 508.527 366.515 506.818 357.884 506.835C326.391 506.898 294.898 506.92 263.405 507.049C260.969 507.058 258.535 507.777 255.447 508.625Z\" fill=\"#FEFFFF\"><\/path><path d=\"M298.438 737.671C331.415 747.395 364.716 752.606 398.683 752.387C488.361 751.807 567.228 722.266 634.204 662.417C691.602 611.127 728.17 547.475 743.972 472.129C756.127 414.169 753.529 356.679 736.697 299.902C723.682 255.999 702.629 216.263 673.992 180.539C673.367 179.759 672.269 178.994 672.229 178.181C672.11 175.783 671.508 172.6 672.754 171.126C674.801 168.706 677.939 169.359 680.066 171.996C683.721 176.526 687.434 181.021 690.87 185.716C727.975 236.42 751.156 292.848 758.575 355.262C769.065 443.519 750.484 525.344 701.61 599.849C666.222 653.794 619.359 695.139 561.821 724.15C513.741 748.392 462.648 760.995 408.717 762.207C329.628 763.983 257.371 742.676 192.635 697.378C125.53 650.421 79.4627 587.538 54.4538 509.442C39.6892 463.336 34.9273 416.055 39.2032 367.925C43.9535 314.455 59.6962 264.338 87.1248 218.125C134.459 138.375 202.166 83.0764 290.625 55.6763C393.173 23.9117 491.788 35.7116 584.934 89.7862C590.253 92.8739 595.353 96.3374 600.578 99.588C603.666 101.509 605.342 104.021 603.137 107.434C600.857 110.966 597.888 110.056 594.947 108.08C572.911 93.2796 549.468 81.2261 524.653 71.7805C492.727 59.628 459.753 52.3073 425.694 49.815C376.577 46.2208 328.781 52.4945 282.333 68.934C234.227 85.9606 191.913 112.287 155.204 147.73C126.312 175.627 102.796 207.462 84.862 243.37C65.8801 281.376 54.015 321.503 49.8095 363.827C41.4292 448.165 60.2397 526.055 107.435 596.34C154.063 665.78 218.054 712.694 298.438 737.671Z\" fill=\"#18A9AB\"><\/path><path d=\"M337 557.995C404.49 557.994 471.48 557.988 538.471 557.998C548.13 557.999 557.789 558.112 567.448 558.121C586.875 558.138 594.8 549.218 592.774 529.005C587.236 529.005 581.624 529.062 576.012 528.993C566 528.87 562.177 524.978 562.174 514.941C562.158 447.835 562.143 380.728 562.154 313.622C562.156 304.742 566.062 299.908 573.074 299.849C578.825 299.801 583.312 303.666 583.965 309.404C584.21 311.547 584.155 313.729 584.155 315.894C584.164 377.552 584.162 439.209 584.162 500.867C584.162 502.677 584.162 504.487 584.162 507.006C590.563 507.006 596.658 506.98 602.752 507.012C611.79 507.059 615.621 511.297 615.289 520.426C615.101 525.575 615.43 530.741 615.337 535.896C614.86 562.224 599.282 578.404 573.026 579.847C568.704 580.085 564.367 580.15 560.037 580.15C450.053 580.164 340.069 580.116 230.085 580.202C213.287 580.215 199.39 575.077 190.286 560.126C186.113 553.273 184.372 545.693 184.04 537.814C183.766 531.329 183.869 524.82 184.015 518.327C184.177 511.118 188.418 507.097 195.772 507.013C201.913 506.943 208.056 506.999 214.84 506.999C214.84 504.884 214.838 503.116 214.84 501.347C214.892 439.358 214.929 377.369 215.045 315.38C215.05 312.604 215.417 309.72 216.237 307.079C217.917 301.67 221.268 299.565 226.727 299.875C231.749 300.161 235.486 303.201 236.588 308.219C237.011 310.142 236.987 312.186 236.987 314.175C237.006 380.832 237.005 447.489 237.003 514.146C237.003 524.697 232.706 528.997 222.189 529.001C217.206 529.002 212.224 529.001 207.375 529.001C201.875 544.199 211.323 557.959 227.017 557.98C263.511 558.028 300.006 557.995 337 557.995Z\" fill=\"#15A8AA\"><\/path><path d=\"M373 220.998C416.329 220.998 459.159 220.99 501.988 221.001C526.823 221.007 540.119 234.438 540.172 259.374C540.255 298.365 540.418 337.355 540.538 376.346C540.561 383.923 539.654 391.346 535.739 398.011C528.591 410.183 517.238 414.752 503.786 414.787C460.82 414.897 417.853 414.995 374.889 414.68C368.117 414.631 363.741 416.932 359.6 421.935C349.525 434.108 339.047 445.949 328.685 457.883C322.753 464.714 316.308 466.901 309.741 464.467C303.298 462.08 300.139 456.317 300.138 446.94C300.136 436.623 300.138 426.306 300.138 415.67C295.86 415.076 291.941 414.594 288.043 413.98C271.129 411.316 259.915 398.266 259.85 381.169C259.722 347.512 259.591 313.855 259.519 280.197C259.503 272.704 260.215 265.18 259.746 257.724C258.283 234.488 276.397 220.954 296.007 220.987C318.005 221.023 340.003 220.997 362.001 220.998C365.501 220.998 369 220.998 373 220.998ZM481.5 392.841C489.164 392.84 496.832 392.991 504.491 392.797C513.423 392.57 517.159 389.042 518.141 380.319C518.419 377.847 518.63 375.351 518.632 372.866C518.663 336.713 518.654 300.559 518.65 264.406C518.65 262.241 518.756 260.062 518.557 257.914C517.496 246.446 513.846 243.161 502.291 243.161C433.816 243.16 365.342 243.163 296.867 243.165C285.886 243.165 281.858 247.181 281.844 258.254C281.82 276.403 281.836 294.551 281.832 312.699C281.828 334.843 281.783 356.986 281.835 379.13C281.857 388.406 286.508 392.854 295.778 392.762C299.609 392.724 303.443 392.573 307.269 392.686C318.916 393.031 321.983 396.147 322.119 407.787C322.205 415.182 322.135 422.579 322.135 430.938C323.617 429.543 324.366 428.953 324.978 428.245C332.706 419.314 340.682 410.58 348.035 401.349C353.202 394.862 359.436 392.498 367.548 392.556C405.197 392.83 442.849 392.777 481.5 392.841Z\" fill=\"#15A9AB\"><\/path><path d=\"M255.773 508.396C258.535 507.777 260.968 507.058 263.405 507.049C294.898 506.92 326.391 506.898 357.884 506.835C366.515 506.818 368.92 508.527 372.193 516.315C372.718 517.564 374.678 518.993 375.991 519.009C391.811 519.203 407.635 519.21 423.456 519.031C424.669 519.017 426.511 517.463 426.957 516.227C429.503 509.16 432.277 507.016 439.87 507.013C471.865 507.002 503.859 506.999 535.853 507.001C544.331 507.001 549.204 510.883 549.252 517.641C549.302 524.673 544.352 528.956 535.728 528.976C508.233 529.04 480.737 529.078 453.243 528.917C449.147 528.893 446.237 530.065 443.937 533.399C440.032 539.059 434.459 541.415 427.66 541.394C409.163 541.336 390.666 541.287 372.17 541.418C364.942 541.469 359.103 538.989 355.072 532.99C352.944 529.824 350.242 528.94 346.609 528.953C319.447 529.048 292.285 529.035 265.124 528.977C259.895 528.965 254.689 528.519 251.632 523.264C248.505 517.888 249.853 512.792 255.773 508.396Z\" fill=\"#15A8AA\"><\/path><path d=\"M481 392.841C442.849 392.777 405.197 392.83 367.548 392.557C359.436 392.498 353.202 394.862 348.035 401.349C340.682 410.58 332.705 419.314 324.978 428.245C324.366 428.953 323.617 429.543 322.135 430.938C322.135 422.579 322.205 415.182 322.119 407.787C321.983 396.147 318.916 393.031 307.269 392.686C303.443 392.573 299.609 392.724 295.778 392.762C286.508 392.854 281.857 388.406 281.835 379.13C281.783 356.986 281.828 334.843 281.832 312.699C281.836 294.551 281.82 276.403 281.844 258.254C281.858 247.181 285.885 243.165 296.867 243.165C365.341 243.163 433.816 243.16 502.291 243.161C513.846 243.161 517.496 246.446 518.557 257.914C518.756 260.063 518.65 262.241 518.65 264.406C518.654 300.56 518.663 336.713 518.632 372.866C518.63 375.351 518.419 377.847 518.141 380.319C517.159 389.042 513.423 392.57 504.491 392.797C496.832 392.992 489.164 392.84 481 392.841ZM408.5 307.004C385.194 307.004 361.889 307.002 338.583 307.005C330.76 307.006 322.931 306.862 315.113 307.068C306.465 307.295 301.43 315.108 305.13 322.698C307.472 327.5 311.863 329.044 317.136 329.038C372.07 328.971 427.004 328.998 481.939 328.989C483.435 328.989 484.961 329.041 486.421 328.78C490.637 328.025 493.764 325.838 495.103 321.573C497.732 313.202 492.638 307.028 482.912 307.01C458.441 306.962 433.971 307 408.5 307.004ZM377.5 263C356.676 263.047 335.852 263.019 315.029 263.183C308.549 263.233 304.225 267.588 304.002 273.638C303.782 279.623 307.954 284.265 314.275 284.923C316.423 285.146 318.6 285.159 320.764 285.159C373.908 285.165 427.053 285.159 480.197 285.136C482.359 285.135 484.563 285.186 486.673 284.806C493.288 283.613 496.993 277.499 495.191 271.033C493.636 265.452 489.688 263.011 481.957 263.007C447.471 262.99 412.986 263 377.5 263ZM312.364 372.718C313.353 372.811 314.342 372.985 315.331 372.985C346.447 373 377.563 372.999 408.679 372.995C409.51 372.995 410.352 373.025 411.17 372.908C418.039 371.926 422.357 367.458 422.163 361.575C421.979 356.005 417.644 351.083 412.168 351.068C379.718 350.977 347.267 351.001 314.817 351.129C309.085 351.152 304.981 355.006 304.085 360.336C303.257 365.263 306.336 370.13 312.364 372.718Z\" fill=\"#FDFEFD\"><\/path><path d=\"M409 307.004C433.971 307 458.441 306.962 482.912 307.01C492.638 307.029 497.732 313.202 495.103 321.574C493.764 325.838 490.637 328.025 486.421 328.78C484.961 329.042 483.435 328.989 481.939 328.989C427.004 328.998 372.07 328.971 317.136 329.038C311.863 329.044 307.472 327.501 305.13 322.698C301.43 315.109 306.466 307.295 315.113 307.068C322.932 306.862 330.76 307.006 338.584 307.005C361.889 307.002 385.195 307.004 409 307.004Z\" fill=\"#F1A628\"><\/path><path d=\"M378 263C412.986 263 447.471 262.99 481.957 263.007C489.688 263.011 493.636 265.453 495.191 271.033C496.993 277.499 493.288 283.613 486.673 284.806C484.563 285.187 482.359 285.136 480.197 285.137C427.053 285.159 373.908 285.165 320.764 285.159C318.6 285.159 316.423 285.147 314.275 284.923C307.954 284.265 303.782 279.623 304.002 273.638C304.226 267.588 308.549 263.234 315.029 263.183C335.852 263.02 356.676 263.047 378 263Z\" fill=\"#F1A627\"><\/path><path d=\"M312.004 372.502C306.336 370.13 303.257 365.263 304.085 360.336C304.981 355.006 309.085 351.152 314.817 351.129C347.267 351.001 379.718 350.977 412.168 351.068C417.644 351.084 421.979 356.005 422.163 361.575C422.357 367.458 418.039 371.926 411.17 372.908C410.352 373.025 409.51 372.995 408.679 372.995C377.563 372.999 346.447 373 315.331 372.985C314.342 372.985 313.353 372.811 312.004 372.502Z\" fill=\"#F1A628\"><\/path><\/g><defs><clipPath id=\"clip0_1427_3523\"><rect width=\"800\" height=\"800\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tRemplissez le formulaire d\u00e9di\u00e9 :\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tCompl\u00e9tez ce <a href=\"https:\/\/www.time2plug.com\/page\/formulaire-partenariat-installateur\/\">formulaire sur mesure<\/a> en sp\u00e9cifiant les membres de votre \u00e9quipe, en d\u00e9finissant la port\u00e9e g\u00e9ographique de votre activit\u00e9, ainsi que votre niveau de qualification en Infrastructure de Recharge pour les V\u00e9hicules \u00c9lectriques (IRVE) et votre degr\u00e9 d'expertise.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3074871 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"3074871\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:3}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"800\" height=\"800\" viewBox=\"0 0 800 800\" fill=\"none\"><g clip-path=\"url(#clip0_1427_3561)\"><path d=\"M1 298C1 198.667 1 99.8333 1 1C267.667 1 534.333 1 801 1C801 267.667 801 534.333 801 801C534.333 801 267.667 801 1 801C1 633.5 1 466 1 298ZM452.057 604.387C465.734 609.44 479.759 611.19 494.261 609.146C546.932 601.724 574.788 564.542 577.763 518.239C579.492 491.342 568.946 468.832 550.379 449.932C545.956 445.43 544.034 440.849 544.054 434.497C544.252 372.007 544.127 309.515 544.252 247.024C544.263 241.267 542.522 236.841 538.411 232.833C526.48 221.203 514.666 209.447 503.043 197.511C499.121 193.484 494.788 191.894 489.268 191.925C457.608 192.101 425.947 192.112 394.286 192.132C354.791 192.158 315.297 192.133 275.802 192.142C267.45 192.144 265.508 194.006 265.413 202.406C265.316 210.903 265.406 219.403 265.38 227.902C265.375 229.65 265.217 231.397 265.117 233.392C262.657 233.392 260.835 233.392 259.014 233.392C250.515 233.393 242.014 233.272 233.518 233.432C226.088 233.572 224.192 235.691 224.138 243.174C224.131 244.174 224.137 245.174 224.137 246.174C224.137 356.325 224.139 466.476 224.134 576.627C224.134 590.263 224.709 590.841 238.506 590.852C298.995 590.901 359.484 590.889 419.972 591.161C424.044 591.179 428.289 592.936 432.132 594.618C438.664 597.478 444.941 600.922 452.057 604.387ZM569.083 721.533C636.501 685.65 688.165 633.98 723.017 566.046C759.189 495.537 770.547 420.816 758.067 342.583C748.043 279.743 722.571 223.694 682.907 174.019C680.597 171.126 678.086 168.291 674.24 171.335C670.375 174.394 672.556 177.485 674.92 180.343C675.663 181.241 676.38 182.163 677.092 183.086C739.062 263.417 763.318 354.039 748.596 454.248C736.768 534.763 700.509 603.578 640.334 658.375C552.718 738.162 449.512 767.611 333.044 745.831C245.649 729.488 174.574 684.471 121.091 613.621C58.0218 530.071 36.65 435.834 56.0504 333.003C70.1333 258.357 105.744 194.853 161.636 143.552C238.459 73.0374 329.485 42.3251 433.469 50.8567C483.277 54.9433 529.88 69.8772 573.392 94.3974C581.217 98.8064 588.775 103.694 596.383 108.476C599.437 110.396 602.441 111.173 604.64 107.766C606.839 104.356 604.971 101.809 601.865 99.9755C601.436 99.7222 601.05 99.3961 600.631 99.1244C518.613 45.9597 429.307 27.9441 333.353 45.5914C258.112 59.4292 193.157 94.1063 140.812 149.922C51.9627 244.663 21.4065 356.653 48.87 483.374C65.4645 559.944 105.194 623.885 164.686 674.841C241.396 740.544 330.759 768.97 431.335 761.571C479.712 758.013 525.409 744.337 569.083 721.533Z\" fill=\"white\"><\/path><path d=\"M451.691 604.254C444.941 600.922 438.664 597.478 432.132 594.618C428.289 592.936 424.044 591.179 419.972 591.161C359.484 590.889 298.995 590.901 238.506 590.852C224.709 590.841 224.134 590.263 224.134 576.627C224.139 466.476 224.137 356.325 224.137 246.174C224.137 245.174 224.131 244.174 224.138 243.174C224.192 235.691 226.088 233.572 233.518 233.432C242.014 233.272 250.515 233.393 259.014 233.392C260.835 233.392 262.657 233.392 265.117 233.392C265.217 231.397 265.375 229.65 265.38 227.902C265.406 219.403 265.316 210.903 265.413 202.406C265.508 194.006 267.45 192.144 275.802 192.142C315.297 192.133 354.791 192.158 394.286 192.132C425.947 192.112 457.608 192.101 489.268 191.925C494.788 191.894 499.121 193.484 503.043 197.511C514.666 209.447 526.48 221.203 538.411 232.833C542.522 236.841 544.263 241.267 544.252 247.024C544.127 309.515 544.252 372.007 544.054 434.497C544.034 440.849 545.956 445.43 550.379 449.932C568.946 468.832 579.492 491.342 577.764 518.239C574.788 564.542 546.932 601.724 494.261 609.146C479.759 611.19 465.734 609.44 451.691 604.254ZM271.582 528.237C273.34 523.61 277.337 523.834 281.2 523.833C315.193 523.825 349.187 523.829 383.18 523.83C385.109 523.83 387.038 523.83 389.667 523.83C389.667 514.947 389.667 506.757 389.667 498.171C387.75 498.171 385.944 498.171 384.137 498.171C350.31 498.17 316.483 498.185 282.657 498.16C273.908 498.153 271.214 496.471 271.139 491.224C271.066 486.125 274.289 484.151 282.575 484.141C318.066 484.098 353.558 484.071 389.049 483.917C391.215 483.907 394.541 483.531 395.347 482.161C399.69 474.778 403.407 467.026 407.75 458.604C405.201 458.604 403.735 458.604 402.27 458.604C362.444 458.61 322.619 458.617 282.793 458.618C281.128 458.618 279.447 458.707 277.802 458.51C273.853 458.038 271.256 456.011 271.171 451.778C271.085 447.549 273.491 445.351 277.528 444.902C280.17 444.609 282.838 444.417 285.494 444.415C328.319 444.386 371.145 444.342 413.969 444.462C419.207 444.476 423.56 443.235 427.829 440.047C440.441 430.629 454.567 424.601 470.312 422.798C476.366 422.105 482.454 421.714 488.445 421.193C488.445 377.431 488.445 334.208 488.445 290.621C479.248 290.621 470.434 290.624 461.619 290.621C446.422 290.614 445.991 290.178 445.991 274.926C445.991 265.991 445.991 257.056 445.991 248.072C376.403 248.072 307.479 248.072 238.282 248.072C238.282 357.508 238.282 466.724 238.282 576.052C295.871 576.052 353.204 576.052 411.205 576.052C409.684 573.919 408.338 572.443 407.456 570.728C402.91 561.895 397.914 553.228 394.249 544.035C392.351 539.275 390.306 537.733 385.361 537.76C351.536 537.95 317.708 537.861 283.882 537.852C282.051 537.851 280.199 537.929 278.392 537.693C272.819 536.965 271.194 534.897 271.582 528.237ZM509.035 591.741C541.975 578.981 561.14 555.102 563.613 519.872C567.196 468.83 520.185 427.928 469.561 436.876C423.918 444.943 394.826 490.192 406.084 535.605C417.076 579.948 464.392 606.035 509.035 591.741ZM320.5 233.392C362.999 233.393 405.499 233.438 447.998 233.337C453.348 233.324 457.544 234.924 461.328 238.8C473.319 251.081 485.474 263.206 497.724 275.23C501.304 278.743 502.93 282.592 502.913 287.627C502.795 322.126 502.852 356.626 502.855 391.126C502.856 400.459 502.775 409.794 502.963 419.123C502.992 420.609 503.884 422.945 504.991 423.403C513.097 426.755 521.359 429.728 529.835 432.919C529.835 371.423 529.835 310.377 529.835 248.853C519.232 248.853 508.935 248.857 498.639 248.852C489.051 248.848 487.377 247.157 487.368 237.441C487.359 227.146 487.366 216.851 487.366 206.343C418.062 206.343 349.18 206.343 280.306 206.343C280.306 215.437 280.306 224.196 280.306 233.393C293.564 233.393 306.532 233.393 320.5 233.392ZM501.557 233.872C506.912 234.332 512.268 234.792 517.274 235.221C511.681 229.659 506.43 224.438 501.366 219.402C501.366 223.471 501.366 228.232 501.557 233.872ZM466.961 265.539C465.017 263.387 463.073 261.234 460.393 258.266C460.393 265.202 460.393 270.526 460.393 275.662C465.978 275.662 471.164 275.662 477.902 275.662C473.76 271.843 470.612 268.94 466.961 265.539Z\" fill=\"#19AAAC\"><\/path><path d=\"M568.771 721.73C525.409 744.337 479.712 758.013 431.335 761.571C330.759 768.97 241.396 740.544 164.686 674.841C105.194 623.885 65.4645 559.944 48.87 483.374C21.4065 356.653 51.9627 244.663 140.812 149.922C193.157 94.1063 258.112 59.4291 333.353 45.5914C429.307 27.9441 518.613 45.9597 600.631 99.1243C601.05 99.3961 601.436 99.7221 601.865 99.9754C604.971 101.809 606.839 104.356 604.64 107.766C602.441 111.173 599.437 110.396 596.383 108.476C588.775 103.694 581.217 98.8064 573.392 94.3974C529.88 69.8772 483.277 54.9432 433.469 50.8566C329.485 42.3251 238.459 73.0374 161.636 143.552C105.744 194.853 70.1333 258.357 56.0505 333.003C36.6501 435.834 58.0219 530.071 121.091 613.621C174.574 684.471 245.649 729.488 333.044 745.831C449.512 767.611 552.718 738.162 640.334 658.375C700.509 603.577 736.768 534.763 748.596 454.248C763.318 354.039 739.062 263.417 677.092 183.086C676.38 182.163 675.663 181.241 674.92 180.343C672.556 177.485 670.375 174.394 674.24 171.335C678.086 168.291 680.597 171.126 682.907 174.019C722.571 223.694 748.043 279.743 758.067 342.583C770.547 420.816 759.189 495.537 723.017 566.046C688.165 633.98 636.501 685.65 568.771 721.73Z\" fill=\"#1AAAAC\"><\/path><path d=\"M271.447 528.608C271.194 534.897 272.819 536.965 278.393 537.693C280.199 537.929 282.051 537.851 283.882 537.852C317.708 537.861 351.536 537.95 385.362 537.76C390.306 537.733 392.351 539.275 394.249 544.035C397.914 553.228 402.91 561.895 407.456 570.728C408.338 572.443 409.684 573.92 411.205 576.052C353.204 576.052 295.871 576.052 238.282 576.052C238.282 466.724 238.282 357.508 238.282 248.072C307.479 248.072 376.403 248.072 445.991 248.072C445.991 257.056 445.991 265.991 445.991 274.926C445.991 290.178 446.422 290.614 461.619 290.621C470.434 290.624 479.248 290.621 488.446 290.621C488.446 334.208 488.446 377.431 488.446 421.193C482.455 421.714 476.366 422.105 470.312 422.798C454.567 424.601 440.441 430.629 427.829 440.047C423.56 443.236 419.207 444.476 413.969 444.462C371.145 444.342 328.319 444.386 285.494 444.415C282.838 444.417 280.17 444.609 277.528 444.902C273.491 445.351 271.085 447.549 271.171 451.778C271.256 456.011 273.853 458.038 277.802 458.51C279.447 458.707 281.128 458.618 282.793 458.618C322.619 458.617 362.444 458.61 402.27 458.604C403.735 458.604 405.201 458.604 407.75 458.604C403.407 467.026 399.69 474.778 395.347 482.161C394.541 483.531 391.215 483.907 389.049 483.917C353.558 484.071 318.066 484.098 282.575 484.141C274.289 484.151 271.066 486.125 271.139 491.225C271.214 496.471 273.908 498.153 282.657 498.16C316.484 498.185 350.31 498.17 384.137 498.171C385.944 498.171 387.75 498.171 389.667 498.171C389.667 506.757 389.667 514.947 389.667 523.83C387.038 523.83 385.109 523.83 383.18 523.83C349.187 523.829 315.193 523.825 281.2 523.833C277.337 523.834 273.34 523.61 271.447 528.608ZM273.086 338.505C273.402 338.693 273.718 338.881 274.554 339.639C276.988 340.058 279.422 340.84 281.857 340.843C336.224 340.908 390.591 340.908 444.958 340.801C447.085 340.797 449.21 339.616 452.011 338.909C454.072 336.604 457.526 334.853 455.213 330.089C454.126 329.065 453.039 328.042 452 326.991C452 326.991 452.016 327.044 451.501 326.354C449.365 326.177 447.23 325.849 445.094 325.846C390.027 325.76 334.96 325.697 279.894 325.71C278.259 325.71 276.624 326.577 274.997 326.995C274.997 326.995 275.04 327.011 274.401 326.854C273.935 327.255 273.469 327.655 272.997 327.997C272.997 327.997 273.055 328.008 272.318 328.256C270.372 331.667 269.54 334.994 272.997 338.001C272.997 338.001 273.013 337.947 273.086 338.505ZM273.177 417.715C275.85 418.415 278.522 419.721 281.197 419.726C336.265 419.843 391.333 419.826 446.401 419.734C447.995 419.731 449.587 418.615 451.731 417.663C456.912 412.076 457.022 409.626 451.99 406.15C449.512 405.582 447.035 404.523 444.556 404.518C390.643 404.423 336.729 404.439 282.815 404.471C280.499 404.472 278.102 404.53 275.881 405.101C270.241 406.55 268.906 412.421 273 417C273 417 273.027 416.973 273.177 417.715ZM449.822 379.623C457.473 374.075 457.525 373.897 452.948 366.429C450.538 365.954 448.129 365.067 445.719 365.064C390.729 364.989 335.739 365.003 280.748 365.048C279.158 365.049 277.568 365.557 275.348 366.098C272.549 367.886 270.746 370.052 271.796 373.725C272.572 376.44 273.033 379.234 277.324 379.728C278.979 379.82 280.634 379.993 282.289 379.994C324.104 380.008 365.919 380.018 407.734 379.996C421.557 379.988 435.381 379.887 449.822 379.623ZM383.497 286.399C349.704 286.399 315.912 286.388 282.12 286.423C279.976 286.426 277.735 286.464 275.708 287.061C271.331 288.348 269.264 294.427 272.498 297.521C274.405 299.346 277.747 300.399 280.487 300.493C290.464 300.833 300.459 300.62 310.446 300.619C339.078 300.617 367.71 300.642 396.342 300.593C402.435 300.582 405.716 298.414 405.853 294.692C406.016 290.283 401.47 286.449 395.98 286.406C392.152 286.376 388.323 286.4 383.497 286.399Z\" fill=\"#FDFEFE\"><\/path><path d=\"M508.65 591.841C464.392 606.035 417.076 579.948 406.084 535.605C394.826 490.192 423.918 444.943 469.561 436.876C520.185 427.928 567.196 468.83 563.613 519.872C561.14 555.102 541.975 578.981 508.65 591.841ZM517.265 475.563C509.795 482.658 502.414 489.85 494.83 496.822C485.909 505.022 476.813 513.03 468.372 520.602C464.887 517.363 459.696 512.671 454.655 507.824C445.966 499.47 433.3 499.269 425.13 507.468C416.818 515.809 416.726 528.302 425.176 536.946C434.836 546.829 444.609 556.606 454.496 566.262C464.548 576.079 475.705 575.83 485.613 565.792C504.099 547.063 522.554 528.302 541.047 509.58C549.415 501.108 550.777 490.68 544.612 481.598C538.92 473.215 528.495 470.702 517.265 475.563Z\" fill=\"#FDFEFE\"><\/path><path d=\"M320 233.393C306.532 233.393 293.564 233.393 280.306 233.393C280.306 224.197 280.306 215.437 280.306 206.343C349.18 206.343 418.062 206.343 487.366 206.343C487.366 216.851 487.359 227.146 487.368 237.441C487.377 247.157 489.051 248.848 498.639 248.852C508.935 248.857 519.232 248.854 529.834 248.854C529.834 310.377 529.834 371.423 529.834 432.919C521.359 429.728 513.097 426.755 504.991 423.403C503.884 422.945 502.992 420.609 502.963 419.124C502.775 409.794 502.856 400.459 502.855 391.126C502.852 356.626 502.795 322.127 502.912 287.627C502.93 282.592 501.304 278.743 497.724 275.23C485.474 263.206 473.319 251.082 461.328 238.8C457.544 234.924 453.347 233.324 447.998 233.337C405.499 233.438 362.999 233.393 320 233.393Z\" fill=\"white\"><\/path><path d=\"M501.461 233.432C501.366 228.232 501.366 223.471 501.366 219.402C506.43 224.438 511.681 229.659 517.274 235.221C512.268 234.792 506.912 234.332 501.461 233.432Z\" fill=\"#E4F5F5\"><\/path><path d=\"M467.212 265.788C470.612 268.94 473.76 271.843 477.902 275.662C471.164 275.662 465.978 275.662 460.393 275.662C460.393 270.526 460.393 265.202 460.393 258.266C463.073 261.234 465.017 263.387 467.212 265.788Z\" fill=\"#F8FCFC\"><\/path><path d=\"M453.517 367.05C457.525 373.897 457.473 374.075 449.219 379.401C447.622 379.122 446.628 379.013 445.633 379.013C389.359 379.004 333.085 379.004 276.811 379.003C273.033 379.235 272.572 376.44 271.796 373.725C270.746 370.052 272.549 367.886 276.13 366.042C279.739 366.041 282.565 366.143 285.392 366.144C334.003 366.153 382.613 366.113 431.223 366.191C438.655 366.203 446.086 366.75 453.517 367.05Z\" fill=\"#EDA62A\"><\/path><path d=\"M455.236 330.814C457.526 334.853 454.072 336.604 451.173 338.941C392.074 338.968 333.814 338.963 275.311 338.672C274.384 338.24 273.698 338.093 273.013 337.947C273.013 337.947 272.997 338.001 273.103 337.603C273.157 334.14 273.106 331.074 273.054 328.008C273.054 328.008 272.997 327.997 273.331 328.157C274.124 327.881 274.582 327.446 275.04 327.011C275.04 327.011 274.997 326.995 275.46 327.082C277.417 327.099 278.911 326.97 280.405 326.97C337.609 326.988 394.812 327.017 452.016 327.044C452.016 327.044 452 326.991 451.986 327.338C453.06 328.728 454.148 329.771 455.236 330.814Z\" fill=\"#F1A628\"><\/path><path d=\"M452.216 406.89C457.022 409.626 456.912 412.076 450.973 417.811C448.05 418.017 445.887 418.123 443.723 418.123C391.25 418.132 338.777 418.158 286.304 418.08C281.878 418.074 277.452 417.359 273.027 416.973C273.027 416.973 273 417 273.107 416.599C270.754 409.255 272.871 406.199 280.243 406.049C280.742 406.039 281.241 406.039 281.74 406.039C336.273 406.04 390.806 406.03 445.339 406.077C447.632 406.079 449.924 406.607 452.216 406.89Z\" fill=\"#F1A627\"><\/path><path d=\"M383.995 286.399C388.323 286.4 392.152 286.376 395.98 286.406C401.47 286.449 406.016 290.283 405.853 294.692C405.716 298.414 402.435 300.582 396.342 300.593C367.71 300.643 339.078 300.617 310.446 300.619C300.458 300.62 290.464 300.833 280.487 300.493C277.746 300.399 274.405 299.346 272.498 297.521C269.264 294.427 271.331 288.348 275.708 287.061C277.735 286.464 279.975 286.426 282.12 286.424C315.912 286.388 349.704 286.399 383.995 286.399Z\" fill=\"#1DABAD\"><\/path><path d=\"M452.103 406.52C449.924 406.607 447.632 406.079 445.339 406.077C390.806 406.03 336.273 406.04 281.74 406.039C281.241 406.039 280.742 406.039 280.244 406.049C272.871 406.198 270.754 409.255 273.121 416.585C268.906 412.421 270.241 406.55 275.881 405.101C278.102 404.53 280.499 404.472 282.815 404.471C336.729 404.439 390.643 404.423 444.556 404.518C447.035 404.523 449.512 405.582 452.103 406.52Z\" fill=\"#70B799\"><\/path><path d=\"M273.102 417.344C277.452 417.358 281.877 418.074 286.304 418.08C338.777 418.158 391.25 418.132 443.723 418.123C445.887 418.123 448.05 418.017 450.697 417.989C449.587 418.615 447.995 419.731 446.401 419.734C391.333 419.826 336.264 419.843 281.196 419.726C278.522 419.72 275.85 418.415 273.102 417.344Z\" fill=\"#70B799\"><\/path><path d=\"M275.553 338.958C333.814 338.964 392.074 338.969 450.835 338.978C449.209 339.616 447.085 340.797 444.958 340.801C390.591 340.908 336.224 340.908 281.857 340.843C279.422 340.84 276.988 340.058 274.672 339.308C275.044 338.971 275.299 338.965 275.553 338.958Z\" fill=\"#85BC9E\"><\/path><path d=\"M453.233 366.739C446.086 366.75 438.655 366.203 431.223 366.191C382.613 366.113 334.003 366.153 285.392 366.144C282.565 366.143 279.739 366.041 276.445 365.908C277.568 365.557 279.158 365.049 280.748 365.048C335.739 365.003 390.729 364.988 445.719 365.063C448.129 365.067 450.538 365.954 453.233 366.739Z\" fill=\"#4AC0BB\"><\/path><path d=\"M451.759 326.699C394.813 327.017 337.609 326.988 280.405 326.97C278.911 326.97 277.417 327.099 275.456 327.104C276.624 326.577 278.259 325.71 279.894 325.709C334.96 325.696 390.027 325.76 445.094 325.846C447.23 325.849 449.365 326.177 451.759 326.699Z\" fill=\"#4CAA8D\"><\/path><path d=\"M277.067 379.365C333.085 379.004 389.359 379.004 445.633 379.013C446.628 379.013 447.622 379.122 448.911 379.504C435.381 379.887 421.557 379.988 407.733 379.995C365.918 380.018 324.103 380.008 282.288 379.994C280.634 379.993 278.979 379.82 277.067 379.365Z\" fill=\"#18A9AA\"><\/path><path d=\"M272.686 328.132C273.106 331.074 273.157 334.14 273.13 337.6C269.54 334.994 270.372 331.667 272.686 328.132Z\" fill=\"#4CAA8D\"><\/path><path d=\"M455.224 330.452C454.148 329.771 453.06 328.728 451.962 327.352C453.039 328.042 454.126 329.065 455.224 330.452Z\" fill=\"#4CAA8D\"><\/path><path d=\"M275.311 338.673C275.299 338.965 275.044 338.971 274.412 339.024C273.718 338.882 273.402 338.693 273.049 338.226C273.698 338.094 274.384 338.24 275.311 338.673Z\" fill=\"#4CAA8D\"><\/path><path d=\"M274.72 326.933C274.582 327.446 274.124 327.882 273.334 328.186C273.469 327.655 273.935 327.255 274.72 326.933Z\" fill=\"#4CAA8D\"><\/path><path d=\"M517.591 475.363C528.495 470.702 538.921 473.215 544.612 481.598C550.778 490.679 549.415 501.108 541.047 509.58C522.554 528.302 504.099 547.063 485.613 565.792C475.705 575.83 464.548 576.078 454.496 566.262C444.609 556.606 434.836 546.829 425.176 536.946C416.727 528.302 416.818 515.809 425.13 507.468C433.3 499.269 445.966 499.47 454.656 507.824C459.697 512.671 464.887 517.363 468.372 520.602C476.813 513.03 485.91 505.022 494.83 496.821C502.414 489.85 509.795 482.658 517.591 475.363ZM528.288 486.881C525.847 488.056 522.873 488.693 521.049 490.494C507.186 504.177 493.512 518.053 479.852 531.94C469.867 542.09 469.535 542.119 459.385 531.975C454.677 527.27 450.015 522.5 445.039 518.091C443.349 516.594 440.435 514.904 438.642 515.386C432.8 516.96 431.154 523.248 435.377 527.599C444.882 537.394 454.575 547.014 464.41 556.479C468.56 560.472 471.363 560.22 475.596 555.952C494.234 537.158 512.826 518.317 531.355 499.414C536.361 494.306 535.544 490.462 528.288 486.881Z\" fill=\"#18A9AA\"><\/path><path d=\"M528.68 486.924C535.544 490.462 536.361 494.306 531.354 499.414C512.826 518.317 494.234 537.158 475.596 555.952C471.363 560.22 468.56 560.472 464.41 556.479C454.575 547.014 444.882 537.394 435.377 527.599C431.154 523.248 432.8 516.96 438.642 515.386C440.435 514.904 443.349 516.594 445.039 518.091C450.015 522.5 454.677 527.27 459.385 531.975C469.535 542.119 469.867 542.09 479.851 531.94C493.512 518.053 507.186 504.177 521.049 490.494C522.873 488.693 525.846 488.056 528.68 486.924Z\" fill=\"#EDA62A\"><\/path><\/g><defs><clipPath id=\"clip0_1427_3561\"><rect width=\"800\" height=\"800\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSoumettez les documents requis :\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tEnsuite, apr\u00e8s avoir compl\u00e9t\u00e9 le formulaire, vous recevrez un email de confirmation contenant la liste des pi\u00e8ces justificatives \u00e0 nous transmettre. Cet email inclura \u00e9galement le contrat de partenariat \u00e0 signer et \u00e0 nous retourner. Veuillez pr\u00e9parer ces documents pour finaliser votre int\u00e9gration en tant que partenaire Time2plug.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a1b84b0 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"a1b84b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:5}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"800\" height=\"800\" viewBox=\"0 0 800 800\" fill=\"none\"><g clip-path=\"url(#clip0_1427_3702)\"><path d=\"M801 288C801 459.333 801 630.167 801 801C534.333 801 267.667 801 1 801C1 534.333 1 267.667 1 1C267.667 1 534.333 1 801 1C801 96.5 801 192 801 288ZM359.728 232.175C356.352 226.728 349.559 226.043 344.701 230.853C332.399 243.031 320.153 255.265 307.949 267.542C302.731 272.79 303.894 279.835 310.625 282.798C314.627 284.561 318.951 285.588 323.124 286.967C327.035 288.261 328.995 291.068 328.881 295.106C328.704 301.36 327.783 307.647 328.249 313.84C328.458 316.635 330.744 320.831 332.986 321.536C336.02 322.491 341.074 321.932 343.255 319.885C356.232 307.701 368.852 295.111 381.128 282.217C386.935 276.117 384.859 269.74 376.996 266.955C372.882 265.497 368.669 264.305 364.605 262.726C363.185 262.174 362.076 260.823 360.962 258.932C360.972 251.866 361.043 244.798 360.947 237.733C360.925 236.094 360.333 234.463 359.728 232.175ZM541.871 375.623C541.862 362.447 541.852 349.271 542.143 335.425C545.199 329.674 550.878 330.667 555.99 330.984C555.969 406.291 555.949 481.598 555.09 556.983C553.183 557.321 551.269 557.97 549.368 557.935C544.919 557.852 541.557 559.053 540.994 564.038C540.268 570.471 541.592 572.223 548.97 573.977C579.483 573.985 609.996 574.006 640.509 573.961C642.027 573.959 643.544 573.377 645.845 573.012C650.737 573.427 651.462 569.603 651.828 566.358C652.265 562.485 647.95 558.343 643.837 558.033C641.22 557.835 638.584 557.893 635.981 556.93C635.987 450.242 635.997 343.553 635.96 236.865C635.96 235.539 635.358 234.214 634.988 232.21C633.392 230.81 631.795 229.41 629.797 227.195C607.78 227.115 585.762 227.025 563.744 226.998C563.097 226.998 562.449 227.658 561.075 228.016C558.039 228.833 556.771 230.89 556.133 234.334C556.087 260.846 556.042 287.357 555.081 313.976C536.363 312.976 526.698 321.103 525.024 335.971C525.07 370.63 525.115 405.289 524.854 440.623C522.194 447.017 518.258 448.842 510.488 447.39C510 441.943 509.811 436.496 508.979 431.149C506.345 414.214 491.135 400.65 474.379 401.097C469.861 401.218 467.821 399.484 465.79 395.581C459.179 382.876 452.359 370.248 444.897 358.031C440.657 351.09 435.681 344.153 425.704 344.805C422.803 344.995 419.84 344.252 416.907 343.915C402.711 342.281 388.541 340.345 374.311 339.101C364.267 338.223 354.14 338.28 343.618 337.164C329.41 337.16 315.203 337.155 300.142 337.029C292.689 337.387 285.212 337.486 277.788 338.163C265.965 339.241 254.154 340.532 242.382 342.062C234.387 343.101 225.776 343.094 219.465 348.989C215.774 352.438 212.865 356.911 210.278 361.318C204.002 372.012 197.561 382.677 192.338 393.89C190.062 398.776 187.43 400.897 182.583 400.981C166.548 401.258 154.985 410.919 149.984 425.493C146.999 434.192 147.922 442.923 148.865 451.827C150.563 467.861 151.615 483.962 153.025 500.028C153.527 505.746 154.54 511.426 154.87 517.15C155.325 525.041 156.325 533.079 155.35 540.835C153.632 554.501 158.737 571.747 176.907 574.014C191.251 573.956 205.595 573.897 220.753 573.969C228.464 572.626 235.204 570.387 239.393 562.545C242.786 556.192 242.895 549.749 244.02 543.011C300.994 543.03 357.968 543.049 414.989 543.986C414.993 546.141 414.998 548.296 415 550.451C415.01 563.422 423.748 572.692 437.971 573.977C451.629 573.931 465.287 573.885 479.761 573.97C491.927 572.524 499.521 566.647 501.998 553.091C501.945 544.08 501.892 535.069 501.97 525.158C502.647 516.461 503.198 507.751 504.036 499.069C504.838 490.753 505.612 482.41 506.991 474.179C508.673 464.139 508.963 464.542 519.231 463.905C530.898 463.181 539.081 455.568 541.865 442.676C541.912 435.253 542.038 427.829 541.962 420.408C541.937 417.922 541.399 415.442 541.017 412.03C541.046 400.032 541.075 388.034 541.871 375.623ZM150.497 649.003C144.703 642.872 138.319 637.191 133.236 630.518C121.814 615.521 110.037 600.641 100.275 584.577C90.063 567.773 81.0697 550.055 73.3294 531.972C65.3452 513.32 59.9853 493.654 55.7157 473.688C51.1643 452.404 48.9346 430.915 48.1157 409.283C47.3653 389.464 48.3373 369.621 52.0644 350.087C55.3617 332.806 58.3535 315.363 63.3273 298.537C67.9233 282.988 74.268 267.837 81.1368 253.115C87.9739 238.461 95.6441 224.063 104.328 210.432C121.212 183.93 141.097 159.752 165.252 139.439C177.389 129.231 189.761 119.238 202.621 109.972C220.654 96.9809 240.206 86.4718 260.692 77.8428C270.859 73.5607 281.159 69.4829 291.661 66.1374C308.883 60.6515 326.248 55.5957 344.371 53.772C358.572 52.3429 372.709 50.0481 386.939 49.1817C397.15 48.5599 407.514 49.1501 417.725 50.1092C434.367 51.6725 451.038 53.3799 467.519 56.1028C496.555 60.9002 524.214 70.5224 550.547 83.4636C565.935 91.0262 580.471 100.326 595.362 108.895C598.244 110.553 601.202 111.214 603.175 108.128C605.054 105.19 604.537 102.081 601.292 100.029C598.135 98.0336 594.867 96.2124 591.726 94.193C570.388 80.4747 547.652 69.5969 523.848 60.9419C502.433 53.1558 480.669 46.642 457.938 43.9105C444.255 42.2664 430.613 39.7985 416.885 39.1623C402.835 38.5112 388.666 39.1292 374.619 40.1448C361.209 41.1142 347.779 42.7163 334.557 45.13C320.339 47.7254 306.208 51.0751 292.296 55.0078C264.934 62.743 239.325 74.6633 214.81 89.0191C191.049 102.933 168.938 119.182 149.367 138.44C135.771 151.818 123.518 166.628 111.304 181.328C92.8158 203.579 79.1938 228.973 67.5763 255.222C54.9393 283.775 45.6035 313.571 42.0141 344.794C39.9306 362.918 38.088 381.106 37.2172 399.318C36.708 409.967 38.0002 420.752 39.0672 431.417C40.4205 444.945 41.5498 458.578 44.2224 471.875C50.547 503.342 60.8228 533.61 75.2197 562.326C80.8388 573.534 87.6128 584.171 94.016 594.976C105.672 614.644 120.045 632.275 135.555 648.954C142.775 656.72 150.607 663.967 158.592 670.958C167.6 678.844 176.789 686.592 186.433 693.673C214.988 714.639 246.003 731.255 279.555 742.557C296.367 748.221 313.904 751.757 331.158 756.076C350.722 760.974 370.788 762.211 390.796 762.791C404.971 763.201 419.227 762.021 433.4 760.94C444.663 760.081 455.982 758.938 467.046 756.756C480.599 754.084 494.213 751.079 507.255 746.62C524.484 740.73 541.714 734.352 557.967 726.228C575.673 717.378 592.691 706.937 609.195 695.964C621.553 687.747 633.052 678.073 644.13 668.15C653.755 659.528 662.853 650.147 671.103 640.205C682.911 625.977 694.476 611.431 704.789 596.109C717.371 577.413 727.36 557.167 735.443 536.064C738.997 526.785 743.184 517.664 745.764 508.114C750.909 489.064 756.529 470.072 758.096 450.224C759.247 435.637 761.633 421.08 761.743 406.496C761.865 390.366 760.484 374.174 758.886 358.095C757.612 345.277 755.803 332.408 752.86 319.883C747.045 295.138 738.808 271.122 728.034 248.047C715.357 220.895 699.173 195.899 680.651 172.426C679.263 170.668 674.682 169.578 672.766 170.536C670.075 171.882 669.646 175.554 671.92 178.504C673.323 180.324 674.846 182.052 676.236 183.883C697.861 212.367 715.545 242.983 728.361 276.515C741.641 311.26 748.557 347.227 750.826 384.13C751.606 396.831 750.849 409.697 749.876 422.417C748.789 436.634 747.171 450.855 744.878 464.927C739.863 495.707 729.786 524.978 716.37 553.043C707.209 572.207 695.773 590.021 683.453 607.392C669.076 627.664 651.74 645.055 634.068 662.229C629.589 666.582 624.905 670.845 619.8 674.411C604.785 684.901 589.671 695.267 574.296 705.219C556.639 716.648 537.541 725.452 517.568 731.745C497.585 738.041 477.107 742.806 456.746 747.84C449.968 749.515 442.909 750.269 435.929 750.859C427.439 751.577 418.901 751.889 410.379 751.992C397.321 752.15 384.234 752.457 371.207 751.784C362.138 751.314 353.065 749.719 344.143 747.896C328.238 744.644 312.246 741.541 296.651 737.108C270.714 729.737 246.221 718.763 222.979 704.993C196.705 689.427 172.645 671.043 150.497 649.003Z\" fill=\"white\"><\/path><path d=\"M555.934 330.059C550.878 330.667 545.199 329.674 541.74 336.079C541.26 349.835 541.182 362.936 541.104 376.037C541.075 388.034 541.046 400.032 541.003 412.963C541.017 423.62 541.047 433.344 541.076 443.068C539.081 455.568 530.898 463.181 519.231 463.905C508.963 464.542 508.673 464.139 506.991 474.179C505.612 482.41 504.838 490.753 504.036 499.069C503.198 507.751 502.647 516.461 501.654 525.932C501.512 535.813 501.686 544.92 501.859 554.027C499.521 566.647 491.927 572.524 479.029 573.654C465.958 573.226 453.62 573.086 441.282 573.041C439.872 573.036 438.459 573.56 437.048 573.839C423.748 572.692 415.01 563.422 415 550.451C414.998 548.296 414.993 546.141 414.687 543.222C413.41 542.307 412.436 542.024 411.461 542.024C356.211 542.002 300.96 541.998 245.71 542.047C244.838 542.048 243.967 542.715 243.096 543.071C242.895 549.749 242.786 556.192 239.393 562.545C235.204 570.387 228.464 572.626 220.023 573.654C205.429 573.235 191.567 573.122 177.704 573.065C177.128 573.062 176.549 573.582 175.972 573.858C158.737 571.747 153.632 554.501 155.35 540.835C156.325 533.079 155.325 525.041 154.87 517.15C154.54 511.426 153.527 505.745 153.025 500.028C151.615 483.962 150.563 467.861 148.865 451.827C147.922 442.923 146.999 434.192 149.984 425.493C154.985 410.919 166.548 401.258 182.583 400.981C187.43 400.897 190.062 398.776 192.338 393.89C197.561 382.677 204.002 372.012 210.278 361.318C212.865 356.911 215.774 352.438 219.465 348.989C225.776 343.093 234.387 343.101 242.382 342.062C254.154 340.532 265.965 339.241 277.788 338.163C285.212 337.486 292.689 337.387 300.866 337.388C315.744 337.805 329.897 337.862 344.05 337.92C354.14 338.28 364.267 338.223 374.311 339.101C388.541 340.345 402.711 342.281 416.907 343.915C419.84 344.252 422.803 344.995 425.704 344.805C435.681 344.153 440.657 351.09 444.897 358.031C452.359 370.248 459.179 382.876 465.79 395.581C467.821 399.484 469.861 401.218 474.379 401.097C491.135 400.649 506.345 414.214 508.979 431.149C509.811 436.496 510 441.943 510.488 447.39C518.258 448.842 522.194 447.017 525.259 439.961C525.774 438.484 525.983 437.668 525.983 436.853C525.999 404.175 526.006 371.497 525.962 338.818C525.96 337.561 525.44 336.305 525.162 335.049C526.698 321.103 536.363 312.976 555.91 313.724C556.8 286.961 556.859 260.451 556.919 233.94C556.771 230.89 558.039 228.833 561.918 228.067C585.24 228.081 607.719 228.046 630.198 228.01C631.795 229.41 633.392 230.81 634.966 233.023C634.964 236.001 635.001 238.166 635.001 240.331C635.004 344.105 634.998 447.878 635.044 551.652C635.044 553.713 635.639 555.775 635.956 557.837C638.584 557.893 641.22 557.835 643.837 558.033C647.95 558.343 652.265 562.485 651.828 566.358C651.462 569.603 650.737 573.427 644.982 573.017C613.688 573.015 583.256 572.996 552.824 573.038C551.232 573.04 549.64 573.56 548.047 573.838C541.592 572.223 540.268 570.471 540.994 564.038C541.557 559.053 544.919 557.852 549.368 557.935C551.269 557.97 553.183 557.321 555.797 557.004C556.668 556.083 556.977 555.141 556.977 554.198C556.999 481.038 557.004 407.878 556.953 334.719C556.952 333.165 556.288 331.612 555.934 330.059ZM383.951 522.719C383.624 522.519 383.297 522.32 382.3 521.796C378.787 520.864 375.322 519.592 371.749 519.096C368.207 518.603 364.556 518.892 360.302 518.337C359.489 518.227 358.675 518.019 357.862 518.019C337.843 518 317.824 517.988 297.805 518.039C296.551 518.042 295.299 518.56 293.115 518.97C285.885 519.367 277.995 517.039 271.678 524.265C269.235 529.396 273.998 526.856 274.944 526.861C310.071 527.023 345.2 527.009 380.328 526.96C381.922 526.958 383.515 526.409 385.362 525.977C385.362 525.977 385.648 526.019 386.194 525.925C386.03 525.612 385.866 525.299 385.22 524.787C384.805 524.248 384.391 523.709 383.951 522.719ZM437.882 557.625C450.307 557.754 462.732 557.915 475.158 557.971C476.746 557.979 478.336 557.442 480.588 556.85C487.497 552.544 485.726 545.73 485.956 539.716C480.462 540.54 475.247 541.321 469.097 541.986C461.035 542.01 452.973 542.033 444.062 542.011C440.103 542.503 436.145 542.995 431.863 543.527C432.778 548.641 429.499 554.961 437.882 557.625ZM221.394 556.926C226.333 553.472 226.654 548.653 225.689 543.671C207.867 539.343 189.516 547.057 172.006 538.963C172.006 542.982 171.679 546.344 172.095 549.612C172.54 553.098 172.943 557.087 178.645 557.696C190.734 557.8 202.822 557.942 214.911 557.969C216.838 557.973 218.767 557.459 221.394 556.926ZM425.243 415.878C422.245 415.921 419.247 416.002 416.249 416.002C354.771 416.006 293.293 416 231.057 416.016C229.67 414.673 227.13 413.364 227.089 411.982C226.874 404.662 226.556 397.212 227.662 390.021C229.154 380.318 231.909 370.809 234.122 361.217C231.725 362.158 229.414 363.577 228.244 365.642C219.69 380.739 211.241 395.9 203.048 411.195C200.805 415.384 197.991 417.218 193.265 417.087C189.027 416.969 184.611 416.969 180.551 418.005C169.499 420.826 164.044 429.896 165.031 441.052C165.869 450.535 166.991 459.993 167.955 469.466C169.336 483.031 170.6 496.609 172.086 510.162C172.888 517.477 177.015 525.421 187.772 526.654C205.903 526.749 224.034 526.852 242.165 526.908C242.76 526.909 243.357 526.421 244.662 526.013C251.217 520.064 257.569 513.867 264.42 508.281C267.422 505.833 271.441 504.631 275.93 502.969C311.64 502.952 347.351 502.934 383.806 502.991C386.937 504.893 390.415 506.398 393.121 508.782C397.959 513.042 402.229 517.94 406.949 522.344C408.671 523.95 410.997 524.907 413.698 526.662C432.192 526.755 450.686 526.855 469.18 526.907C469.77 526.908 470.362 526.421 471.71 526.028C478.882 524.204 483.468 519.764 484.967 512.476C485.59 509.446 485.719 506.314 486.059 503.227C487.371 491.335 488.625 479.436 490.006 467.552C490.875 460.075 492.161 452.642 492.846 445.152C493.793 434.782 492.627 426.336 482.397 419.971C477.115 416.684 471.119 416.677 465.189 417.04C459.632 417.381 456.307 415.314 453.81 410.034C447.968 397.684 441.719 385.494 434.949 373.631C432.212 368.833 430.029 362.828 424.399 361.288C426.69 375.697 428.987 390.237 431.323 404.771C432.174 410.07 430.149 414.602 425.243 415.878ZM572.838 355.5C572.838 422.853 572.838 490.206 572.838 557.607C588.869 557.607 603.951 557.607 619.237 557.607C619.237 452.817 619.237 348.342 619.237 243.752C603.63 243.752 588.418 243.752 572.838 243.752C572.838 280.92 572.838 317.71 572.838 355.5ZM356.391 354.228C324.801 352.633 293.275 353.943 261.775 356.36C254.84 356.892 253.045 358.447 250.98 365.212C249.867 368.859 248.472 372.439 247.622 376.144C245.835 383.939 244.323 391.796 242.652 399.853C300.537 399.853 357.283 399.853 414.488 399.853C414.08 396.898 413.962 394.238 413.317 391.713C411.1 383.025 408.692 374.385 406.368 365.724C403.954 356.732 403.605 356.591 394.165 356.159C381.889 355.597 369.625 354.798 356.391 354.228Z\" fill=\"#15A8AA\"><\/path><path d=\"M150.747 649.253C172.645 671.044 196.705 689.427 222.979 704.994C246.221 718.763 270.713 729.737 296.651 737.108C312.246 741.541 328.238 744.644 344.143 747.896C353.065 749.719 362.138 751.314 371.207 751.784C384.234 752.458 397.321 752.15 410.379 751.992C418.901 751.889 427.439 751.577 435.928 750.859C442.908 750.269 449.967 749.515 456.746 747.84C477.107 742.806 497.585 738.041 517.568 731.745C537.541 725.452 556.639 716.648 574.296 705.219C589.671 695.268 604.784 684.901 619.799 674.411C624.905 670.845 629.589 666.582 634.068 662.229C651.74 645.055 669.076 627.664 683.453 607.392C695.773 590.021 707.209 572.207 716.37 553.043C729.786 524.978 739.863 495.707 744.878 464.927C747.171 450.855 748.789 436.634 749.876 422.417C750.849 409.697 751.606 396.831 750.826 384.13C748.557 347.227 741.64 311.26 728.361 276.515C715.544 242.983 697.86 212.367 676.236 183.883C674.846 182.053 673.323 180.325 671.92 178.504C669.645 175.554 670.075 171.882 672.766 170.536C674.682 169.578 679.263 170.668 680.651 172.426C699.173 195.899 715.357 220.895 728.034 248.047C738.808 271.122 747.045 295.138 752.859 319.883C755.802 332.408 757.611 345.277 758.886 358.095C760.484 374.174 761.864 390.366 761.742 406.496C761.632 421.08 759.246 435.637 758.095 450.224C756.529 470.072 750.909 489.065 745.763 508.114C743.184 517.664 738.997 526.785 735.443 536.065C727.36 557.167 717.371 577.413 704.789 596.109C694.476 611.432 682.911 625.977 671.103 640.205C662.853 650.147 653.754 659.528 644.13 668.15C633.052 678.073 621.552 687.748 609.195 695.964C592.691 706.937 575.673 717.378 557.966 726.228C541.714 734.352 524.484 740.73 507.255 746.62C494.213 751.079 480.598 754.084 467.045 756.756C455.981 758.938 444.663 760.081 433.4 760.94C419.227 762.021 404.971 763.201 390.796 762.791C370.788 762.211 350.722 760.974 331.158 756.076C313.904 751.757 296.367 748.221 279.555 742.557C246.003 731.255 214.988 714.639 186.433 693.673C176.789 686.592 167.6 678.844 158.591 670.958C150.606 663.967 142.775 656.72 135.555 648.954C120.045 632.275 105.671 614.644 94.0158 594.976C87.6126 584.171 80.8386 573.534 75.2195 562.326C60.8226 533.61 50.5468 503.342 44.2222 471.875C41.5496 458.578 40.4203 444.945 39.067 431.417C38 420.752 36.7078 409.967 37.217 399.318C38.0878 381.107 39.9303 362.918 42.0139 344.794C45.6033 313.571 54.9391 283.775 67.576 255.222C79.1936 228.973 92.8156 203.579 111.303 181.329C123.518 166.628 135.771 151.819 149.367 138.44C168.938 119.182 191.049 102.934 214.81 89.0191C239.325 74.6634 264.933 62.7431 292.296 55.0078C306.207 51.0752 320.339 47.7255 334.557 45.13C347.779 42.7164 361.209 41.1143 374.619 40.1448C388.666 39.1293 402.835 38.5113 416.884 39.1624C430.612 39.7986 444.255 42.2664 457.937 43.9106C480.669 46.6421 502.432 53.1558 523.847 60.9419C547.652 69.5969 570.388 80.4748 591.726 94.193C594.867 96.2124 598.135 98.0337 601.292 100.029C604.537 102.081 605.053 105.19 603.175 108.128C601.202 111.214 598.243 110.553 595.362 108.895C580.471 100.326 565.935 91.0263 550.546 83.4637C524.214 70.5225 496.555 60.9003 467.518 56.1029C451.038 53.38 434.367 51.6725 417.725 50.1093C407.514 49.1502 397.15 48.5599 386.938 49.1818C372.709 50.0482 358.572 52.343 344.37 53.7721C326.248 55.5958 308.883 60.6516 291.661 66.1374C281.159 69.483 270.859 73.5607 260.692 77.8429C240.205 86.4719 220.653 96.981 202.621 109.972C189.761 119.238 177.388 129.231 165.251 139.439C141.097 159.752 121.212 183.93 104.328 210.432C95.6439 224.063 87.9737 238.461 81.1366 253.115C74.2678 267.837 67.9231 282.989 63.3271 298.537C58.3533 315.363 55.3615 332.806 52.0642 350.088C48.3371 369.621 47.3651 389.464 48.1155 409.284C48.9344 430.916 51.1641 452.404 55.7155 473.688C59.9851 493.654 65.345 513.32 73.3292 531.973C81.0695 550.055 90.0628 567.773 100.275 584.577C110.037 600.641 121.814 615.521 133.236 630.518C138.318 637.191 144.703 642.872 150.747 649.253Z\" fill=\"#17A9AB\"><\/path><path d=\"M360.825 259.837C362.076 260.823 363.185 262.174 364.605 262.726C368.669 264.305 372.882 265.497 376.996 266.955C384.859 269.739 386.935 276.117 381.128 282.217C368.851 295.111 356.232 307.701 343.255 319.884C341.074 321.932 336.019 322.491 332.985 321.536C330.744 320.83 328.458 316.635 328.248 313.84C327.783 307.647 328.704 301.36 328.881 295.106C328.995 291.068 327.035 288.261 323.123 286.967C318.951 285.588 314.627 284.561 310.625 282.798C303.894 279.834 302.731 272.79 307.949 267.542C320.152 255.265 332.399 243.031 344.7 230.853C349.559 226.043 356.351 226.728 359.82 232.981C359.949 237.257 359.909 240.73 360.041 244.198C360.239 249.413 360.558 254.624 360.825 259.837ZM334.544 273.01C343.733 275.849 346.689 282.35 344.706 292.358C349.694 286.973 353.911 282.422 357.752 278.275C354.352 276.641 349.138 275.637 346.574 272.48C343.997 269.307 344.059 263.991 343.145 260.339C339.472 263.831 335.406 267.696 331.08 271.809C332.134 272.268 332.97 272.633 334.544 273.01Z\" fill=\"#16A9AB\"><\/path><path d=\"M635.969 557.383C635.639 555.775 635.045 553.713 635.044 551.652C634.998 447.878 635.004 344.105 635.001 240.331C635.001 238.166 634.964 236.001 634.991 233.362C635.358 234.214 635.96 235.539 635.96 236.865C635.997 343.553 635.987 450.241 635.969 557.383Z\" fill=\"#91D7D9\"><\/path><path d=\"M555.962 330.521C556.288 331.612 556.952 333.165 556.953 334.719C557.004 407.878 556.999 481.038 556.977 554.198C556.977 555.141 556.668 556.083 556.216 556.966C555.949 481.598 555.969 406.291 555.962 330.521Z\" fill=\"#51BEC1\"><\/path><path d=\"M243.558 543.041C243.967 542.715 244.838 542.048 245.71 542.047C300.96 541.998 356.211 542.002 411.461 542.024C412.436 542.024 413.41 542.307 414.664 542.763C357.968 543.049 300.994 543.03 243.558 543.041Z\" fill=\"#51BEC1\"><\/path><path d=\"M525.093 335.51C525.44 336.305 525.96 337.562 525.962 338.819C526.006 371.497 525.999 404.175 525.983 436.853C525.983 437.668 525.774 438.484 525.412 439.623C525.115 405.289 525.07 370.63 525.093 335.51Z\" fill=\"#51BEC1\"><\/path><path d=\"M548.509 573.908C549.64 573.56 551.232 573.04 552.824 573.038C583.256 572.996 613.688 573.016 644.591 573.043C643.544 573.377 642.027 573.959 640.509 573.961C609.996 574.006 579.483 573.985 548.509 573.908Z\" fill=\"#51BEC1\"><\/path><path d=\"M556.525 234.137C556.859 260.451 556.799 286.961 556.369 313.67C556.042 287.357 556.087 260.846 556.525 234.137Z\" fill=\"#C1E9E9\"><\/path><path d=\"M629.998 227.602C607.72 228.046 585.241 228.082 562.282 228.064C562.449 227.658 563.097 226.997 563.745 226.998C585.762 227.025 607.78 227.115 629.998 227.602Z\" fill=\"#97D9DB\"><\/path><path d=\"M176.439 573.936C176.549 573.582 177.128 573.062 177.704 573.065C191.567 573.122 205.429 573.235 219.616 573.589C205.595 573.897 191.251 573.956 176.439 573.936Z\" fill=\"#52BFC2\"><\/path><path d=\"M343.834 337.542C329.897 337.862 315.744 337.805 301.293 337.449C315.203 337.155 329.41 337.159 343.834 337.542Z\" fill=\"#80D0D3\"><\/path><path d=\"M437.51 573.908C438.46 573.56 439.872 573.036 441.282 573.041C453.621 573.086 465.958 573.226 478.621 573.588C465.287 573.885 451.629 573.931 437.51 573.908Z\" fill=\"#51BEC1\"><\/path><path d=\"M541.488 375.83C541.182 362.936 541.259 349.835 541.59 336.415C541.852 349.271 541.862 362.447 541.488 375.83Z\" fill=\"#BFE8E8\"><\/path><path d=\"M541.471 442.872C541.047 433.344 541.017 423.62 541.042 413.427C541.399 415.441 541.937 417.922 541.962 420.407C542.038 427.829 541.912 435.253 541.471 442.872Z\" fill=\"#BCE7E7\"><\/path><path d=\"M501.929 553.559C501.685 544.92 501.512 535.813 501.588 526.382C501.892 535.069 501.945 544.08 501.929 553.559Z\" fill=\"#52BFC1\"><\/path><path d=\"M360.894 259.384C360.558 254.624 360.239 249.413 360.041 244.198C359.909 240.73 359.949 237.257 359.958 233.308C360.333 234.463 360.925 236.094 360.947 237.733C361.043 244.798 360.972 251.866 360.894 259.384Z\" fill=\"#97D9DB\"><\/path><path d=\"M274.998 502.863C271.441 504.631 267.422 505.833 264.42 508.281C257.57 513.867 251.217 520.064 243.846 526.018C224.393 526.075 205.758 526.127 187.122 526.179C177.016 525.421 172.888 517.477 172.086 510.162C170.6 496.609 169.336 483.031 167.955 469.466C166.991 459.993 165.869 450.535 165.031 441.052C164.044 429.896 169.5 420.826 180.551 418.005C184.611 416.969 189.027 416.969 193.265 417.087C197.991 417.218 200.805 415.384 203.049 411.195C211.241 395.9 219.69 380.739 228.245 365.642C229.414 363.577 231.725 362.158 234.122 361.217C231.909 370.809 229.154 380.318 227.662 390.021C226.556 397.212 226.874 404.662 227.089 411.982C227.13 413.364 229.67 414.673 231.642 416.409C232.716 416.877 233.205 417.019 233.694 417.019C296.713 417.026 359.733 417.028 422.753 416.977C423.903 416.976 425.053 416.333 426.203 415.989C430.149 414.602 432.174 410.07 431.323 404.771C428.987 390.237 426.691 375.697 424.399 361.288C430.029 362.828 432.212 368.833 434.95 373.63C441.719 385.494 447.968 397.684 453.81 410.034C456.307 415.314 459.632 417.381 465.189 417.04C471.119 416.677 477.115 416.684 482.397 419.971C492.627 426.336 493.793 434.782 492.846 445.152C492.161 452.642 490.875 460.075 490.006 467.552C488.625 479.436 487.371 491.335 486.059 503.227C485.719 506.314 485.59 509.446 484.967 512.476C483.468 519.764 478.883 524.204 470.87 526.026C451.036 526.069 432.042 526.115 413.048 526.161C410.998 524.907 408.671 523.95 406.95 522.344C402.23 517.94 397.959 513.042 393.121 508.782C390.416 506.398 386.937 504.892 383.237 502.561C347.465 502.088 312.262 502.04 277.059 502.037C276.372 502.037 275.685 502.576 274.998 502.863ZM369.795 487.041C374.757 486.756 376.474 483.034 376.368 479.194C376.258 475.19 374.03 471.792 368.588 471.202C341.675 471.114 314.762 471.019 287.849 470.983C287.183 470.982 286.516 471.631 285.207 472.289C281.226 474.037 280.445 477.628 281.247 481.127C282.081 484.765 284.491 487.576 289.38 487.87C315.091 487.913 340.803 487.965 366.514 487.961C367.354 487.961 368.194 487.402 369.795 487.041ZM187.025 438.973C187.064 456.99 187.103 475.007 187.054 493.793C187.351 494.883 187.684 495.965 187.939 497.065C190.637 508.687 203.951 519.465 215.722 518.924C219.836 518.736 225.079 519.103 226.89 513.833C228.669 508.657 225.196 503.7 219.294 503.073C207.766 501.848 203.024 495.421 203.96 485.665C204.212 483.042 203.999 480.374 203.999 477.377C205.19 477.827 206.153 478.047 206.97 478.521C222.282 487.399 239.247 487.873 256.195 487.904C265.213 487.92 269.291 481.213 264.697 474.504C262.294 470.994 259.409 467.698 256.264 464.83C239.659 449.691 219.774 440.34 198.853 432.94C192.091 430.548 190.031 431.58 187.025 438.973ZM469.977 437.148C467.835 432.529 463.974 430.678 458.903 432.654C451.624 435.491 444.553 438.855 437.379 441.963C420.713 449.182 405.766 458.875 393.823 472.728C389.538 477.698 391.838 485.501 397.849 486.849C401.025 487.562 404.367 488.083 407.595 487.919C419.991 487.288 432.389 486.449 444.05 481.528C447.266 480.171 450.501 478.857 454.001 477.41C454.001 480.366 453.935 482.861 454.013 485.351C454.273 493.616 450.738 501.065 440.116 502.066C438.371 502.231 436.328 502.581 435.061 503.623C433.372 505.011 431.474 507.031 431.167 509.011C430.673 512.207 429.944 516.605 434.484 517.628C438.142 518.452 442.147 518.345 445.921 517.939C458.859 516.55 469.263 505.667 470.847 492.669C470.906 475.068 470.976 457.466 470.983 439.864C470.983 439.208 470.37 438.552 469.977 437.148Z\" fill=\"white\"><\/path><path d=\"M572.837 355C572.837 317.71 572.837 280.92 572.837 243.752C588.418 243.752 603.63 243.752 619.236 243.752C619.236 348.342 619.236 452.817 619.236 557.607C603.951 557.607 588.868 557.607 572.837 557.607C572.837 490.206 572.837 422.853 572.837 355Z\" fill=\"#EEA629\"><\/path><path d=\"M356.873 354.165C369.625 354.798 381.889 355.597 394.165 356.159C403.604 356.591 403.954 356.732 406.367 365.724C408.692 374.385 411.099 383.025 413.317 391.713C413.962 394.238 414.08 396.898 414.488 399.854C357.283 399.854 300.537 399.854 242.652 399.854C244.323 391.796 245.835 383.939 247.622 376.144C248.472 372.439 249.866 368.859 250.98 365.212C253.045 358.447 254.839 356.892 261.775 356.36C293.275 353.943 324.801 352.633 356.873 354.165Z\" fill=\"#F0A628\"><\/path><path d=\"M178.011 557.15C172.943 557.087 172.54 553.098 172.095 549.612C171.679 546.344 172.006 542.982 172.006 538.963C189.516 547.057 207.867 539.343 225.689 543.671C226.654 548.653 226.333 553.472 220.603 557.004C205.878 557.105 191.944 557.127 178.011 557.15Z\" fill=\"white\"><\/path><path d=\"M470.032 542.103C475.247 541.321 480.462 540.54 485.956 539.716C485.725 545.73 487.497 552.544 479.793 556.958C465.076 557.103 451.154 557.14 437.231 557.177C429.498 554.961 432.778 548.641 431.863 543.527C436.145 542.995 440.103 542.503 444.678 542.434C449.738 542.891 454.186 543.048 458.626 542.924C462.433 542.817 466.23 542.389 470.032 542.103Z\" fill=\"white\"><\/path><path d=\"M385.648 526.02C385.648 526.02 385.362 525.978 384.755 525.998C360.886 526.012 337.625 526.005 314.365 526C301.571 525.998 288.777 526.054 275.985 525.912C274.766 525.898 273.56 524.659 272.348 523.988C277.996 517.039 285.885 519.367 294.043 518.974C316.964 518.931 338.958 518.885 360.952 518.838C364.556 518.892 368.207 518.604 371.749 519.096C375.322 519.592 378.787 520.864 382.722 522.197C383.422 522.788 383.699 522.979 383.976 523.17C384.391 523.709 384.805 524.248 385.525 525.149C385.77 525.681 385.709 525.85 385.648 526.02Z\" fill=\"white\"><\/path><path d=\"M425.723 415.933C425.053 416.333 423.903 416.976 422.753 416.977C359.733 417.029 296.713 417.026 233.693 417.019C233.205 417.019 232.716 416.877 232.021 416.399C293.293 416 354.771 416.006 416.249 416.002C419.247 416.002 422.245 415.921 425.723 415.933Z\" fill=\"#93D8DA\"><\/path><path d=\"M272.013 524.127C273.56 524.659 274.766 525.898 275.985 525.912C288.777 526.054 301.571 525.998 314.364 526C337.625 526.005 360.886 526.012 384.627 526.066C383.515 526.409 381.922 526.958 380.328 526.96C345.2 527.009 310.071 527.023 274.944 526.861C273.998 526.856 269.235 529.396 272.013 524.127Z\" fill=\"#51BEC1\"><\/path><path d=\"M275.464 502.916C275.685 502.576 276.372 502.037 277.059 502.037C312.262 502.04 347.465 502.088 382.864 502.524C347.351 502.934 311.64 502.952 275.464 502.916Z\" fill=\"#C1E9E9\"><\/path><path d=\"M360.627 518.588C338.958 518.885 316.964 518.931 294.508 518.909C295.299 518.561 296.551 518.042 297.805 518.039C317.823 517.989 337.843 518 357.862 518.019C358.675 518.02 359.489 518.227 360.627 518.588Z\" fill=\"#51BEC1\"><\/path><path d=\"M413.373 526.412C432.042 526.115 451.035 526.069 470.491 526.092C470.361 526.421 469.77 526.908 469.18 526.907C450.685 526.855 432.191 526.755 413.373 526.412Z\" fill=\"#51BEC1\"><\/path><path d=\"M187.447 526.416C205.757 526.127 224.393 526.075 243.491 526.092C243.357 526.421 242.76 526.909 242.165 526.908C224.034 526.852 205.903 526.749 187.447 526.416Z\" fill=\"#51BEC1\"><\/path><path d=\"M437.557 557.401C451.154 557.14 465.076 557.103 479.461 557.111C478.336 557.442 476.746 557.979 475.158 557.971C462.732 557.915 450.307 557.754 437.557 557.401Z\" fill=\"#BCE7E7\"><\/path><path d=\"M178.328 557.423C191.944 557.127 205.878 557.105 220.253 557.133C218.767 557.459 216.838 557.973 214.911 557.969C202.822 557.942 190.733 557.8 178.328 557.423Z\" fill=\"#BDE7E8\"><\/path><path d=\"M469.565 542.044C466.231 542.389 462.433 542.817 458.627 542.924C454.186 543.048 449.738 542.891 445.103 542.456C452.973 542.033 461.035 542.01 469.565 542.044Z\" fill=\"#AEE2E3\"><\/path><path d=\"M383.964 522.944C383.699 522.979 383.422 522.788 383.058 522.359C383.297 522.32 383.624 522.519 383.964 522.944Z\" fill=\"#51BEC1\"><\/path><path d=\"M385.921 525.972C385.709 525.85 385.77 525.681 385.766 525.249C385.866 525.299 386.03 525.612 385.921 525.972Z\" fill=\"#51BEC1\"><\/path><path d=\"M334.175 273.004C332.97 272.633 332.134 272.269 331.081 271.809C335.407 267.696 339.472 263.831 343.146 260.339C344.059 263.991 343.997 269.307 346.574 272.48C349.138 275.637 354.352 276.641 357.752 278.275C353.911 282.422 349.695 286.974 344.706 292.359C346.689 282.35 343.733 275.849 334.175 273.004Z\" fill=\"white\"><\/path><path d=\"M470.064 493.074C469.263 505.667 458.859 516.55 445.921 517.94C442.146 518.345 438.142 518.452 434.484 517.628C429.944 516.605 430.673 512.207 431.167 509.011C431.473 507.031 433.372 505.011 435.061 503.623C436.327 502.581 438.371 502.231 440.115 502.066C450.737 501.065 454.273 493.616 454.013 485.351C453.935 482.861 454.001 480.366 454.001 477.41C450.501 478.857 447.266 480.171 444.05 481.528C432.389 486.449 419.991 487.288 407.595 487.919C404.367 488.083 401.025 487.562 397.849 486.849C391.837 485.501 389.538 477.698 393.822 472.728C405.766 458.875 420.713 449.182 437.379 441.963C444.552 438.855 451.624 435.491 458.902 432.654C463.974 430.678 467.835 432.529 469.949 437.994C469.969 456.918 470.016 474.996 470.064 493.074ZM448.48 459.014C450.187 457.088 451.894 455.161 453.601 453.235C453.355 452.904 453.109 452.572 452.863 452.241C442.67 457.826 432.478 463.412 422.286 468.997C432.298 469.223 440.573 465.461 448.48 459.014Z\" fill=\"#16A9AB\"><\/path><path d=\"M187.164 438.05C190.031 431.58 192.091 430.548 198.853 432.94C219.774 440.34 239.659 449.691 256.264 464.83C259.409 467.698 262.294 470.994 264.697 474.504C269.291 481.213 265.213 487.92 256.195 487.904C239.247 487.873 222.282 487.399 206.97 478.521C206.154 478.047 205.19 477.827 203.999 477.377C203.999 480.374 204.212 483.042 203.96 485.665C203.024 495.421 207.766 501.848 219.294 503.073C225.196 503.7 228.669 508.657 226.89 513.833C225.079 519.103 219.836 518.736 215.722 518.924C203.951 519.465 190.637 508.687 187.939 497.065C187.684 495.965 187.351 494.883 187.376 493.094C187.777 474.872 187.865 457.35 187.905 439.827C187.906 439.235 187.422 438.642 187.164 438.05ZM210.067 460.532C217.535 466.226 225.8 469.677 235.647 468.934C225.396 463.474 215.145 458.014 204.895 452.553C204.586 453.002 204.277 453.451 203.968 453.899C205.834 455.934 207.7 457.97 210.067 460.532Z\" fill=\"#15A8AB\"><\/path><path d=\"M288.966 487.103C284.491 487.576 282.08 484.765 281.247 481.127C280.445 477.628 281.226 474.037 286.005 472.182C314.22 472.028 341.637 471.98 369.054 471.933C374.03 471.792 376.257 475.19 376.368 479.194C376.474 483.034 374.757 486.756 368.946 487.02C341.72 487.034 315.343 487.068 288.966 487.103Z\" fill=\"#14A8AA\"><\/path><path d=\"M368.821 471.567C341.637 471.98 314.22 472.028 286.327 472.026C286.516 471.632 287.183 470.982 287.848 470.983C314.762 471.019 341.675 471.114 368.821 471.567Z\" fill=\"#53BFC2\"><\/path><path d=\"M289.173 487.486C315.343 487.068 341.72 487.034 368.565 487.051C368.193 487.402 367.354 487.962 366.514 487.962C340.803 487.965 315.091 487.913 289.173 487.486Z\" fill=\"#C1E9E9\"><\/path><path d=\"M470.455 492.872C470.016 474.996 469.968 456.918 469.981 438.368C470.369 438.552 470.983 439.208 470.982 439.864C470.976 457.466 470.906 475.068 470.455 492.872Z\" fill=\"#95D8DA\"><\/path><path d=\"M187.094 438.511C187.422 438.642 187.906 439.235 187.905 439.827C187.865 457.35 187.778 474.872 187.419 492.709C187.103 475.007 187.064 456.99 187.094 438.511Z\" fill=\"#52BFC1\"><\/path><path d=\"M448.221 459.269C440.573 465.461 432.298 469.223 422.286 468.998C432.478 463.412 442.67 457.826 452.863 452.241C453.109 452.572 453.355 452.904 453.601 453.235C451.894 455.162 450.187 457.088 448.221 459.269Z\" fill=\"white\"><\/path><path d=\"M209.816 460.269C207.699 457.97 205.833 455.935 203.967 453.899C204.276 453.451 204.585 453.002 204.894 452.553C215.145 458.014 225.396 463.474 235.647 468.934C225.799 469.677 217.535 466.226 209.816 460.269Z\" fill=\"white\"><\/path><\/g><defs><clipPath id=\"clip0_1427_3702\"><rect width=\"800\" height=\"800\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tConnectez-vous \u00e0 notre Portail :\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tEnfin, acc\u00e9dez \u00e0 notre Portail d\u00e9di\u00e9 aux installateurs partenaires. Cet outil est con\u00e7u pour simplifier votre gestion de projets. Vous b\u00e9n\u00e9ficierez \u00e9galement d'une formation personnalis\u00e9e pour ma\u00eetriser toutes les fonctionnalit\u00e9s du Portail et optimiser votre exp\u00e9rience avec Time2plug.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<aside class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9ccd4a0\" data-id=\"9ccd4a0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e7c52d elementor-hidden-mobile elementor-invisible elementor-widget elementor-widget-image\" data-id=\"2e7c52d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.5,&quot;sizes&quot;:[]},&quot;_animation&quot;:&quot;slideInRight&quot;,&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1384\" height=\"1239\" src=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/04\/Frame-1274.png\" class=\"attachment-2048x2048 size-2048x2048 wp-image-12090\" alt=\"Analyse, Installation et Gestion de borne de recharge\" srcset=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/04\/Frame-1274.png 1384w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/04\/Frame-1274-300x269.png 300w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/04\/Frame-1274-1024x917.png 1024w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/04\/Frame-1274-768x688.png 768w\" sizes=\"(max-width: 1384px) 100vw, 1384px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-910fcad elementor-hidden-desktop elementor-hidden-tablet elementor-invisible elementor-widget elementor-widget-image\" data-id=\"910fcad\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInRight&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1384\" height=\"1239\" src=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/04\/Frame-1274.png\" class=\"attachment-2048x2048 size-2048x2048 wp-image-12090\" alt=\"Analyse, Installation et Gestion de borne de recharge\" srcset=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/04\/Frame-1274.png 1384w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/04\/Frame-1274-300x269.png 300w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/04\/Frame-1274-1024x917.png 1024w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/04\/Frame-1274-768x688.png 768w\" sizes=\"(max-width: 1384px) 100vw, 1384px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/aside>\n\t\t\t\t\t<\/div>\n\t\t<\/main>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ac2883d elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"ac2883d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-be3e48e\" data-id=\"be3e48e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d722a9 elementor-widget elementor-widget-heading\" data-id=\"5d722a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"color:#061360\">Notre Portail installateur,<\/span> votre outil d'accompagnement optimal <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<main class=\"elementor-section elementor-top-section elementor-element elementor-element-3b4db38 elementor-section-content-middle elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"3b4db38\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<aside class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fc59a56\" data-id=\"fc59a56\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;animation&quot;:&quot;none&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cd99f86 elementor-widget__width-initial elementor-hidden-mobile elementor-invisible elementor-widget elementor-widget-image\" data-id=\"cd99f86\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInLeft&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/06\/Mockup-tablette-1024x768.png\" class=\"attachment-large size-large wp-image-13749\" alt=\"Mockup du portail installateur Time2plug\" srcset=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/06\/Mockup-tablette-1024x768.png 1024w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/06\/Mockup-tablette-300x225.png 300w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/06\/Mockup-tablette-768x576.png 768w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/06\/Mockup-tablette.png 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/aside>\n\t\t\t\t<article class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-dc3baad\" data-id=\"dc3baad\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;animation&quot;:&quot;none&quot;,&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5b24e6e elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"5b24e6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tValidez instantan\u00e9ment les missions propos\u00e9es par nos experts\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e81920 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"7e81920\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tGardez un \u0153il sur vos projets en temps r\u00e9el\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb836e3 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"bb836e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPlanifiez vos interventions directement selon vos disponibilit\u00e9s\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b93b5ef elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"b93b5ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAcc\u00e9dez \u00e0 la documentation et aux contacts du projet o\u00f9 que vous soyez\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ddad73b elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"ddad73b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tUtilisez notre g\u00e9n\u00e9rateur de devis int\u00e9gr\u00e9 et suivez leur statut en un clic\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t\t<\/div>\n\t\t<\/main>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6345535 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6345535\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-04306d1\" data-id=\"04306d1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c3e3ef4 elementor-widget elementor-widget-heading\" data-id=\"c3e3ef4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"color:#061360\">Quelques<\/span> chiffres cl\u00e9s :<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<main class=\"elementor-section elementor-top-section elementor-element elementor-element-082e87f elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"082e87f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<article class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0d17d7a\" data-id=\"0d17d7a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8d7391e elementor-widget elementor-widget-counter\" data-id=\"8d7391e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<h3 class=\"elementor-counter-title\"> installateurs partenaires<\/h3>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\">+ <\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"400\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4152848\" data-id=\"4152848\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d25956 elementor-widget elementor-widget-counter\" data-id=\"0d25956\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<h3 class=\"elementor-counter-title\">expert attribu\u00e9 par projet.<\/h3>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"1\" data-from-value=\"1\" data-delimiter=\",\">1<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b427179\" data-id=\"b427179\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a7c435d elementor-widget elementor-widget-counter\" data-id=\"a7c435d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<h3 class=\"elementor-counter-title\">projets trait\u00e9s en 2023.<\/h3>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\">+ <\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"1000\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t\t<\/div>\n\t\t<\/main>\n\t\t\t\t<main class=\"elementor-section elementor-top-section elementor-element elementor-element-3d91d67 elementor-section-full_width elementor-section-stretched elementor-hidden-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"3d91d67\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2d5646d\" data-id=\"2d5646d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5b8a709 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"5b8a709\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Supervision<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a71c47a elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"a71c47a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00c0 partir de 2035, l&rsquo;Union europ\u00e9enne interdira la vente de voitures neuves \u00e9quip\u00e9es de moteurs thermiques. D\u00e8s lors, seuls les v\u00e9hicules neufs 100 % \u00e9lectriques seront autoris\u00e9s \u00e0 la vente, une d\u00e9cision vot\u00e9e par le Parlement europ\u00e9en le 8 juin 2022. Ainsi, parall\u00e8lement \u00e0 cette \u00e9volution, la Loi d&rsquo;Orientation des Mobilit\u00e9s (LOM), promulgu\u00e9e le 26 d\u00e9cembre 2019, renforce la transition vers la mobilit\u00e9 \u00e9lectrique.<\/p><p>Selon la LOM, d&rsquo;une part, les b\u00e2timents non r\u00e9sidentiels dot\u00e9s d&rsquo;un parking de plus de vingt places doivent \u00eatre \u00e9quip\u00e9s d&rsquo;au moins un point de recharge pour v\u00e9hicules \u00e9lectriques et hybrides d&rsquo;ici le 1er janvier 2025. D&rsquo;autre part, depuis 2017, l&rsquo;intervention d&rsquo;un technicien certifi\u00e9 IRVE est obligatoire pour l&rsquo;installation de bornes de recharge d\u00e9livrant une puissance sup\u00e9rieure ou \u00e9gale \u00e0 3,7 kW en courant alternatif.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7a2b69 elementor-align-center elementor-widget__width-inherit elementor-widget elementor-widget-button\" data-id=\"b7a2b69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.time2plug.com\/page\/la-supervision-chez-time2plug\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">D\u00e9couvrir<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/main>\n\t\t\t\t<main class=\"elementor-section elementor-top-section elementor-element elementor-element-1f54c45 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"1f54c45\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-12116a2\" data-id=\"12116a2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2442c61 elementor-widget elementor-widget-heading\" data-id=\"2442c61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"color:#061360\">L'avis de <\/span>nos installateurs :<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9187b2 elementor-arrows-yes elementor-pagination-type-bullets elementor--star-style-star_fontawesome elementor-widget elementor-widget-reviews\" data-id=\"d9187b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_per_view&quot;:&quot;3&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"reviews.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositives\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial elementor-repeater-item-e533a6c\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__header\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/06\/groupe_jp_fauch_logo.jpg\" alt=\"Fauch\u00e9\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Fauch\u00e9<\/span><\/cite>\t\t\t\t\t<div class=\"elementor-testimonial__icon elementor-icon elementor-icon-\" aria-label=\"Lire plus\"><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\tDe belles opportunit\u00e9s amen\u00e9es par une \u00e9quipe dynamique et comp\u00e9tente. Une interface conviviale permet de r\u00e9ceptionner les offres de mission avec un contact d\u00e9di\u00e9 \u00e0 chaque affaire.\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial elementor-repeater-item-4de06ee\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__header\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/06\/images-e1718808100240.png\" alt=\"Luxelec2.0\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Luxelec2.0<\/span><\/cite>\t\t\t\t\t<div class=\"elementor-testimonial__icon elementor-icon elementor-icon-\" aria-label=\"Lire plus\"><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\tTout s'est tr\u00e8s bien pass\u00e9. Le client est satisfait, et le service a \u00e9t\u00e9 rapide. La borne a \u00e9t\u00e9 re\u00e7ue \u00e0 temps et en parfait \u00e9tat. Aucun probl\u00e8me \u00e0 signaler. Rien \u00e0 redire.\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial elementor-repeater-item-2f6edb0\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__header\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/06\/5ff7168c710000b6e38436df.jpg\" alt=\"SNMG2E\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">SNMG2E<\/span><\/cite>\t\t\t\t\t<div class=\"elementor-testimonial__icon elementor-icon elementor-icon-\" aria-label=\"Lire plus\"><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\tTout fonctionne parfaitement. Nous collaborons efficacement sur les diff\u00e9rents sujets, et l'organisation globale est excellente. Nous n'avons rencontr\u00e9 aucun probl\u00e8me majeur, car nous trouvons toujours des solutions adapt\u00e9es gr\u00e2ce \u00e0 des \u00e9changes r\u00e9guliers et rapides. C'est parfait !\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial elementor-repeater-item-b790a8c\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__header\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/10\/Frame-1000001582.jpg\" alt=\"Preezeo\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Preezeo<\/span><\/cite>\t\t\t\t\t<div class=\"elementor-testimonial__icon elementor-icon elementor-icon-\" aria-label=\"Lire plus\"><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\tF\u00e9licitations pour la qualit\u00e9 du travail sur votre portail partenaire, il nous simplifie vraiment la t\u00e2che !\nNous avons bien re\u00e7u le mode op\u00e9ratoire pour la cr\u00e9ation des devis, c'est un vrai plaisir.\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Pr\u00e9c\u00e9dent\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Suivant\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/main>\n\t\t\t\t<main class=\"elementor-section elementor-top-section elementor-element elementor-element-88e8f80 elementor-section-full_width elementor-section-content-middle elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"88e8f80\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-01f7947\" data-id=\"01f7947\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e6073ed elementor-widget elementor-widget-heading\" data-id=\"e6073ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Devenir apporteur d'affaires ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2335718 elementor-widget elementor-widget-text-editor\" data-id=\"2335718\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vous souhaitez proposer \u00e0 votre client une solution de supervision adapt\u00e9e, mais vous n&rsquo;avez pas l&rsquo;expertise n\u00e9cessaire ?<\/p><p><strong>Time2plug<\/strong> <strong>vous propose de<\/strong> <strong>prendre en charge la gestion des bornes de recharge de votre client et de mettre en place les services qui r\u00e9pondent le mieux \u00e0 ses besoins sp\u00e9cifiques.<\/strong><\/p><p>Si l&rsquo;offre aboutit \u00e0 une signature, vous <strong>recevrez une commission de 20 % du montant total du contrat pour la premi\u00e8re ann\u00e9e !<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-974b0ca elementor-align-center elementor-widget elementor-widget-button\" data-id=\"974b0ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.time2plug.com\/form-supervision\/collaborator\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Remplir le formulaire <\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/main>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Devenir un installateur partenaire Devenir un installateur partenaire Pourquoi choisir Time2plug comme partenaire ? Des projets cl\u00e9 en main Recevez des projets pr\u00eats \u00e0 \u00eatre install\u00e9s, sans les complications administratives. Ainsi concentrez-vous uniquement sur l&rsquo;installation et la qualit\u00e9. D\u00e9velopper votre entreprise Acc\u00e9dez \u00e0 de nouvelles opportunit\u00e9s de croissance et augmentez vos revenus gr\u00e2ce \u00e0 un [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"ocean_front_end_style_editor":"no","ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"on","ocean_disable_heading":"default","ocean_post_title":"Bornes de recharge pour entreprises","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","footnotes":""},"class_list":["post-12685","page","type-page","status-publish","hentry","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Devenir un installateur partenaire<\/title>\n<meta name=\"description\" content=\"Rejoignez le r\u00e9seau de partenaires Time2plug et acc\u00e9dez \u00e0 des opportunit\u00e9s exclusives pour devenir un installateur de bornes partenaire.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.time2plug.com\/page\/devenir-un-installateur-partenaire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Devenir un installateur partenaire\" \/>\n<meta property=\"og:description\" content=\"Rejoignez le r\u00e9seau de partenaires Time2plug et acc\u00e9dez \u00e0 des opportunit\u00e9s exclusives pour devenir un installateur de bornes partenaire.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.time2plug.com\/page\/devenir-un-installateur-partenaire\/\" \/>\n<meta property=\"og:site_name\" content=\"Time2plug\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-27T13:36:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/04\/Frame-1274.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1384\" \/>\n\t<meta property=\"og:image:height\" content=\"1239\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/devenir-un-installateur-partenaire\\\/\",\"url\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/devenir-un-installateur-partenaire\\\/\",\"name\":\"Devenir un installateur partenaire\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/devenir-un-installateur-partenaire\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/devenir-un-installateur-partenaire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Frame-1274.png\",\"datePublished\":\"2024-06-24T13:28:17+00:00\",\"dateModified\":\"2025-02-27T13:36:57+00:00\",\"description\":\"Rejoignez le r\u00e9seau de partenaires Time2plug et acc\u00e9dez \u00e0 des opportunit\u00e9s exclusives pour devenir un installateur de bornes partenaire.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/devenir-un-installateur-partenaire\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.time2plug.com\\\/page\\\/devenir-un-installateur-partenaire\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/devenir-un-installateur-partenaire\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Frame-1274.png\",\"contentUrl\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Frame-1274.png\",\"width\":1384,\"height\":1239,\"caption\":\"Analyse, Installation et Gestion de borne de recharge\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/devenir-un-installateur-partenaire\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Devenir un installateur partenaire\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/#website\",\"url\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/\",\"name\":\"Time2plug\",\"description\":\"Installation et gestion de bornes recharge pour voitures \u00e9lectriques\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/#organization\"},\"alternateName\":\"Bornes de recharge pour voitures \u00e9lectriques\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/#organization\",\"name\":\"Time2plug\",\"alternateName\":\"Bornes de recharge pour voitures \u00e9lectriques\",\"url\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/T2P-Blanc_Background-Orange.png\",\"contentUrl\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/T2P-Blanc_Background-Orange.png\",\"width\":300,\"height\":300,\"caption\":\"Time2plug\"},\"image\":{\"@id\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/time2plug\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Devenir un installateur partenaire","description":"Rejoignez le r\u00e9seau de partenaires Time2plug et acc\u00e9dez \u00e0 des opportunit\u00e9s exclusives pour devenir un installateur de bornes partenaire.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.time2plug.com\/page\/devenir-un-installateur-partenaire\/","og_locale":"fr_FR","og_type":"article","og_title":"Devenir un installateur partenaire","og_description":"Rejoignez le r\u00e9seau de partenaires Time2plug et acc\u00e9dez \u00e0 des opportunit\u00e9s exclusives pour devenir un installateur de bornes partenaire.","og_url":"https:\/\/www.time2plug.com\/page\/devenir-un-installateur-partenaire\/","og_site_name":"Time2plug","article_modified_time":"2025-02-27T13:36:57+00:00","og_image":[{"width":1384,"height":1239,"url":"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/04\/Frame-1274.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.time2plug.com\/page\/devenir-un-installateur-partenaire\/","url":"https:\/\/www.time2plug.com\/page\/devenir-un-installateur-partenaire\/","name":"Devenir un installateur partenaire","isPartOf":{"@id":"https:\/\/www.time2plug.com\/page\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.time2plug.com\/page\/devenir-un-installateur-partenaire\/#primaryimage"},"image":{"@id":"https:\/\/www.time2plug.com\/page\/devenir-un-installateur-partenaire\/#primaryimage"},"thumbnailUrl":"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/04\/Frame-1274.png","datePublished":"2024-06-24T13:28:17+00:00","dateModified":"2025-02-27T13:36:57+00:00","description":"Rejoignez le r\u00e9seau de partenaires Time2plug et acc\u00e9dez \u00e0 des opportunit\u00e9s exclusives pour devenir un installateur de bornes partenaire.","breadcrumb":{"@id":"https:\/\/www.time2plug.com\/page\/devenir-un-installateur-partenaire\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.time2plug.com\/page\/devenir-un-installateur-partenaire\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.time2plug.com\/page\/devenir-un-installateur-partenaire\/#primaryimage","url":"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/04\/Frame-1274.png","contentUrl":"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/04\/Frame-1274.png","width":1384,"height":1239,"caption":"Analyse, Installation et Gestion de borne de recharge"},{"@type":"BreadcrumbList","@id":"https:\/\/www.time2plug.com\/page\/devenir-un-installateur-partenaire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.time2plug.com\/page\/"},{"@type":"ListItem","position":2,"name":"Devenir un installateur partenaire"}]},{"@type":"WebSite","@id":"https:\/\/www.time2plug.com\/page\/#website","url":"https:\/\/www.time2plug.com\/page\/","name":"Time2plug","description":"Installation et gestion de bornes recharge pour voitures \u00e9lectriques","publisher":{"@id":"https:\/\/www.time2plug.com\/page\/#organization"},"alternateName":"Bornes de recharge pour voitures \u00e9lectriques","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.time2plug.com\/page\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.time2plug.com\/page\/#organization","name":"Time2plug","alternateName":"Bornes de recharge pour voitures \u00e9lectriques","url":"https:\/\/www.time2plug.com\/page\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.time2plug.com\/page\/#\/schema\/logo\/image\/","url":"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/04\/T2P-Blanc_Background-Orange.png","contentUrl":"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/04\/T2P-Blanc_Background-Orange.png","width":300,"height":300,"caption":"Time2plug"},"image":{"@id":"https:\/\/www.time2plug.com\/page\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/time2plug\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.time2plug.com\/page\/wp-json\/wp\/v2\/pages\/12685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.time2plug.com\/page\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.time2plug.com\/page\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.time2plug.com\/page\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.time2plug.com\/page\/wp-json\/wp\/v2\/comments?post=12685"}],"version-history":[{"count":0,"href":"https:\/\/www.time2plug.com\/page\/wp-json\/wp\/v2\/pages\/12685\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.time2plug.com\/page\/wp-json\/wp\/v2\/media?parent=12685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}