{"id":463,"date":"2022-09-27T16:07:30","date_gmt":"2022-09-27T14:07:30","guid":{"rendered":"https:\/\/uat.time2plug.fr\/?page_id=463"},"modified":"2025-05-05T10:09:45","modified_gmt":"2025-05-05T08:09:45","slug":"borne-de-recharge-pour-hotels","status":"publish","type":"page","link":"https:\/\/www.time2plug.com\/page\/borne-de-recharge-pour-hotels\/","title":{"rendered":"H\u00f4tels"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"463\" class=\"elementor elementor-463\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<header class=\"elementor-section elementor-top-section elementor-element elementor-element-dc3c61c elementor-section-height-min-height elementor-hidden-mobile elementor-section-full_width elementor-section-stretched elementor-section-items-bottom elementor-section-height-default\" data-id=\"dc3c61c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_start&quot;:0,&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;shape_divider_bottom&quot;:&quot;mountains&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" opacity=\"0.33\" d=\"M473,67.3c-203.9,88.3-263.1-34-320.3,0C66,119.1,0,59.7,0,59.7V0h1000v59.7 c0,0-62.1,26.1-94.9,29.3c-32.8,3.3-62.8-12.3-75.8-22.1C806,49.6,745.3,8.7,694.9,4.7S492.4,59,473,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" opacity=\"0.66\" d=\"M734,67.3c-45.5,0-77.2-23.2-129.1-39.1c-28.6-8.7-150.3-10.1-254,39.1 s-91.7-34.4-149.2,0C115.7,118.3,0,39.8,0,39.8V0h1000v36.5c0,0-28.2-18.5-92.1-18.5C810.2,18.1,775.7,67.3,734,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M766.1,28.9c-200-57.5-266,65.5-395.1,19.5C242,1.8,242,5.4,184.8,20.6C128,35.8,132.3,44.9,89.9,52.5C28.6,63.7,0,0,0,0 h1000c0,0-9.9,40.9-83.6,48.1S829.6,47,766.1,28.9z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8534541\" data-id=\"8534541\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1227b29 elementor-widget elementor-widget-heading\" data-id=\"1227b29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Bornes de recharge pour h\u00f4tels<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-19bfcf1 elementor-hidden-tablet elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default\" data-id=\"19bfcf1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-08cc580\" data-id=\"08cc580\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f01fef elementor-align-left elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"6f01fef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"\/solutions-recharge\/parking?type=public\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ma solution personnalis\u00e9e<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/header>\n\t\t\t\t<header class=\"elementor-section elementor-top-section elementor-element elementor-element-73aaba2 elementor-section-height-full elementor-section-full_width elementor-section-stretched elementor-section-items-bottom elementor-hidden-desktop elementor-hidden-tablet elementor-section-height-default\" data-id=\"73aaba2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_start&quot;:0,&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;shape_divider_bottom&quot;:&quot;mountains&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" opacity=\"0.33\" d=\"M473,67.3c-203.9,88.3-263.1-34-320.3,0C66,119.1,0,59.7,0,59.7V0h1000v59.7 c0,0-62.1,26.1-94.9,29.3c-32.8,3.3-62.8-12.3-75.8-22.1C806,49.6,745.3,8.7,694.9,4.7S492.4,59,473,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" opacity=\"0.66\" d=\"M734,67.3c-45.5,0-77.2-23.2-129.1-39.1c-28.6-8.7-150.3-10.1-254,39.1 s-91.7-34.4-149.2,0C115.7,118.3,0,39.8,0,39.8V0h1000v36.5c0,0-28.2-18.5-92.1-18.5C810.2,18.1,775.7,67.3,734,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M766.1,28.9c-200-57.5-266,65.5-395.1,19.5C242,1.8,242,5.4,184.8,20.6C128,35.8,132.3,44.9,89.9,52.5C28.6,63.7,0,0,0,0 h1000c0,0-9.9,40.9-83.6,48.1S829.6,47,766.1,28.9z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-18756ec\" data-id=\"18756ec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a4c4c2 elementor-widget elementor-widget-heading\" data-id=\"7a4c4c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Bornes de recharge pour h\u00f4tels<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5afd067 elementor-hidden-tablet elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default\" data-id=\"5afd067\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-8214854\" data-id=\"8214854\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f1fad2 elementor-align-left elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"4f1fad2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/solutions-recharge\/parking?type=public\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ma solution personnalis\u00e9e<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/header>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a5fc46b elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"a5fc46b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c0f3c3a\" data-id=\"c0f3c3a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a19ca38 elementor-widget elementor-widget-breadcrumbs\" data-id=\"a19ca38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<nav id=\"breadcrumbs\"><span><span><a href=\"https:\/\/www.time2plug.com\/page\/\">Accueil<\/a><\/span><\/span><\/nav>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9f0d72f elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"9f0d72f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-db328f0\" data-id=\"db328f0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c59eab elementor-widget elementor-widget-heading\" data-id=\"1c59eab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"color:#061360\">L'offre Time2plug <\/span>pour les h\u00f4tels<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d80d4e3 elementor-widget elementor-widget-text-editor\" data-id=\"d80d4e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sur mesure, simple, rapide, et cl\u00e9 en main.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<main class=\"elementor-section elementor-top-section elementor-element elementor-element-c1a2fd2 elementor-section-content-middle elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"c1a2fd2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<article class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5a65c02\" data-id=\"5a65c02\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;animation&quot;:&quot;none&quot;,&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b2e2b65 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"b2e2b65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"800\" height=\"800\" viewBox=\"0 0 800 800\" fill=\"none\"><g clip-path=\"url(#clip0_1427_3523)\"><path d=\"M801 288C801 459.333 801 630.167 801 801C534.333 801 267.667 801 1 801C1 534.333 1 267.667 1 1C267.667 1 534.333 1 801 1C801 96.5 801 192 801 288ZM298.06 737.529C218.054 712.694 154.063 665.781 107.435 596.34C60.2398 526.055 41.4293 448.165 49.8096 363.827C54.0151 321.503 65.8802 281.376 84.8621 243.37C102.796 207.462 126.312 175.627 155.204 147.73C191.913 112.287 234.228 85.9607 282.334 68.9341C328.781 52.4946 376.577 46.2209 425.694 49.8151C459.753 52.3074 492.727 59.6281 524.653 71.7806C549.468 81.2262 572.912 93.2797 594.947 108.08C597.888 110.056 600.857 110.966 603.138 107.434C605.342 104.021 603.666 101.509 600.578 99.5881C595.353 96.3375 590.253 92.874 584.934 89.7862C491.788 35.7117 393.173 23.9118 290.625 55.6763C202.166 83.0765 134.459 138.375 87.1249 218.125C59.6963 264.338 43.9536 314.455 39.2033 367.925C34.9274 416.055 39.6893 463.336 54.4539 509.442C79.4628 587.538 125.53 650.421 192.635 697.378C257.371 742.677 329.629 763.983 408.717 762.207C462.648 760.996 513.741 748.392 561.821 724.15C619.359 695.139 666.223 653.794 701.61 599.849C750.484 525.344 769.065 443.519 758.575 355.262C751.156 292.848 727.975 236.42 690.87 185.716C687.434 181.021 683.721 176.526 680.067 171.996C677.939 169.359 674.801 168.706 672.755 171.126C671.509 172.6 672.11 175.783 672.229 178.181C672.269 178.994 673.367 179.759 673.992 180.539C702.629 216.263 723.682 255.999 736.697 299.902C753.53 356.679 756.127 414.169 743.972 472.129C728.17 547.476 691.602 611.127 634.204 662.417C567.228 722.266 488.361 751.807 398.683 752.387C364.716 752.606 331.416 747.395 298.06 737.529ZM336.5 557.995C300.005 557.995 263.511 558.028 227.017 557.98C211.323 557.959 201.875 544.199 207.375 529.001C212.224 529.001 217.206 529.002 222.189 529.001C232.706 528.997 237.003 524.697 237.003 514.146C237.005 447.489 237.006 380.832 236.987 314.175C236.987 312.186 237.011 310.142 236.588 308.219C235.486 303.201 231.749 300.161 226.727 299.875C221.268 299.565 217.917 301.67 216.237 307.079C215.417 309.719 215.05 312.604 215.045 315.38C214.929 377.369 214.892 439.358 214.84 501.347C214.838 503.116 214.84 504.884 214.84 506.999C208.056 506.999 201.913 506.943 195.772 507.013C188.418 507.097 184.177 511.118 184.015 518.327C183.869 524.82 183.766 531.328 184.04 537.813C184.372 545.693 186.113 553.273 190.286 560.126C199.39 575.077 213.287 580.215 230.085 580.202C340.069 580.116 450.053 580.164 560.037 580.15C564.367 580.15 568.704 580.084 573.026 579.847C599.282 578.404 614.86 562.224 615.337 535.896C615.43 530.741 615.101 525.575 615.289 520.426C615.621 511.297 611.79 507.059 602.752 507.012C596.658 506.98 590.563 507.006 584.162 507.006C584.162 504.487 584.162 502.677 584.162 500.867C584.162 439.209 584.164 377.552 584.155 315.894C584.155 313.729 584.21 311.547 583.965 309.404C583.312 303.666 578.825 299.801 573.074 299.849C566.062 299.908 562.156 304.742 562.154 313.621C562.143 380.728 562.158 447.835 562.174 514.941C562.177 524.978 566 528.87 576.012 528.993C581.624 529.062 587.236 529.005 592.774 529.005C594.8 549.218 586.875 558.138 567.448 558.12C557.789 558.112 548.13 557.999 538.471 557.998C471.48 557.987 404.49 557.994 336.5 557.995ZM372.5 220.998C369 220.998 365.501 220.998 362.001 220.998C340.003 220.997 318.005 221.023 296.007 220.987C276.397 220.954 258.283 234.488 259.746 257.724C260.215 265.18 259.503 272.705 259.519 280.197C259.591 313.855 259.722 347.512 259.85 381.169C259.915 398.267 271.129 411.316 288.043 413.98C291.941 414.594 295.86 415.076 300.138 415.67C300.138 426.306 300.136 436.623 300.138 446.94C300.139 456.317 303.298 462.08 309.741 464.467C316.308 466.901 322.753 464.714 328.685 457.883C339.047 445.949 349.525 434.108 359.6 421.936C363.741 416.932 368.117 414.631 374.889 414.68C417.853 414.995 460.82 414.897 503.786 414.787C517.238 414.752 528.591 410.183 535.739 398.011C539.654 391.346 540.561 383.923 540.538 376.346C540.418 337.355 540.255 298.365 540.172 259.374C540.119 234.438 526.823 221.007 501.988 221.001C459.159 220.991 416.329 220.998 372.5 220.998ZM255.447 508.625C249.853 512.792 248.505 517.888 251.632 523.264C254.689 528.519 259.895 528.965 265.124 528.977C292.285 529.035 319.447 529.048 346.609 528.953C350.242 528.94 352.944 529.824 355.072 532.99C359.104 538.989 364.942 541.469 372.17 541.418C390.666 541.287 409.163 541.336 427.66 541.394C434.459 541.415 440.032 539.059 443.937 533.399C446.237 530.065 449.147 528.893 453.243 528.917C480.737 529.078 508.233 529.04 535.728 528.976C544.352 528.956 549.302 524.673 549.252 517.641C549.204 510.883 544.331 507.001 535.853 507.001C503.859 506.999 471.865 507.002 439.87 507.013C432.277 507.016 429.503 509.16 426.957 516.227C426.511 517.463 424.669 519.017 423.456 519.031C407.636 519.21 391.811 519.203 375.991 519.009C374.678 518.993 372.718 517.564 372.193 516.315C368.921 508.527 366.515 506.818 357.884 506.835C326.391 506.898 294.898 506.92 263.405 507.049C260.969 507.058 258.535 507.777 255.447 508.625Z\" fill=\"#FEFFFF\"><\/path><path d=\"M298.438 737.671C331.415 747.395 364.716 752.606 398.683 752.387C488.361 751.807 567.228 722.266 634.204 662.417C691.602 611.127 728.17 547.475 743.972 472.129C756.127 414.169 753.529 356.679 736.697 299.902C723.682 255.999 702.629 216.263 673.992 180.539C673.367 179.759 672.269 178.994 672.229 178.181C672.11 175.783 671.508 172.6 672.754 171.126C674.801 168.706 677.939 169.359 680.066 171.996C683.721 176.526 687.434 181.021 690.87 185.716C727.975 236.42 751.156 292.848 758.575 355.262C769.065 443.519 750.484 525.344 701.61 599.849C666.222 653.794 619.359 695.139 561.821 724.15C513.741 748.392 462.648 760.995 408.717 762.207C329.628 763.983 257.371 742.676 192.635 697.378C125.53 650.421 79.4627 587.538 54.4538 509.442C39.6892 463.336 34.9273 416.055 39.2032 367.925C43.9535 314.455 59.6962 264.338 87.1248 218.125C134.459 138.375 202.166 83.0764 290.625 55.6763C393.173 23.9117 491.788 35.7116 584.934 89.7862C590.253 92.8739 595.353 96.3374 600.578 99.588C603.666 101.509 605.342 104.021 603.137 107.434C600.857 110.966 597.888 110.056 594.947 108.08C572.911 93.2796 549.468 81.2261 524.653 71.7805C492.727 59.628 459.753 52.3073 425.694 49.815C376.577 46.2208 328.781 52.4945 282.333 68.934C234.227 85.9606 191.913 112.287 155.204 147.73C126.312 175.627 102.796 207.462 84.862 243.37C65.8801 281.376 54.015 321.503 49.8095 363.827C41.4292 448.165 60.2397 526.055 107.435 596.34C154.063 665.78 218.054 712.694 298.438 737.671Z\" fill=\"#18A9AB\"><\/path><path d=\"M337 557.995C404.49 557.994 471.48 557.988 538.471 557.998C548.13 557.999 557.789 558.112 567.448 558.121C586.875 558.138 594.8 549.218 592.774 529.005C587.236 529.005 581.624 529.062 576.012 528.993C566 528.87 562.177 524.978 562.174 514.941C562.158 447.835 562.143 380.728 562.154 313.622C562.156 304.742 566.062 299.908 573.074 299.849C578.825 299.801 583.312 303.666 583.965 309.404C584.21 311.547 584.155 313.729 584.155 315.894C584.164 377.552 584.162 439.209 584.162 500.867C584.162 502.677 584.162 504.487 584.162 507.006C590.563 507.006 596.658 506.98 602.752 507.012C611.79 507.059 615.621 511.297 615.289 520.426C615.101 525.575 615.43 530.741 615.337 535.896C614.86 562.224 599.282 578.404 573.026 579.847C568.704 580.085 564.367 580.15 560.037 580.15C450.053 580.164 340.069 580.116 230.085 580.202C213.287 580.215 199.39 575.077 190.286 560.126C186.113 553.273 184.372 545.693 184.04 537.814C183.766 531.329 183.869 524.82 184.015 518.327C184.177 511.118 188.418 507.097 195.772 507.013C201.913 506.943 208.056 506.999 214.84 506.999C214.84 504.884 214.838 503.116 214.84 501.347C214.892 439.358 214.929 377.369 215.045 315.38C215.05 312.604 215.417 309.72 216.237 307.079C217.917 301.67 221.268 299.565 226.727 299.875C231.749 300.161 235.486 303.201 236.588 308.219C237.011 310.142 236.987 312.186 236.987 314.175C237.006 380.832 237.005 447.489 237.003 514.146C237.003 524.697 232.706 528.997 222.189 529.001C217.206 529.002 212.224 529.001 207.375 529.001C201.875 544.199 211.323 557.959 227.017 557.98C263.511 558.028 300.006 557.995 337 557.995Z\" fill=\"#15A8AA\"><\/path><path d=\"M373 220.998C416.329 220.998 459.159 220.99 501.988 221.001C526.823 221.007 540.119 234.438 540.172 259.374C540.255 298.365 540.418 337.355 540.538 376.346C540.561 383.923 539.654 391.346 535.739 398.011C528.591 410.183 517.238 414.752 503.786 414.787C460.82 414.897 417.853 414.995 374.889 414.68C368.117 414.631 363.741 416.932 359.6 421.935C349.525 434.108 339.047 445.949 328.685 457.883C322.753 464.714 316.308 466.901 309.741 464.467C303.298 462.08 300.139 456.317 300.138 446.94C300.136 436.623 300.138 426.306 300.138 415.67C295.86 415.076 291.941 414.594 288.043 413.98C271.129 411.316 259.915 398.266 259.85 381.169C259.722 347.512 259.591 313.855 259.519 280.197C259.503 272.704 260.215 265.18 259.746 257.724C258.283 234.488 276.397 220.954 296.007 220.987C318.005 221.023 340.003 220.997 362.001 220.998C365.501 220.998 369 220.998 373 220.998ZM481.5 392.841C489.164 392.84 496.832 392.991 504.491 392.797C513.423 392.57 517.159 389.042 518.141 380.319C518.419 377.847 518.63 375.351 518.632 372.866C518.663 336.713 518.654 300.559 518.65 264.406C518.65 262.241 518.756 260.062 518.557 257.914C517.496 246.446 513.846 243.161 502.291 243.161C433.816 243.16 365.342 243.163 296.867 243.165C285.886 243.165 281.858 247.181 281.844 258.254C281.82 276.403 281.836 294.551 281.832 312.699C281.828 334.843 281.783 356.986 281.835 379.13C281.857 388.406 286.508 392.854 295.778 392.762C299.609 392.724 303.443 392.573 307.269 392.686C318.916 393.031 321.983 396.147 322.119 407.787C322.205 415.182 322.135 422.579 322.135 430.938C323.617 429.543 324.366 428.953 324.978 428.245C332.706 419.314 340.682 410.58 348.035 401.349C353.202 394.862 359.436 392.498 367.548 392.556C405.197 392.83 442.849 392.777 481.5 392.841Z\" fill=\"#15A9AB\"><\/path><path d=\"M255.773 508.396C258.535 507.777 260.968 507.058 263.405 507.049C294.898 506.92 326.391 506.898 357.884 506.835C366.515 506.818 368.92 508.527 372.193 516.315C372.718 517.564 374.678 518.993 375.991 519.009C391.811 519.203 407.635 519.21 423.456 519.031C424.669 519.017 426.511 517.463 426.957 516.227C429.503 509.16 432.277 507.016 439.87 507.013C471.865 507.002 503.859 506.999 535.853 507.001C544.331 507.001 549.204 510.883 549.252 517.641C549.302 524.673 544.352 528.956 535.728 528.976C508.233 529.04 480.737 529.078 453.243 528.917C449.147 528.893 446.237 530.065 443.937 533.399C440.032 539.059 434.459 541.415 427.66 541.394C409.163 541.336 390.666 541.287 372.17 541.418C364.942 541.469 359.103 538.989 355.072 532.99C352.944 529.824 350.242 528.94 346.609 528.953C319.447 529.048 292.285 529.035 265.124 528.977C259.895 528.965 254.689 528.519 251.632 523.264C248.505 517.888 249.853 512.792 255.773 508.396Z\" fill=\"#15A8AA\"><\/path><path d=\"M481 392.841C442.849 392.777 405.197 392.83 367.548 392.557C359.436 392.498 353.202 394.862 348.035 401.349C340.682 410.58 332.705 419.314 324.978 428.245C324.366 428.953 323.617 429.543 322.135 430.938C322.135 422.579 322.205 415.182 322.119 407.787C321.983 396.147 318.916 393.031 307.269 392.686C303.443 392.573 299.609 392.724 295.778 392.762C286.508 392.854 281.857 388.406 281.835 379.13C281.783 356.986 281.828 334.843 281.832 312.699C281.836 294.551 281.82 276.403 281.844 258.254C281.858 247.181 285.885 243.165 296.867 243.165C365.341 243.163 433.816 243.16 502.291 243.161C513.846 243.161 517.496 246.446 518.557 257.914C518.756 260.063 518.65 262.241 518.65 264.406C518.654 300.56 518.663 336.713 518.632 372.866C518.63 375.351 518.419 377.847 518.141 380.319C517.159 389.042 513.423 392.57 504.491 392.797C496.832 392.992 489.164 392.84 481 392.841ZM408.5 307.004C385.194 307.004 361.889 307.002 338.583 307.005C330.76 307.006 322.931 306.862 315.113 307.068C306.465 307.295 301.43 315.108 305.13 322.698C307.472 327.5 311.863 329.044 317.136 329.038C372.07 328.971 427.004 328.998 481.939 328.989C483.435 328.989 484.961 329.041 486.421 328.78C490.637 328.025 493.764 325.838 495.103 321.573C497.732 313.202 492.638 307.028 482.912 307.01C458.441 306.962 433.971 307 408.5 307.004ZM377.5 263C356.676 263.047 335.852 263.019 315.029 263.183C308.549 263.233 304.225 267.588 304.002 273.638C303.782 279.623 307.954 284.265 314.275 284.923C316.423 285.146 318.6 285.159 320.764 285.159C373.908 285.165 427.053 285.159 480.197 285.136C482.359 285.135 484.563 285.186 486.673 284.806C493.288 283.613 496.993 277.499 495.191 271.033C493.636 265.452 489.688 263.011 481.957 263.007C447.471 262.99 412.986 263 377.5 263ZM312.364 372.718C313.353 372.811 314.342 372.985 315.331 372.985C346.447 373 377.563 372.999 408.679 372.995C409.51 372.995 410.352 373.025 411.17 372.908C418.039 371.926 422.357 367.458 422.163 361.575C421.979 356.005 417.644 351.083 412.168 351.068C379.718 350.977 347.267 351.001 314.817 351.129C309.085 351.152 304.981 355.006 304.085 360.336C303.257 365.263 306.336 370.13 312.364 372.718Z\" fill=\"#FDFEFD\"><\/path><path d=\"M409 307.004C433.971 307 458.441 306.962 482.912 307.01C492.638 307.029 497.732 313.202 495.103 321.574C493.764 325.838 490.637 328.025 486.421 328.78C484.961 329.042 483.435 328.989 481.939 328.989C427.004 328.998 372.07 328.971 317.136 329.038C311.863 329.044 307.472 327.501 305.13 322.698C301.43 315.109 306.466 307.295 315.113 307.068C322.932 306.862 330.76 307.006 338.584 307.005C361.889 307.002 385.195 307.004 409 307.004Z\" fill=\"#F1A628\"><\/path><path d=\"M378 263C412.986 263 447.471 262.99 481.957 263.007C489.688 263.011 493.636 265.453 495.191 271.033C496.993 277.499 493.288 283.613 486.673 284.806C484.563 285.187 482.359 285.136 480.197 285.137C427.053 285.159 373.908 285.165 320.764 285.159C318.6 285.159 316.423 285.147 314.275 284.923C307.954 284.265 303.782 279.623 304.002 273.638C304.226 267.588 308.549 263.234 315.029 263.183C335.852 263.02 356.676 263.047 378 263Z\" fill=\"#F1A627\"><\/path><path d=\"M312.004 372.502C306.336 370.13 303.257 365.263 304.085 360.336C304.981 355.006 309.085 351.152 314.817 351.129C347.267 351.001 379.718 350.977 412.168 351.068C417.644 351.084 421.979 356.005 422.163 361.575C422.357 367.458 418.039 371.926 411.17 372.908C410.352 373.025 409.51 372.995 408.679 372.995C377.563 372.999 346.447 373 315.331 372.985C314.342 372.985 313.353 372.811 312.004 372.502Z\" fill=\"#F1A628\"><\/path><\/g><defs><clipPath id=\"clip0_1427_3523\"><rect width=\"800\" height=\"800\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tEtude de  votre besoin :\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tRemplissez notre <a href=\"https:\/\/www.time2plug.com\/solutions-recharge\/parking?type=entreprise\">questionnaire en ligne<\/a> et b\u00e9n\u00e9ficier ainsi d'un suivi personnalis\u00e9 par un de nos conseillers Time2plug. <span style=\"font-family: &quot;Open Sans&quot;, sans-serif;font-size: 16px;font-style: normal;font-weight: 600\">Incluant une \u00e9tude approfondie de vos besoins et une proposition tarifaire sur mesure. Ainsi qu'un accompagnement continu pendant toute la dur\u00e9e du projet.<\/span>\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-303dbbb elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"303dbbb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:5}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"800\" height=\"800\" viewBox=\"0 0 800 800\" fill=\"none\"><g clip-path=\"url(#clip0_1427_3702)\"><path d=\"M801 288C801 459.333 801 630.167 801 801C534.333 801 267.667 801 1 801C1 534.333 1 267.667 1 1C267.667 1 534.333 1 801 1C801 96.5 801 192 801 288ZM359.728 232.175C356.352 226.728 349.559 226.043 344.701 230.853C332.399 243.031 320.153 255.265 307.949 267.542C302.731 272.79 303.894 279.835 310.625 282.798C314.627 284.561 318.951 285.588 323.124 286.967C327.035 288.261 328.995 291.068 328.881 295.106C328.704 301.36 327.783 307.647 328.249 313.84C328.458 316.635 330.744 320.831 332.986 321.536C336.02 322.491 341.074 321.932 343.255 319.885C356.232 307.701 368.852 295.111 381.128 282.217C386.935 276.117 384.859 269.74 376.996 266.955C372.882 265.497 368.669 264.305 364.605 262.726C363.185 262.174 362.076 260.823 360.962 258.932C360.972 251.866 361.043 244.798 360.947 237.733C360.925 236.094 360.333 234.463 359.728 232.175ZM541.871 375.623C541.862 362.447 541.852 349.271 542.143 335.425C545.199 329.674 550.878 330.667 555.99 330.984C555.969 406.291 555.949 481.598 555.09 556.983C553.183 557.321 551.269 557.97 549.368 557.935C544.919 557.852 541.557 559.053 540.994 564.038C540.268 570.471 541.592 572.223 548.97 573.977C579.483 573.985 609.996 574.006 640.509 573.961C642.027 573.959 643.544 573.377 645.845 573.012C650.737 573.427 651.462 569.603 651.828 566.358C652.265 562.485 647.95 558.343 643.837 558.033C641.22 557.835 638.584 557.893 635.981 556.93C635.987 450.242 635.997 343.553 635.96 236.865C635.96 235.539 635.358 234.214 634.988 232.21C633.392 230.81 631.795 229.41 629.797 227.195C607.78 227.115 585.762 227.025 563.744 226.998C563.097 226.998 562.449 227.658 561.075 228.016C558.039 228.833 556.771 230.89 556.133 234.334C556.087 260.846 556.042 287.357 555.081 313.976C536.363 312.976 526.698 321.103 525.024 335.971C525.07 370.63 525.115 405.289 524.854 440.623C522.194 447.017 518.258 448.842 510.488 447.39C510 441.943 509.811 436.496 508.979 431.149C506.345 414.214 491.135 400.65 474.379 401.097C469.861 401.218 467.821 399.484 465.79 395.581C459.179 382.876 452.359 370.248 444.897 358.031C440.657 351.09 435.681 344.153 425.704 344.805C422.803 344.995 419.84 344.252 416.907 343.915C402.711 342.281 388.541 340.345 374.311 339.101C364.267 338.223 354.14 338.28 343.618 337.164C329.41 337.16 315.203 337.155 300.142 337.029C292.689 337.387 285.212 337.486 277.788 338.163C265.965 339.241 254.154 340.532 242.382 342.062C234.387 343.101 225.776 343.094 219.465 348.989C215.774 352.438 212.865 356.911 210.278 361.318C204.002 372.012 197.561 382.677 192.338 393.89C190.062 398.776 187.43 400.897 182.583 400.981C166.548 401.258 154.985 410.919 149.984 425.493C146.999 434.192 147.922 442.923 148.865 451.827C150.563 467.861 151.615 483.962 153.025 500.028C153.527 505.746 154.54 511.426 154.87 517.15C155.325 525.041 156.325 533.079 155.35 540.835C153.632 554.501 158.737 571.747 176.907 574.014C191.251 573.956 205.595 573.897 220.753 573.969C228.464 572.626 235.204 570.387 239.393 562.545C242.786 556.192 242.895 549.749 244.02 543.011C300.994 543.03 357.968 543.049 414.989 543.986C414.993 546.141 414.998 548.296 415 550.451C415.01 563.422 423.748 572.692 437.971 573.977C451.629 573.931 465.287 573.885 479.761 573.97C491.927 572.524 499.521 566.647 501.998 553.091C501.945 544.08 501.892 535.069 501.97 525.158C502.647 516.461 503.198 507.751 504.036 499.069C504.838 490.753 505.612 482.41 506.991 474.179C508.673 464.139 508.963 464.542 519.231 463.905C530.898 463.181 539.081 455.568 541.865 442.676C541.912 435.253 542.038 427.829 541.962 420.408C541.937 417.922 541.399 415.442 541.017 412.03C541.046 400.032 541.075 388.034 541.871 375.623ZM150.497 649.003C144.703 642.872 138.319 637.191 133.236 630.518C121.814 615.521 110.037 600.641 100.275 584.577C90.063 567.773 81.0697 550.055 73.3294 531.972C65.3452 513.32 59.9853 493.654 55.7157 473.688C51.1643 452.404 48.9346 430.915 48.1157 409.283C47.3653 389.464 48.3373 369.621 52.0644 350.087C55.3617 332.806 58.3535 315.363 63.3273 298.537C67.9233 282.988 74.268 267.837 81.1368 253.115C87.9739 238.461 95.6441 224.063 104.328 210.432C121.212 183.93 141.097 159.752 165.252 139.439C177.389 129.231 189.761 119.238 202.621 109.972C220.654 96.9809 240.206 86.4718 260.692 77.8428C270.859 73.5607 281.159 69.4829 291.661 66.1374C308.883 60.6515 326.248 55.5957 344.371 53.772C358.572 52.3429 372.709 50.0481 386.939 49.1817C397.15 48.5599 407.514 49.1501 417.725 50.1092C434.367 51.6725 451.038 53.3799 467.519 56.1028C496.555 60.9002 524.214 70.5224 550.547 83.4636C565.935 91.0262 580.471 100.326 595.362 108.895C598.244 110.553 601.202 111.214 603.175 108.128C605.054 105.19 604.537 102.081 601.292 100.029C598.135 98.0336 594.867 96.2124 591.726 94.193C570.388 80.4747 547.652 69.5969 523.848 60.9419C502.433 53.1558 480.669 46.642 457.938 43.9105C444.255 42.2664 430.613 39.7985 416.885 39.1623C402.835 38.5112 388.666 39.1292 374.619 40.1448C361.209 41.1142 347.779 42.7163 334.557 45.13C320.339 47.7254 306.208 51.0751 292.296 55.0078C264.934 62.743 239.325 74.6633 214.81 89.0191C191.049 102.933 168.938 119.182 149.367 138.44C135.771 151.818 123.518 166.628 111.304 181.328C92.8158 203.579 79.1938 228.973 67.5763 255.222C54.9393 283.775 45.6035 313.571 42.0141 344.794C39.9306 362.918 38.088 381.106 37.2172 399.318C36.708 409.967 38.0002 420.752 39.0672 431.417C40.4205 444.945 41.5498 458.578 44.2224 471.875C50.547 503.342 60.8228 533.61 75.2197 562.326C80.8388 573.534 87.6128 584.171 94.016 594.976C105.672 614.644 120.045 632.275 135.555 648.954C142.775 656.72 150.607 663.967 158.592 670.958C167.6 678.844 176.789 686.592 186.433 693.673C214.988 714.639 246.003 731.255 279.555 742.557C296.367 748.221 313.904 751.757 331.158 756.076C350.722 760.974 370.788 762.211 390.796 762.791C404.971 763.201 419.227 762.021 433.4 760.94C444.663 760.081 455.982 758.938 467.046 756.756C480.599 754.084 494.213 751.079 507.255 746.62C524.484 740.73 541.714 734.352 557.967 726.228C575.673 717.378 592.691 706.937 609.195 695.964C621.553 687.747 633.052 678.073 644.13 668.15C653.755 659.528 662.853 650.147 671.103 640.205C682.911 625.977 694.476 611.431 704.789 596.109C717.371 577.413 727.36 557.167 735.443 536.064C738.997 526.785 743.184 517.664 745.764 508.114C750.909 489.064 756.529 470.072 758.096 450.224C759.247 435.637 761.633 421.08 761.743 406.496C761.865 390.366 760.484 374.174 758.886 358.095C757.612 345.277 755.803 332.408 752.86 319.883C747.045 295.138 738.808 271.122 728.034 248.047C715.357 220.895 699.173 195.899 680.651 172.426C679.263 170.668 674.682 169.578 672.766 170.536C670.075 171.882 669.646 175.554 671.92 178.504C673.323 180.324 674.846 182.052 676.236 183.883C697.861 212.367 715.545 242.983 728.361 276.515C741.641 311.26 748.557 347.227 750.826 384.13C751.606 396.831 750.849 409.697 749.876 422.417C748.789 436.634 747.171 450.855 744.878 464.927C739.863 495.707 729.786 524.978 716.37 553.043C707.209 572.207 695.773 590.021 683.453 607.392C669.076 627.664 651.74 645.055 634.068 662.229C629.589 666.582 624.905 670.845 619.8 674.411C604.785 684.901 589.671 695.267 574.296 705.219C556.639 716.648 537.541 725.452 517.568 731.745C497.585 738.041 477.107 742.806 456.746 747.84C449.968 749.515 442.909 750.269 435.929 750.859C427.439 751.577 418.901 751.889 410.379 751.992C397.321 752.15 384.234 752.457 371.207 751.784C362.138 751.314 353.065 749.719 344.143 747.896C328.238 744.644 312.246 741.541 296.651 737.108C270.714 729.737 246.221 718.763 222.979 704.993C196.705 689.427 172.645 671.043 150.497 649.003Z\" fill=\"white\"><\/path><path d=\"M555.934 330.059C550.878 330.667 545.199 329.674 541.74 336.079C541.26 349.835 541.182 362.936 541.104 376.037C541.075 388.034 541.046 400.032 541.003 412.963C541.017 423.62 541.047 433.344 541.076 443.068C539.081 455.568 530.898 463.181 519.231 463.905C508.963 464.542 508.673 464.139 506.991 474.179C505.612 482.41 504.838 490.753 504.036 499.069C503.198 507.751 502.647 516.461 501.654 525.932C501.512 535.813 501.686 544.92 501.859 554.027C499.521 566.647 491.927 572.524 479.029 573.654C465.958 573.226 453.62 573.086 441.282 573.041C439.872 573.036 438.459 573.56 437.048 573.839C423.748 572.692 415.01 563.422 415 550.451C414.998 548.296 414.993 546.141 414.687 543.222C413.41 542.307 412.436 542.024 411.461 542.024C356.211 542.002 300.96 541.998 245.71 542.047C244.838 542.048 243.967 542.715 243.096 543.071C242.895 549.749 242.786 556.192 239.393 562.545C235.204 570.387 228.464 572.626 220.023 573.654C205.429 573.235 191.567 573.122 177.704 573.065C177.128 573.062 176.549 573.582 175.972 573.858C158.737 571.747 153.632 554.501 155.35 540.835C156.325 533.079 155.325 525.041 154.87 517.15C154.54 511.426 153.527 505.745 153.025 500.028C151.615 483.962 150.563 467.861 148.865 451.827C147.922 442.923 146.999 434.192 149.984 425.493C154.985 410.919 166.548 401.258 182.583 400.981C187.43 400.897 190.062 398.776 192.338 393.89C197.561 382.677 204.002 372.012 210.278 361.318C212.865 356.911 215.774 352.438 219.465 348.989C225.776 343.093 234.387 343.101 242.382 342.062C254.154 340.532 265.965 339.241 277.788 338.163C285.212 337.486 292.689 337.387 300.866 337.388C315.744 337.805 329.897 337.862 344.05 337.92C354.14 338.28 364.267 338.223 374.311 339.101C388.541 340.345 402.711 342.281 416.907 343.915C419.84 344.252 422.803 344.995 425.704 344.805C435.681 344.153 440.657 351.09 444.897 358.031C452.359 370.248 459.179 382.876 465.79 395.581C467.821 399.484 469.861 401.218 474.379 401.097C491.135 400.649 506.345 414.214 508.979 431.149C509.811 436.496 510 441.943 510.488 447.39C518.258 448.842 522.194 447.017 525.259 439.961C525.774 438.484 525.983 437.668 525.983 436.853C525.999 404.175 526.006 371.497 525.962 338.818C525.96 337.561 525.44 336.305 525.162 335.049C526.698 321.103 536.363 312.976 555.91 313.724C556.8 286.961 556.859 260.451 556.919 233.94C556.771 230.89 558.039 228.833 561.918 228.067C585.24 228.081 607.719 228.046 630.198 228.01C631.795 229.41 633.392 230.81 634.966 233.023C634.964 236.001 635.001 238.166 635.001 240.331C635.004 344.105 634.998 447.878 635.044 551.652C635.044 553.713 635.639 555.775 635.956 557.837C638.584 557.893 641.22 557.835 643.837 558.033C647.95 558.343 652.265 562.485 651.828 566.358C651.462 569.603 650.737 573.427 644.982 573.017C613.688 573.015 583.256 572.996 552.824 573.038C551.232 573.04 549.64 573.56 548.047 573.838C541.592 572.223 540.268 570.471 540.994 564.038C541.557 559.053 544.919 557.852 549.368 557.935C551.269 557.97 553.183 557.321 555.797 557.004C556.668 556.083 556.977 555.141 556.977 554.198C556.999 481.038 557.004 407.878 556.953 334.719C556.952 333.165 556.288 331.612 555.934 330.059ZM383.951 522.719C383.624 522.519 383.297 522.32 382.3 521.796C378.787 520.864 375.322 519.592 371.749 519.096C368.207 518.603 364.556 518.892 360.302 518.337C359.489 518.227 358.675 518.019 357.862 518.019C337.843 518 317.824 517.988 297.805 518.039C296.551 518.042 295.299 518.56 293.115 518.97C285.885 519.367 277.995 517.039 271.678 524.265C269.235 529.396 273.998 526.856 274.944 526.861C310.071 527.023 345.2 527.009 380.328 526.96C381.922 526.958 383.515 526.409 385.362 525.977C385.362 525.977 385.648 526.019 386.194 525.925C386.03 525.612 385.866 525.299 385.22 524.787C384.805 524.248 384.391 523.709 383.951 522.719ZM437.882 557.625C450.307 557.754 462.732 557.915 475.158 557.971C476.746 557.979 478.336 557.442 480.588 556.85C487.497 552.544 485.726 545.73 485.956 539.716C480.462 540.54 475.247 541.321 469.097 541.986C461.035 542.01 452.973 542.033 444.062 542.011C440.103 542.503 436.145 542.995 431.863 543.527C432.778 548.641 429.499 554.961 437.882 557.625ZM221.394 556.926C226.333 553.472 226.654 548.653 225.689 543.671C207.867 539.343 189.516 547.057 172.006 538.963C172.006 542.982 171.679 546.344 172.095 549.612C172.54 553.098 172.943 557.087 178.645 557.696C190.734 557.8 202.822 557.942 214.911 557.969C216.838 557.973 218.767 557.459 221.394 556.926ZM425.243 415.878C422.245 415.921 419.247 416.002 416.249 416.002C354.771 416.006 293.293 416 231.057 416.016C229.67 414.673 227.13 413.364 227.089 411.982C226.874 404.662 226.556 397.212 227.662 390.021C229.154 380.318 231.909 370.809 234.122 361.217C231.725 362.158 229.414 363.577 228.244 365.642C219.69 380.739 211.241 395.9 203.048 411.195C200.805 415.384 197.991 417.218 193.265 417.087C189.027 416.969 184.611 416.969 180.551 418.005C169.499 420.826 164.044 429.896 165.031 441.052C165.869 450.535 166.991 459.993 167.955 469.466C169.336 483.031 170.6 496.609 172.086 510.162C172.888 517.477 177.015 525.421 187.772 526.654C205.903 526.749 224.034 526.852 242.165 526.908C242.76 526.909 243.357 526.421 244.662 526.013C251.217 520.064 257.569 513.867 264.42 508.281C267.422 505.833 271.441 504.631 275.93 502.969C311.64 502.952 347.351 502.934 383.806 502.991C386.937 504.893 390.415 506.398 393.121 508.782C397.959 513.042 402.229 517.94 406.949 522.344C408.671 523.95 410.997 524.907 413.698 526.662C432.192 526.755 450.686 526.855 469.18 526.907C469.77 526.908 470.362 526.421 471.71 526.028C478.882 524.204 483.468 519.764 484.967 512.476C485.59 509.446 485.719 506.314 486.059 503.227C487.371 491.335 488.625 479.436 490.006 467.552C490.875 460.075 492.161 452.642 492.846 445.152C493.793 434.782 492.627 426.336 482.397 419.971C477.115 416.684 471.119 416.677 465.189 417.04C459.632 417.381 456.307 415.314 453.81 410.034C447.968 397.684 441.719 385.494 434.949 373.631C432.212 368.833 430.029 362.828 424.399 361.288C426.69 375.697 428.987 390.237 431.323 404.771C432.174 410.07 430.149 414.602 425.243 415.878ZM572.838 355.5C572.838 422.853 572.838 490.206 572.838 557.607C588.869 557.607 603.951 557.607 619.237 557.607C619.237 452.817 619.237 348.342 619.237 243.752C603.63 243.752 588.418 243.752 572.838 243.752C572.838 280.92 572.838 317.71 572.838 355.5ZM356.391 354.228C324.801 352.633 293.275 353.943 261.775 356.36C254.84 356.892 253.045 358.447 250.98 365.212C249.867 368.859 248.472 372.439 247.622 376.144C245.835 383.939 244.323 391.796 242.652 399.853C300.537 399.853 357.283 399.853 414.488 399.853C414.08 396.898 413.962 394.238 413.317 391.713C411.1 383.025 408.692 374.385 406.368 365.724C403.954 356.732 403.605 356.591 394.165 356.159C381.889 355.597 369.625 354.798 356.391 354.228Z\" fill=\"#15A8AA\"><\/path><path d=\"M150.747 649.253C172.645 671.044 196.705 689.427 222.979 704.994C246.221 718.763 270.713 729.737 296.651 737.108C312.246 741.541 328.238 744.644 344.143 747.896C353.065 749.719 362.138 751.314 371.207 751.784C384.234 752.458 397.321 752.15 410.379 751.992C418.901 751.889 427.439 751.577 435.928 750.859C442.908 750.269 449.967 749.515 456.746 747.84C477.107 742.806 497.585 738.041 517.568 731.745C537.541 725.452 556.639 716.648 574.296 705.219C589.671 695.268 604.784 684.901 619.799 674.411C624.905 670.845 629.589 666.582 634.068 662.229C651.74 645.055 669.076 627.664 683.453 607.392C695.773 590.021 707.209 572.207 716.37 553.043C729.786 524.978 739.863 495.707 744.878 464.927C747.171 450.855 748.789 436.634 749.876 422.417C750.849 409.697 751.606 396.831 750.826 384.13C748.557 347.227 741.64 311.26 728.361 276.515C715.544 242.983 697.86 212.367 676.236 183.883C674.846 182.053 673.323 180.325 671.92 178.504C669.645 175.554 670.075 171.882 672.766 170.536C674.682 169.578 679.263 170.668 680.651 172.426C699.173 195.899 715.357 220.895 728.034 248.047C738.808 271.122 747.045 295.138 752.859 319.883C755.802 332.408 757.611 345.277 758.886 358.095C760.484 374.174 761.864 390.366 761.742 406.496C761.632 421.08 759.246 435.637 758.095 450.224C756.529 470.072 750.909 489.065 745.763 508.114C743.184 517.664 738.997 526.785 735.443 536.065C727.36 557.167 717.371 577.413 704.789 596.109C694.476 611.432 682.911 625.977 671.103 640.205C662.853 650.147 653.754 659.528 644.13 668.15C633.052 678.073 621.552 687.748 609.195 695.964C592.691 706.937 575.673 717.378 557.966 726.228C541.714 734.352 524.484 740.73 507.255 746.62C494.213 751.079 480.598 754.084 467.045 756.756C455.981 758.938 444.663 760.081 433.4 760.94C419.227 762.021 404.971 763.201 390.796 762.791C370.788 762.211 350.722 760.974 331.158 756.076C313.904 751.757 296.367 748.221 279.555 742.557C246.003 731.255 214.988 714.639 186.433 693.673C176.789 686.592 167.6 678.844 158.591 670.958C150.606 663.967 142.775 656.72 135.555 648.954C120.045 632.275 105.671 614.644 94.0158 594.976C87.6126 584.171 80.8386 573.534 75.2195 562.326C60.8226 533.61 50.5468 503.342 44.2222 471.875C41.5496 458.578 40.4203 444.945 39.067 431.417C38 420.752 36.7078 409.967 37.217 399.318C38.0878 381.107 39.9303 362.918 42.0139 344.794C45.6033 313.571 54.9391 283.775 67.576 255.222C79.1936 228.973 92.8156 203.579 111.303 181.329C123.518 166.628 135.771 151.819 149.367 138.44C168.938 119.182 191.049 102.934 214.81 89.0191C239.325 74.6634 264.933 62.7431 292.296 55.0078C306.207 51.0752 320.339 47.7255 334.557 45.13C347.779 42.7164 361.209 41.1143 374.619 40.1448C388.666 39.1293 402.835 38.5113 416.884 39.1624C430.612 39.7986 444.255 42.2664 457.937 43.9106C480.669 46.6421 502.432 53.1558 523.847 60.9419C547.652 69.5969 570.388 80.4748 591.726 94.193C594.867 96.2124 598.135 98.0337 601.292 100.029C604.537 102.081 605.053 105.19 603.175 108.128C601.202 111.214 598.243 110.553 595.362 108.895C580.471 100.326 565.935 91.0263 550.546 83.4637C524.214 70.5225 496.555 60.9003 467.518 56.1029C451.038 53.38 434.367 51.6725 417.725 50.1093C407.514 49.1502 397.15 48.5599 386.938 49.1818C372.709 50.0482 358.572 52.343 344.37 53.7721C326.248 55.5958 308.883 60.6516 291.661 66.1374C281.159 69.483 270.859 73.5607 260.692 77.8429C240.205 86.4719 220.653 96.981 202.621 109.972C189.761 119.238 177.388 129.231 165.251 139.439C141.097 159.752 121.212 183.93 104.328 210.432C95.6439 224.063 87.9737 238.461 81.1366 253.115C74.2678 267.837 67.9231 282.989 63.3271 298.537C58.3533 315.363 55.3615 332.806 52.0642 350.088C48.3371 369.621 47.3651 389.464 48.1155 409.284C48.9344 430.916 51.1641 452.404 55.7155 473.688C59.9851 493.654 65.345 513.32 73.3292 531.973C81.0695 550.055 90.0628 567.773 100.275 584.577C110.037 600.641 121.814 615.521 133.236 630.518C138.318 637.191 144.703 642.872 150.747 649.253Z\" fill=\"#17A9AB\"><\/path><path d=\"M360.825 259.837C362.076 260.823 363.185 262.174 364.605 262.726C368.669 264.305 372.882 265.497 376.996 266.955C384.859 269.739 386.935 276.117 381.128 282.217C368.851 295.111 356.232 307.701 343.255 319.884C341.074 321.932 336.019 322.491 332.985 321.536C330.744 320.83 328.458 316.635 328.248 313.84C327.783 307.647 328.704 301.36 328.881 295.106C328.995 291.068 327.035 288.261 323.123 286.967C318.951 285.588 314.627 284.561 310.625 282.798C303.894 279.834 302.731 272.79 307.949 267.542C320.152 255.265 332.399 243.031 344.7 230.853C349.559 226.043 356.351 226.728 359.82 232.981C359.949 237.257 359.909 240.73 360.041 244.198C360.239 249.413 360.558 254.624 360.825 259.837ZM334.544 273.01C343.733 275.849 346.689 282.35 344.706 292.358C349.694 286.973 353.911 282.422 357.752 278.275C354.352 276.641 349.138 275.637 346.574 272.48C343.997 269.307 344.059 263.991 343.145 260.339C339.472 263.831 335.406 267.696 331.08 271.809C332.134 272.268 332.97 272.633 334.544 273.01Z\" fill=\"#16A9AB\"><\/path><path d=\"M635.969 557.383C635.639 555.775 635.045 553.713 635.044 551.652C634.998 447.878 635.004 344.105 635.001 240.331C635.001 238.166 634.964 236.001 634.991 233.362C635.358 234.214 635.96 235.539 635.96 236.865C635.997 343.553 635.987 450.241 635.969 557.383Z\" fill=\"#91D7D9\"><\/path><path d=\"M555.962 330.521C556.288 331.612 556.952 333.165 556.953 334.719C557.004 407.878 556.999 481.038 556.977 554.198C556.977 555.141 556.668 556.083 556.216 556.966C555.949 481.598 555.969 406.291 555.962 330.521Z\" fill=\"#51BEC1\"><\/path><path d=\"M243.558 543.041C243.967 542.715 244.838 542.048 245.71 542.047C300.96 541.998 356.211 542.002 411.461 542.024C412.436 542.024 413.41 542.307 414.664 542.763C357.968 543.049 300.994 543.03 243.558 543.041Z\" fill=\"#51BEC1\"><\/path><path d=\"M525.093 335.51C525.44 336.305 525.96 337.562 525.962 338.819C526.006 371.497 525.999 404.175 525.983 436.853C525.983 437.668 525.774 438.484 525.412 439.623C525.115 405.289 525.07 370.63 525.093 335.51Z\" fill=\"#51BEC1\"><\/path><path d=\"M548.509 573.908C549.64 573.56 551.232 573.04 552.824 573.038C583.256 572.996 613.688 573.016 644.591 573.043C643.544 573.377 642.027 573.959 640.509 573.961C609.996 574.006 579.483 573.985 548.509 573.908Z\" fill=\"#51BEC1\"><\/path><path d=\"M556.525 234.137C556.859 260.451 556.799 286.961 556.369 313.67C556.042 287.357 556.087 260.846 556.525 234.137Z\" fill=\"#C1E9E9\"><\/path><path d=\"M629.998 227.602C607.72 228.046 585.241 228.082 562.282 228.064C562.449 227.658 563.097 226.997 563.745 226.998C585.762 227.025 607.78 227.115 629.998 227.602Z\" fill=\"#97D9DB\"><\/path><path d=\"M176.439 573.936C176.549 573.582 177.128 573.062 177.704 573.065C191.567 573.122 205.429 573.235 219.616 573.589C205.595 573.897 191.251 573.956 176.439 573.936Z\" fill=\"#52BFC2\"><\/path><path d=\"M343.834 337.542C329.897 337.862 315.744 337.805 301.293 337.449C315.203 337.155 329.41 337.159 343.834 337.542Z\" fill=\"#80D0D3\"><\/path><path d=\"M437.51 573.908C438.46 573.56 439.872 573.036 441.282 573.041C453.621 573.086 465.958 573.226 478.621 573.588C465.287 573.885 451.629 573.931 437.51 573.908Z\" fill=\"#51BEC1\"><\/path><path d=\"M541.488 375.83C541.182 362.936 541.259 349.835 541.59 336.415C541.852 349.271 541.862 362.447 541.488 375.83Z\" fill=\"#BFE8E8\"><\/path><path d=\"M541.471 442.872C541.047 433.344 541.017 423.62 541.042 413.427C541.399 415.441 541.937 417.922 541.962 420.407C542.038 427.829 541.912 435.253 541.471 442.872Z\" fill=\"#BCE7E7\"><\/path><path d=\"M501.929 553.559C501.685 544.92 501.512 535.813 501.588 526.382C501.892 535.069 501.945 544.08 501.929 553.559Z\" fill=\"#52BFC1\"><\/path><path d=\"M360.894 259.384C360.558 254.624 360.239 249.413 360.041 244.198C359.909 240.73 359.949 237.257 359.958 233.308C360.333 234.463 360.925 236.094 360.947 237.733C361.043 244.798 360.972 251.866 360.894 259.384Z\" fill=\"#97D9DB\"><\/path><path d=\"M274.998 502.863C271.441 504.631 267.422 505.833 264.42 508.281C257.57 513.867 251.217 520.064 243.846 526.018C224.393 526.075 205.758 526.127 187.122 526.179C177.016 525.421 172.888 517.477 172.086 510.162C170.6 496.609 169.336 483.031 167.955 469.466C166.991 459.993 165.869 450.535 165.031 441.052C164.044 429.896 169.5 420.826 180.551 418.005C184.611 416.969 189.027 416.969 193.265 417.087C197.991 417.218 200.805 415.384 203.049 411.195C211.241 395.9 219.69 380.739 228.245 365.642C229.414 363.577 231.725 362.158 234.122 361.217C231.909 370.809 229.154 380.318 227.662 390.021C226.556 397.212 226.874 404.662 227.089 411.982C227.13 413.364 229.67 414.673 231.642 416.409C232.716 416.877 233.205 417.019 233.694 417.019C296.713 417.026 359.733 417.028 422.753 416.977C423.903 416.976 425.053 416.333 426.203 415.989C430.149 414.602 432.174 410.07 431.323 404.771C428.987 390.237 426.691 375.697 424.399 361.288C430.029 362.828 432.212 368.833 434.95 373.63C441.719 385.494 447.968 397.684 453.81 410.034C456.307 415.314 459.632 417.381 465.189 417.04C471.119 416.677 477.115 416.684 482.397 419.971C492.627 426.336 493.793 434.782 492.846 445.152C492.161 452.642 490.875 460.075 490.006 467.552C488.625 479.436 487.371 491.335 486.059 503.227C485.719 506.314 485.59 509.446 484.967 512.476C483.468 519.764 478.883 524.204 470.87 526.026C451.036 526.069 432.042 526.115 413.048 526.161C410.998 524.907 408.671 523.95 406.95 522.344C402.23 517.94 397.959 513.042 393.121 508.782C390.416 506.398 386.937 504.892 383.237 502.561C347.465 502.088 312.262 502.04 277.059 502.037C276.372 502.037 275.685 502.576 274.998 502.863ZM369.795 487.041C374.757 486.756 376.474 483.034 376.368 479.194C376.258 475.19 374.03 471.792 368.588 471.202C341.675 471.114 314.762 471.019 287.849 470.983C287.183 470.982 286.516 471.631 285.207 472.289C281.226 474.037 280.445 477.628 281.247 481.127C282.081 484.765 284.491 487.576 289.38 487.87C315.091 487.913 340.803 487.965 366.514 487.961C367.354 487.961 368.194 487.402 369.795 487.041ZM187.025 438.973C187.064 456.99 187.103 475.007 187.054 493.793C187.351 494.883 187.684 495.965 187.939 497.065C190.637 508.687 203.951 519.465 215.722 518.924C219.836 518.736 225.079 519.103 226.89 513.833C228.669 508.657 225.196 503.7 219.294 503.073C207.766 501.848 203.024 495.421 203.96 485.665C204.212 483.042 203.999 480.374 203.999 477.377C205.19 477.827 206.153 478.047 206.97 478.521C222.282 487.399 239.247 487.873 256.195 487.904C265.213 487.92 269.291 481.213 264.697 474.504C262.294 470.994 259.409 467.698 256.264 464.83C239.659 449.691 219.774 440.34 198.853 432.94C192.091 430.548 190.031 431.58 187.025 438.973ZM469.977 437.148C467.835 432.529 463.974 430.678 458.903 432.654C451.624 435.491 444.553 438.855 437.379 441.963C420.713 449.182 405.766 458.875 393.823 472.728C389.538 477.698 391.838 485.501 397.849 486.849C401.025 487.562 404.367 488.083 407.595 487.919C419.991 487.288 432.389 486.449 444.05 481.528C447.266 480.171 450.501 478.857 454.001 477.41C454.001 480.366 453.935 482.861 454.013 485.351C454.273 493.616 450.738 501.065 440.116 502.066C438.371 502.231 436.328 502.581 435.061 503.623C433.372 505.011 431.474 507.031 431.167 509.011C430.673 512.207 429.944 516.605 434.484 517.628C438.142 518.452 442.147 518.345 445.921 517.939C458.859 516.55 469.263 505.667 470.847 492.669C470.906 475.068 470.976 457.466 470.983 439.864C470.983 439.208 470.37 438.552 469.977 437.148Z\" fill=\"white\"><\/path><path d=\"M572.837 355C572.837 317.71 572.837 280.92 572.837 243.752C588.418 243.752 603.63 243.752 619.236 243.752C619.236 348.342 619.236 452.817 619.236 557.607C603.951 557.607 588.868 557.607 572.837 557.607C572.837 490.206 572.837 422.853 572.837 355Z\" fill=\"#EEA629\"><\/path><path d=\"M356.873 354.165C369.625 354.798 381.889 355.597 394.165 356.159C403.604 356.591 403.954 356.732 406.367 365.724C408.692 374.385 411.099 383.025 413.317 391.713C413.962 394.238 414.08 396.898 414.488 399.854C357.283 399.854 300.537 399.854 242.652 399.854C244.323 391.796 245.835 383.939 247.622 376.144C248.472 372.439 249.866 368.859 250.98 365.212C253.045 358.447 254.839 356.892 261.775 356.36C293.275 353.943 324.801 352.633 356.873 354.165Z\" fill=\"#F0A628\"><\/path><path d=\"M178.011 557.15C172.943 557.087 172.54 553.098 172.095 549.612C171.679 546.344 172.006 542.982 172.006 538.963C189.516 547.057 207.867 539.343 225.689 543.671C226.654 548.653 226.333 553.472 220.603 557.004C205.878 557.105 191.944 557.127 178.011 557.15Z\" fill=\"white\"><\/path><path d=\"M470.032 542.103C475.247 541.321 480.462 540.54 485.956 539.716C485.725 545.73 487.497 552.544 479.793 556.958C465.076 557.103 451.154 557.14 437.231 557.177C429.498 554.961 432.778 548.641 431.863 543.527C436.145 542.995 440.103 542.503 444.678 542.434C449.738 542.891 454.186 543.048 458.626 542.924C462.433 542.817 466.23 542.389 470.032 542.103Z\" fill=\"white\"><\/path><path d=\"M385.648 526.02C385.648 526.02 385.362 525.978 384.755 525.998C360.886 526.012 337.625 526.005 314.365 526C301.571 525.998 288.777 526.054 275.985 525.912C274.766 525.898 273.56 524.659 272.348 523.988C277.996 517.039 285.885 519.367 294.043 518.974C316.964 518.931 338.958 518.885 360.952 518.838C364.556 518.892 368.207 518.604 371.749 519.096C375.322 519.592 378.787 520.864 382.722 522.197C383.422 522.788 383.699 522.979 383.976 523.17C384.391 523.709 384.805 524.248 385.525 525.149C385.77 525.681 385.709 525.85 385.648 526.02Z\" fill=\"white\"><\/path><path d=\"M425.723 415.933C425.053 416.333 423.903 416.976 422.753 416.977C359.733 417.029 296.713 417.026 233.693 417.019C233.205 417.019 232.716 416.877 232.021 416.399C293.293 416 354.771 416.006 416.249 416.002C419.247 416.002 422.245 415.921 425.723 415.933Z\" fill=\"#93D8DA\"><\/path><path d=\"M272.013 524.127C273.56 524.659 274.766 525.898 275.985 525.912C288.777 526.054 301.571 525.998 314.364 526C337.625 526.005 360.886 526.012 384.627 526.066C383.515 526.409 381.922 526.958 380.328 526.96C345.2 527.009 310.071 527.023 274.944 526.861C273.998 526.856 269.235 529.396 272.013 524.127Z\" fill=\"#51BEC1\"><\/path><path d=\"M275.464 502.916C275.685 502.576 276.372 502.037 277.059 502.037C312.262 502.04 347.465 502.088 382.864 502.524C347.351 502.934 311.64 502.952 275.464 502.916Z\" fill=\"#C1E9E9\"><\/path><path d=\"M360.627 518.588C338.958 518.885 316.964 518.931 294.508 518.909C295.299 518.561 296.551 518.042 297.805 518.039C317.823 517.989 337.843 518 357.862 518.019C358.675 518.02 359.489 518.227 360.627 518.588Z\" fill=\"#51BEC1\"><\/path><path d=\"M413.373 526.412C432.042 526.115 451.035 526.069 470.491 526.092C470.361 526.421 469.77 526.908 469.18 526.907C450.685 526.855 432.191 526.755 413.373 526.412Z\" fill=\"#51BEC1\"><\/path><path d=\"M187.447 526.416C205.757 526.127 224.393 526.075 243.491 526.092C243.357 526.421 242.76 526.909 242.165 526.908C224.034 526.852 205.903 526.749 187.447 526.416Z\" fill=\"#51BEC1\"><\/path><path d=\"M437.557 557.401C451.154 557.14 465.076 557.103 479.461 557.111C478.336 557.442 476.746 557.979 475.158 557.971C462.732 557.915 450.307 557.754 437.557 557.401Z\" fill=\"#BCE7E7\"><\/path><path d=\"M178.328 557.423C191.944 557.127 205.878 557.105 220.253 557.133C218.767 557.459 216.838 557.973 214.911 557.969C202.822 557.942 190.733 557.8 178.328 557.423Z\" fill=\"#BDE7E8\"><\/path><path d=\"M469.565 542.044C466.231 542.389 462.433 542.817 458.627 542.924C454.186 543.048 449.738 542.891 445.103 542.456C452.973 542.033 461.035 542.01 469.565 542.044Z\" fill=\"#AEE2E3\"><\/path><path d=\"M383.964 522.944C383.699 522.979 383.422 522.788 383.058 522.359C383.297 522.32 383.624 522.519 383.964 522.944Z\" fill=\"#51BEC1\"><\/path><path d=\"M385.921 525.972C385.709 525.85 385.77 525.681 385.766 525.249C385.866 525.299 386.03 525.612 385.921 525.972Z\" fill=\"#51BEC1\"><\/path><path d=\"M334.175 273.004C332.97 272.633 332.134 272.269 331.081 271.809C335.407 267.696 339.472 263.831 343.146 260.339C344.059 263.991 343.997 269.307 346.574 272.48C349.138 275.637 354.352 276.641 357.752 278.275C353.911 282.422 349.695 286.974 344.706 292.359C346.689 282.35 343.733 275.849 334.175 273.004Z\" fill=\"white\"><\/path><path d=\"M470.064 493.074C469.263 505.667 458.859 516.55 445.921 517.94C442.146 518.345 438.142 518.452 434.484 517.628C429.944 516.605 430.673 512.207 431.167 509.011C431.473 507.031 433.372 505.011 435.061 503.623C436.327 502.581 438.371 502.231 440.115 502.066C450.737 501.065 454.273 493.616 454.013 485.351C453.935 482.861 454.001 480.366 454.001 477.41C450.501 478.857 447.266 480.171 444.05 481.528C432.389 486.449 419.991 487.288 407.595 487.919C404.367 488.083 401.025 487.562 397.849 486.849C391.837 485.501 389.538 477.698 393.822 472.728C405.766 458.875 420.713 449.182 437.379 441.963C444.552 438.855 451.624 435.491 458.902 432.654C463.974 430.678 467.835 432.529 469.949 437.994C469.969 456.918 470.016 474.996 470.064 493.074ZM448.48 459.014C450.187 457.088 451.894 455.161 453.601 453.235C453.355 452.904 453.109 452.572 452.863 452.241C442.67 457.826 432.478 463.412 422.286 468.997C432.298 469.223 440.573 465.461 448.48 459.014Z\" fill=\"#16A9AB\"><\/path><path d=\"M187.164 438.05C190.031 431.58 192.091 430.548 198.853 432.94C219.774 440.34 239.659 449.691 256.264 464.83C259.409 467.698 262.294 470.994 264.697 474.504C269.291 481.213 265.213 487.92 256.195 487.904C239.247 487.873 222.282 487.399 206.97 478.521C206.154 478.047 205.19 477.827 203.999 477.377C203.999 480.374 204.212 483.042 203.96 485.665C203.024 495.421 207.766 501.848 219.294 503.073C225.196 503.7 228.669 508.657 226.89 513.833C225.079 519.103 219.836 518.736 215.722 518.924C203.951 519.465 190.637 508.687 187.939 497.065C187.684 495.965 187.351 494.883 187.376 493.094C187.777 474.872 187.865 457.35 187.905 439.827C187.906 439.235 187.422 438.642 187.164 438.05ZM210.067 460.532C217.535 466.226 225.8 469.677 235.647 468.934C225.396 463.474 215.145 458.014 204.895 452.553C204.586 453.002 204.277 453.451 203.968 453.899C205.834 455.934 207.7 457.97 210.067 460.532Z\" fill=\"#15A8AB\"><\/path><path d=\"M288.966 487.103C284.491 487.576 282.08 484.765 281.247 481.127C280.445 477.628 281.226 474.037 286.005 472.182C314.22 472.028 341.637 471.98 369.054 471.933C374.03 471.792 376.257 475.19 376.368 479.194C376.474 483.034 374.757 486.756 368.946 487.02C341.72 487.034 315.343 487.068 288.966 487.103Z\" fill=\"#14A8AA\"><\/path><path d=\"M368.821 471.567C341.637 471.98 314.22 472.028 286.327 472.026C286.516 471.632 287.183 470.982 287.848 470.983C314.762 471.019 341.675 471.114 368.821 471.567Z\" fill=\"#53BFC2\"><\/path><path d=\"M289.173 487.486C315.343 487.068 341.72 487.034 368.565 487.051C368.193 487.402 367.354 487.962 366.514 487.962C340.803 487.965 315.091 487.913 289.173 487.486Z\" fill=\"#C1E9E9\"><\/path><path d=\"M470.455 492.872C470.016 474.996 469.968 456.918 469.981 438.368C470.369 438.552 470.983 439.208 470.982 439.864C470.976 457.466 470.906 475.068 470.455 492.872Z\" fill=\"#95D8DA\"><\/path><path d=\"M187.094 438.511C187.422 438.642 187.906 439.235 187.905 439.827C187.865 457.35 187.778 474.872 187.419 492.709C187.103 475.007 187.064 456.99 187.094 438.511Z\" fill=\"#52BFC1\"><\/path><path d=\"M448.221 459.269C440.573 465.461 432.298 469.223 422.286 468.998C432.478 463.412 442.67 457.826 452.863 452.241C453.109 452.572 453.355 452.904 453.601 453.235C451.894 455.162 450.187 457.088 448.221 459.269Z\" fill=\"white\"><\/path><path d=\"M209.816 460.269C207.699 457.97 205.833 455.935 203.967 453.899C204.276 453.451 204.585 453.002 204.894 452.553C215.145 458.014 225.396 463.474 235.647 468.934C225.799 469.677 217.535 466.226 209.816 460.269Z\" fill=\"white\"><\/path><\/g><defs><clipPath id=\"clip0_1427_3702\"><rect width=\"800\" height=\"800\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tInstallation :\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<span style=\"font-family: &quot;Open Sans&quot;, sans-serif;font-size: 16px;font-style: normal;font-weight: 600\">Time2plug garantit le meilleur choix des \u00e9quipements de recharge ainsi que du prestataire IRVE. Nous assurons une prise en main et une mise en service par un professionnel certifi\u00e9 pour une installation r\u00e9ussie.<\/span>\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ecbee4d elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"ecbee4d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:7}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"800\" height=\"800\" viewBox=\"0 0 800 800\" fill=\"none\"><g clip-path=\"url(#clip0_1427_3668)\"><path d=\"M801 288C801 459.333 801 630.167 801 801C534.333 801 267.667 801 1 801C1 534.333 1 267.667 1 1C267.667 1 534.333 1 801 1C801 96.5 801 192 801 288ZM219.052 568.72C219.349 569.643 219.723 570.549 219.93 571.492C222.224 581.983 232.295 590.028 243.067 590.026C353.387 590.012 463.707 589.998 574.027 590.022C583.429 590.024 590.533 586.015 594.975 577.893C599.356 569.884 599.653 561.387 594.793 553.534C581.171 531.523 567.196 509.73 553.424 487.811C541.744 469.221 529.829 450.767 518.621 431.894C509.547 416.615 484.89 415.478 475.875 430.207C472.728 435.35 469.352 440.353 466.139 445.457C458.702 457.272 451.301 469.11 443.589 481.412C428.572 446.032 400.953 435.033 364.999 439.533C364.999 436.076 365.195 433.605 364.955 431.177C364.556 427.133 365.963 425.404 370.04 423.73C375.66 421.423 380.862 417.662 385.614 413.757C400.475 401.545 409.55 385.671 413.443 366.911C414.216 363.189 416.426 361.852 419.514 361.039C431.882 357.783 442.564 342.556 440.934 329.87C439.063 315.307 430.492 303.799 414.999 300.336C414.999 295.427 415.008 290.444 414.996 285.462C414.986 280.631 415.647 275.677 414.808 270.992C411.727 253.786 403.996 239.024 390.279 227.783C378.598 218.211 365.455 212.281 349.666 211.202C338.118 211.186 326.57 211.17 314.229 211.321C312.293 211.544 310.323 211.605 308.427 212.012C281.721 217.75 262.866 232.637 253.91 258.985C250.028 270.406 249.76 282.264 250.104 294.117C250.233 298.568 249.205 300.823 244.566 302.169C240.795 303.263 236.846 305.566 234.213 308.458C217.827 326.452 223.975 355.788 248.82 362.17C250.074 362.492 251.344 364.303 251.858 365.696C254.77 373.602 256.497 382.102 260.413 389.448C268.806 405.193 281.492 416.955 297.599 424.889C298.823 425.492 300.475 426.302 300.849 427.388C303.493 435.056 300.569 439.001 292.518 439.001C291.352 439.001 290.186 438.996 289.02 439.002C282.632 439.035 275.945 437.857 269.917 439.346C255.109 443.004 241.614 449.452 232.133 462.301C224.474 472.682 219.725 484.063 219.023 497.973C219.069 521.296 219.115 544.62 219.052 568.72ZM215.673 700.927C214.739 700.268 213.827 699.577 212.868 698.956C189.295 683.702 167.266 666.509 147.817 646.207C140.217 638.274 133.141 629.825 126.033 621.436C111.649 604.459 99.526 585.894 89.1742 566.266C73.7536 537.026 62.602 506.224 55.7761 473.768C51.0902 451.487 48.8019 429.033 48.0935 406.379C47.8251 397.795 48.3638 389.153 49.0634 380.58C50.1725 366.989 50.985 353.309 53.2568 339.892C57.1494 316.903 63.1576 294.34 72.2356 272.827C78.6451 257.637 85.7108 242.649 93.5864 228.171C106.952 203.6 123.491 181.113 142.893 160.984C154.463 148.98 166.983 137.819 179.691 127.002C196.743 112.489 215.467 100.269 235.395 90.0307C246.295 84.4311 257.22 78.6941 268.636 74.3335C283.766 68.5541 299.261 63.6182 314.844 59.181C324.043 56.5617 333.666 55.2255 343.186 53.9906C358.318 52.0278 373.493 50.15 388.709 49.1721C398.251 48.5589 407.95 49.1744 417.495 50.0967C434.3 51.7205 451.146 53.3737 467.786 56.1465C496.465 60.9256 523.822 70.367 549.849 83.1685C565.235 90.7369 579.886 99.8213 594.729 108.462C598.03 110.384 601.136 111.467 603.278 107.946C605.109 104.937 604.595 101.728 600.658 99.781C597.47 98.2047 594.594 95.9984 591.581 94.0698C570.354 80.4835 547.784 69.5797 524.126 61.0129C502.693 53.2518 480.889 46.6461 458.14 43.9837C441.884 42.0812 425.59 39.5271 409.284 39.2972C390.446 39.0317 371.539 40.5635 352.733 42.158C341.389 43.1198 329.98 44.9003 318.958 47.7161C302.889 51.8217 286.95 56.6431 271.304 62.1495C248.396 70.2115 226.781 81.1521 206.292 94.2226C187.565 106.169 169.49 119.017 153.698 134.744C142.463 145.933 130.879 156.894 120.753 169.042C110.657 181.154 101.897 194.424 93.069 207.536C81.3949 224.876 71.9363 243.538 64.2215 262.883C53.6887 289.294 45.1363 316.424 41.9875 344.876C39.9991 362.844 38.0626 380.856 37.2201 398.9C36.7072 409.884 37.9593 421.003 39.0682 431.996C40.4322 445.518 41.4636 459.201 44.4666 472.399C48.5837 490.493 53.6495 508.461 59.7068 526C67.7592 549.317 78.8453 571.317 91.991 592.271C104.916 612.872 119.586 632.105 136.297 649.733C152.216 666.528 169.594 681.682 188.467 695.151C212.172 712.068 237.412 726.153 264.435 736.944C286.165 745.621 308.414 752.849 331.635 756.195C350.948 758.978 370.357 761.578 389.814 762.717C403.257 763.504 416.891 762.083 430.37 760.881C444.543 759.617 458.757 758.085 472.723 755.455C484.168 753.3 495.2 749.05 506.551 746.283C524.07 742.012 540.345 734.6 556.582 727.107C574.371 718.898 591.083 708.835 607.143 697.562C622.499 686.782 637.153 675.228 650.438 661.996C657.726 654.738 665.175 647.552 671.683 639.622C682.483 626.462 693.415 613.277 702.777 599.104C715.744 579.474 727.066 558.79 735.141 536.536C739.467 524.612 744.454 512.857 747.768 500.653C751.649 486.355 754.825 471.761 756.868 457.095C759.359 439.206 761.256 421.132 761.716 403.095C762.097 388.157 760.54 373.098 758.875 358.201C757.393 344.935 754.979 331.735 752.272 318.651C748.007 298.037 741.225 278.123 732.795 258.886C726.911 245.461 720.493 232.127 712.835 219.661C703.057 203.745 691.677 188.819 681.245 173.294C678.77 169.61 675.17 168.9 672.42 170.551C669.353 172.392 670.142 176.091 672.357 179.045C676.956 185.178 681.503 191.351 686.002 197.557C702.957 220.946 717.025 246.009 726.871 273.131C733.419 291.168 739.418 309.609 743.28 328.359C747.335 348.05 749.164 368.276 750.77 388.364C751.716 400.198 750.741 412.246 749.894 424.145C748.985 436.912 747.979 449.76 745.651 462.32C741.368 485.438 734.979 507.985 726.201 529.928C716.908 553.161 705.639 575.267 691.472 595.792C682.941 608.152 673.575 620.002 663.839 631.447C646.327 652.033 626.455 670.163 604.518 686.021C578.772 704.632 551.042 719.587 521.36 730.772C489.526 742.768 456.343 749.103 422.542 751.824C409.3 752.889 395.875 752.531 382.582 751.86C369.785 751.214 356.92 750.052 344.321 747.801C328.195 744.92 312.125 741.364 296.352 736.95C267.969 729.008 241.467 716.566 215.673 700.927Z\" fill=\"white\"><\/path><path d=\"M219.162 497.05C219.725 484.063 224.474 472.682 232.133 462.301C241.614 449.452 255.109 443.004 269.917 439.346C275.945 437.857 282.632 439.035 289.02 439.002C290.186 438.996 291.352 439.001 292.518 439.001C300.569 439.001 303.493 435.056 300.849 427.388C300.475 426.302 298.823 425.493 297.598 424.889C281.492 416.955 268.805 405.193 260.413 389.448C256.497 382.102 254.77 373.602 251.858 365.696C251.344 364.303 250.074 362.492 248.82 362.17C223.975 355.788 217.827 326.452 234.213 308.458C236.846 305.566 240.795 303.264 244.565 302.169C249.205 300.823 250.233 298.568 250.104 294.117C249.76 282.264 250.028 270.406 253.91 258.985C262.866 232.637 281.721 217.75 308.427 212.012C310.323 211.605 312.293 211.544 314.947 211.498C327.149 211.77 338.632 211.866 350.116 211.962C365.455 212.281 378.598 218.211 390.279 227.783C403.996 239.024 411.727 253.786 414.808 270.992C415.647 275.677 414.985 280.631 414.996 285.462C415.007 290.444 414.999 295.427 414.999 300.336C430.491 303.799 439.063 315.307 440.934 329.87C442.564 342.557 431.882 357.783 419.514 361.039C416.426 361.852 414.216 363.189 413.443 366.911C409.55 385.671 400.475 401.545 385.614 413.757C380.862 417.662 375.66 421.423 370.04 423.73C365.963 425.404 364.556 427.133 364.955 431.177C365.195 433.605 364.999 436.076 364.999 439.533C400.953 435.033 428.572 446.032 443.589 481.412C451.301 469.11 458.702 457.272 466.139 445.457C469.352 440.353 472.728 435.35 475.875 430.207C484.89 415.478 509.547 416.615 518.621 431.894C529.829 450.767 541.743 469.221 553.424 487.811C567.196 509.73 581.171 531.523 594.793 553.534C599.653 561.387 599.356 569.884 594.975 577.893C590.533 586.015 583.429 590.024 574.027 590.022C463.707 589.998 353.387 590.012 243.067 590.026C232.295 590.028 222.224 581.983 219.93 571.492C219.723 570.549 219.349 569.643 219.356 568.007C219.771 566.474 219.98 565.655 219.98 564.836C219.999 543.504 220.009 522.172 219.96 500.84C219.957 499.576 219.44 498.314 219.162 497.05ZM383.992 451.995C383.992 451.995 384.081 451.984 383.37 452.457C383.265 465.667 383.161 478.877 383.007 492.832C381.989 499.053 377.311 500.824 371.391 501.317C370.739 501.217 370.087 501.029 369.434 501.028C345.025 501.009 320.616 500.996 296.207 501.039C295.128 501.04 294.05 501.574 292.25 501.954C286.9 500.107 282.93 496.997 282.66 490.299C282.77 477.931 282.89 465.562 282.947 453.194C282.948 452.829 282.284 452.462 281.031 452.017C275.396 453.018 269.76 454.02 263.497 455.578C263.334 456.549 263.028 457.52 263.027 458.491C263.002 496.589 262.994 534.688 263.049 572.787C263.051 574.173 263.713 575.557 264.995 576.991C276.403 576.991 287.811 576.991 300.043 576.991C294.312 568.782 289.134 560.914 289.021 550.118C288.985 541.396 288.948 532.675 288.974 523.205C290.552 517.63 294.513 514.012 299.647 513.996C321.473 513.931 343.3 513.958 365.126 514.019C369.766 514.032 376.179 518.713 376.922 523.076C378.874 534.543 379.193 546.179 375.819 557.341C373.749 564.194 369.78 570.472 366.766 576.795C376.354 576.795 386.885 576.795 397.464 576.795C394.131 562.704 395.277 555.752 402.537 548.324C402.689 547.518 402.972 546.713 402.973 545.907C402.996 516.84 403.007 487.773 402.95 458.706C402.947 457.489 402.286 456.273 401.162 454.979C397.703 453.925 394.244 452.871 390.19 451.402C388.127 451.63 386.065 451.857 383.992 451.995ZM301.554 451.314C299.494 451.314 297.433 451.314 295.385 451.314C295.385 464.087 295.385 476.315 295.385 488.66C320.663 488.66 345.557 488.66 370.714 488.66C370.714 476.083 370.714 463.845 370.714 450.735C368.241 451.222 366.171 451.63 364.014 452.796C363.387 454.091 362.578 455.33 362.161 456.69C357.392 472.252 344.744 476.665 330.821 476.689C317.34 476.713 304.768 467.545 301.554 451.314ZM250.737 576.467C250.822 539.429 250.912 502.392 250.935 465.354C250.935 464.878 250.075 464.402 249.138 464.352C240.453 472.815 234.572 482.77 232.339 495.606C232.23 496.426 232.028 497.246 232.027 498.066C232.006 520.277 231.994 542.488 232.037 564.699C232.04 565.777 232.564 566.854 233.019 568.649C235.94 577.045 242.581 577.757 250.737 576.467ZM399.731 318.212C399.419 318.345 399.179 318.559 398.392 319.193C391.417 326.364 381.981 326.774 373.915 324.498C356.811 319.672 339.601 318.333 322.134 319.15C314.548 319.505 306.938 321.086 299.519 322.864C286.79 325.913 274.583 327.19 263.947 316.545C263.835 316.421 263.743 316.237 263.606 316.194C263.495 316.159 263.206 316.295 263.207 316.35C263.407 325.563 263.627 334.775 263.977 344.912C264.331 350.001 264.48 355.113 265.073 360.174C267.803 383.44 280.733 399.872 300.578 410.996C313.769 418.39 327.829 421.05 343.32 418.246C362.296 414.811 376.693 405.358 388.212 390.382C396.771 379.255 400.476 366.487 402.653 352.239C402.653 340.038 402.653 327.837 402.653 315.636C402.348 315.602 402.042 315.568 401.736 315.534C401.497 316.082 401.258 316.629 400.922 317.607C400.754 317.886 400.507 318.023 399.731 318.212ZM448.925 499.401C444.835 505.894 440.717 512.37 436.661 518.884C427.942 532.891 419.017 546.777 410.651 560.992C406.156 568.63 411.571 576.992 420.464 576.994C471.091 577.008 521.718 576.965 572.345 577.057C577.225 577.066 580.395 574.746 582.902 571.053C585.6 567.078 584.961 563.016 582.57 559.207C568.041 536.058 553.447 512.95 538.885 489.822C528.221 472.884 517.442 456.016 506.981 438.953C502.451 431.564 492.789 430.805 488.407 437.164C485.074 441.999 481.793 446.875 478.647 451.834C468.757 467.424 458.942 483.062 448.925 499.401ZM289.141 233.568C269.996 246.204 260.748 269.625 264.702 287.759C310.382 269.197 356.075 269.422 401.745 287.912C405.922 258.061 383.267 228.142 353.725 224.961C343.681 223.88 333.46 224.507 323.326 224.168C311.193 223.761 300.003 226.68 289.141 233.568ZM312.302 569.216C328.551 583.464 352.919 577.468 361.653 558.324C366.243 548.263 363.653 537.547 364.115 526.739C347.173 526.739 330.875 526.739 314.577 526.739C301.644 526.739 302.047 526.755 301.532 539.931C301.094 551.11 303.462 560.901 312.302 569.216ZM309.605 307.027C330.888 304.832 352.21 304.428 372.874 310.545C382.557 313.411 389.803 311.61 397.292 301.156C362.223 281.559 299.626 283.088 268.633 301.265C276.485 311.941 281.632 313.639 294.116 310.194C298.901 308.874 303.852 308.16 309.605 307.027ZM328.021 432.518C323.845 432.052 319.669 431.587 315 431.066C315 436.166 315.199 440.958 314.957 445.728C314.486 455.026 321.2 461.376 329.775 463.816C335.295 465.387 345.27 459.67 348.614 453.847C352.827 446.511 350.256 438.785 351.001 431.375C343.209 431.915 336.033 432.412 328.021 432.518ZM414.999 501.5C414.999 509.465 414.999 517.43 414.999 526.558C420.095 518.776 424.642 512.4 428.539 505.65C430.583 502.111 433.159 497.624 432.542 494.078C431.423 487.647 428.709 481.256 425.488 475.506C423.142 471.32 420.549 466.521 414.999 464.307C414.999 476.841 414.999 488.67 414.999 501.5ZM241.362 341.808C244.133 344.106 246.904 346.404 250.732 349.579C250.732 336.726 250.732 325.736 250.732 314.688C240.232 317.805 235.979 330.598 241.362 341.808ZM415 344.976C415.069 345.894 415.139 346.811 415.217 347.837C422.339 345.247 427.029 338.377 426.998 331.023C426.968 323.935 422.124 317.181 414.999 314.623C414.999 324.516 414.999 334.298 415 344.976Z\" fill=\"#16A9AA\"><\/path><path d=\"M216.036 701.002C241.467 716.566 267.969 729.008 296.352 736.951C312.125 741.364 328.195 744.92 344.321 747.801C356.92 750.052 369.785 751.214 382.582 751.86C395.875 752.531 409.3 752.889 422.542 751.824C456.343 749.103 489.525 742.768 521.36 730.772C551.042 719.587 578.772 704.632 604.518 686.021C626.455 670.163 646.327 652.033 663.839 631.447C673.575 620.002 682.941 608.152 691.472 595.792C705.639 575.267 716.908 553.161 726.201 529.928C734.979 507.985 741.368 485.438 745.651 462.32C747.979 449.76 748.985 436.912 749.894 424.145C750.741 412.246 751.716 400.198 750.77 388.364C749.164 368.276 747.335 348.05 743.28 328.359C739.418 309.609 733.419 291.168 726.871 273.131C717.025 246.009 702.957 220.946 686.002 197.557C681.503 191.351 676.956 185.178 672.357 179.045C670.142 176.091 669.353 172.392 672.42 170.551C675.17 168.9 678.77 169.61 681.245 173.294C691.677 188.819 703.057 203.745 712.835 219.661C720.493 232.127 726.911 245.462 732.795 258.886C741.225 278.123 748.007 298.037 752.272 318.651C754.979 331.735 757.393 344.935 758.875 358.201C760.54 373.098 762.097 388.157 761.716 403.095C761.256 421.132 759.359 439.206 756.868 457.095C754.825 471.761 751.649 486.355 747.768 500.653C744.454 512.858 739.467 524.612 735.141 536.536C727.066 558.79 715.744 579.474 702.777 599.104C693.415 613.278 682.483 626.462 671.683 639.622C665.175 647.552 657.726 654.738 650.438 661.996C637.153 675.228 622.499 686.782 607.143 697.562C591.083 708.835 574.371 718.898 556.582 727.107C540.345 734.6 524.07 742.012 506.551 746.283C495.2 749.05 484.168 753.3 472.723 755.455C458.756 758.085 444.543 759.617 430.37 760.881C416.891 762.083 403.257 763.504 389.814 762.717C370.357 761.578 350.948 758.978 331.635 756.195C308.414 752.849 286.165 745.621 264.435 736.944C237.412 726.153 212.172 712.068 188.467 695.151C169.594 681.682 152.216 666.528 136.296 649.734C119.586 632.105 104.916 612.872 91.9909 592.271C78.8452 571.317 67.7591 549.317 59.7068 526C53.6495 508.461 48.5836 490.493 44.4665 472.399C41.4635 459.201 40.4322 445.518 39.0681 431.996C37.9592 421.003 36.7071 409.884 37.22 398.9C38.0625 380.856 39.999 362.844 41.9875 344.876C45.1362 316.424 53.6886 289.294 64.2215 262.883C71.9363 243.538 81.3948 224.876 93.0689 207.536C101.896 194.424 110.657 181.154 120.753 169.042C130.879 156.894 142.463 145.933 153.698 134.744C169.49 119.017 187.565 106.169 206.292 94.2226C226.781 81.1521 248.396 70.2115 271.304 62.1495C286.95 56.6432 302.889 51.8217 318.958 47.7162C329.98 44.9003 341.388 43.1198 352.733 42.158C371.539 40.5635 390.446 39.0317 409.284 39.2973C425.59 39.5271 441.884 42.0813 458.14 43.9837C480.889 46.6461 502.693 53.2519 524.126 61.0129C547.784 69.5797 570.354 80.4836 591.581 94.0698C594.594 95.9984 597.47 98.2048 600.658 99.781C604.595 101.728 605.109 104.937 603.278 107.946C601.136 111.467 598.03 110.384 594.729 108.462C579.886 99.8213 565.235 90.7369 549.849 83.1686C523.822 70.367 496.465 60.9256 467.786 56.1466C451.146 53.3737 434.3 51.7206 417.495 50.0968C407.95 49.1744 398.251 48.559 388.709 49.1722C373.492 50.1501 358.318 52.0279 343.186 53.9907C333.666 55.2256 324.043 56.5617 314.844 59.181C299.261 63.6183 283.766 68.5542 268.636 74.3335C257.22 78.6941 246.295 84.4312 235.395 90.0308C215.467 100.269 196.743 112.489 179.691 127.002C166.982 137.819 154.463 148.98 142.893 160.984C123.491 181.113 106.952 203.601 93.5864 228.171C85.7107 242.649 78.645 257.637 72.2355 272.827C63.1575 294.34 57.1493 316.903 53.2567 339.892C50.9849 353.309 50.1725 366.989 49.0634 380.58C48.3638 389.153 47.8251 397.795 48.0935 406.379C48.8019 429.033 51.0902 451.487 55.776 473.768C62.602 506.224 73.7536 537.026 89.1742 566.266C99.5259 585.894 111.649 604.459 126.033 621.436C133.141 629.825 140.217 638.274 147.817 646.207C167.266 666.509 189.295 683.702 212.868 698.956C213.826 699.577 214.739 700.268 216.036 701.002Z\" fill=\"#17A9AB\"><\/path><path d=\"M219.093 497.512C219.44 498.314 219.957 499.577 219.96 500.84C220.009 522.172 219.999 543.504 219.98 564.836C219.98 565.655 219.771 566.474 219.41 567.619C219.115 544.62 219.069 521.296 219.093 497.512Z\" fill=\"#4EBEC0\"><\/path><path d=\"M349.891 211.582C338.632 211.866 327.149 211.77 315.344 211.413C326.57 211.17 338.118 211.186 349.891 211.582Z\" fill=\"#4FBFC1\"><\/path><path d=\"M449.011 499.042C458.942 483.063 468.757 467.424 478.647 451.834C481.793 446.875 485.074 441.999 488.407 437.164C492.79 430.805 502.451 431.564 506.981 438.953C517.442 456.016 528.222 472.884 538.886 489.822C553.447 512.95 568.041 536.058 582.57 559.207C584.961 563.016 585.6 567.078 582.902 571.053C580.395 574.746 577.225 577.066 572.345 577.058C521.718 576.965 471.091 577.008 420.464 576.994C411.572 576.992 406.157 568.63 410.651 560.992C419.017 546.777 427.942 532.891 436.662 518.884C440.717 512.37 444.836 505.894 449.011 499.042ZM468.97 534.516C468.313 535.929 466.896 537.479 467.123 538.731C468.505 546.364 469.915 554.033 472.151 561.437C472.663 563.133 476.591 565.031 478.701 564.78C484.947 564.035 491.099 562.379 497.232 560.857C503.224 559.369 505.291 552.874 500.884 548.932C499.176 547.405 496.409 547.062 493.944 546.11C497.032 541.818 500.125 537.653 503.074 533.388C507.141 527.507 511.546 521.796 514.98 515.557C518.544 509.084 513.782 502.017 506.456 502.004C500.382 501.994 494.307 502.002 487.516 502.002C488.624 499.999 489.249 498.723 490.004 497.528C494.088 491.065 498.251 484.652 502.29 478.162C504.531 474.562 503.424 469.633 500.077 467.533C497.209 465.733 493.059 467.143 490.609 470.855C484.802 479.653 479.083 488.509 473.238 497.281C470.527 501.35 470.005 505.745 472.433 509.764C474.745 513.592 478.703 515.245 483.407 515.046C488.431 514.834 493.471 514.998 498.973 514.998C492.606 523.819 486.743 531.941 480.595 540.457C478.477 534.074 474.729 532.108 468.97 534.516Z\" fill=\"white\"><\/path><path d=\"M402.178 352.891C400.476 366.487 396.771 379.255 388.212 390.382C376.693 405.358 362.296 414.811 343.32 418.246C327.829 421.05 313.77 418.39 300.578 410.996C280.733 399.872 267.803 383.44 265.074 360.173C264.48 355.113 264.331 350.001 263.977 343.984C264.021 334.397 264.065 325.738 264.109 317.078C274.584 327.19 286.79 325.913 299.519 322.863C306.938 321.086 314.549 319.505 322.135 319.15C339.601 318.333 356.811 319.672 373.915 324.498C381.981 326.774 391.417 326.364 398.969 319.025C399.757 318.578 399.969 318.298 400.181 318.018C400.507 318.023 400.754 317.886 401.371 317.546C401.939 329.287 402.058 341.089 402.178 352.891ZM363.61 385.886C365.869 382.403 365.323 379.105 362.145 376.767C358.677 374.216 355.424 374.916 352.225 378.107C349.004 381.321 345.541 385.368 341.486 386.462C331.131 389.258 322.42 390.219 313.074 378.182C310.379 374.711 306.481 375.557 303.185 376.509C300.543 377.272 300.237 382.607 302.261 385.765C303.136 387.131 304.135 388.43 305.183 389.671C313.533 399.557 324.616 401.728 336.821 401.029C347.983 400.389 356.831 395.785 363.61 385.886Z\" fill=\"white\"><\/path><path d=\"M401.975 548.915C395.277 555.752 394.131 562.704 397.464 576.795C386.885 576.795 376.354 576.795 366.766 576.795C369.78 570.472 373.749 564.194 375.819 557.341C379.193 546.179 378.874 534.543 376.922 523.076C376.179 518.713 369.766 514.032 365.126 514.019C343.3 513.958 321.473 513.931 299.647 513.996C294.513 514.012 290.552 517.63 288.558 523.784C288.095 530.46 287.95 536.557 288.048 542.651C288.093 545.457 288.613 548.256 288.918 551.058C289.134 560.914 294.312 568.782 300.043 576.991C287.811 576.991 276.403 576.991 264.502 576.505C264.048 535.686 264.087 495.354 264.125 455.022C269.76 454.02 275.396 453.018 281.51 452.518C282.047 465.663 282.104 478.307 282.161 490.95C282.93 496.997 286.9 500.107 293.078 501.985C319.948 501.964 345.988 501.912 372.029 501.86C377.311 500.824 381.989 499.053 383.423 492.257C383.92 478.449 384.001 465.217 384.081 451.984C384.081 451.984 383.992 451.995 384.426 452.028C386.835 451.98 388.81 451.898 390.785 451.817C394.244 452.871 397.703 453.925 401.575 455.48C401.984 486.959 401.98 517.937 401.975 548.915Z\" fill=\"white\"><\/path><path d=\"M289.434 233.35C300.004 226.68 311.193 223.761 323.326 224.168C333.46 224.507 343.681 223.88 353.725 224.961C383.267 228.142 405.922 258.061 401.746 287.912C356.075 269.422 310.383 269.197 264.702 287.757C260.748 269.625 269.996 246.204 289.434 233.35Z\" fill=\"#F0A628\"><\/path><path d=\"M311.995 569.029C303.462 560.901 301.094 551.11 301.532 539.931C302.047 526.755 301.643 526.739 314.577 526.739C330.875 526.739 347.173 526.739 364.115 526.739C363.653 537.547 366.243 548.263 361.653 558.324C352.919 577.468 328.551 583.464 311.995 569.029ZM321.044 555.335C326.476 561.152 333.361 557.999 339.644 558.2C343.593 558.326 345.743 555.666 345.683 551.822C345.622 547.928 343.073 545.72 339.376 545.449C335.144 545.138 330.847 545.099 326.621 545.452C321.53 545.877 319.638 549.13 321.044 555.335Z\" fill=\"#F0A628\"><\/path><path d=\"M309.166 307.099C303.852 308.16 298.901 308.874 294.116 310.194C281.632 313.639 276.485 311.941 268.633 301.265C299.626 283.088 362.223 281.559 397.292 301.156C389.803 311.61 382.557 313.411 372.874 310.545C352.21 304.428 330.888 304.832 309.166 307.099Z\" fill=\"#EEA629\"><\/path><path d=\"M232.858 494.943C234.572 482.77 240.453 472.815 249.55 464.592C249.974 502.178 249.985 539.523 249.997 576.869C242.581 577.757 235.94 577.045 232.992 567.828C232.929 542.986 232.894 518.964 232.858 494.943Z\" fill=\"white\"><\/path><path d=\"M301.908 452.046C304.769 467.545 317.34 476.713 330.822 476.689C344.744 476.665 357.393 472.252 362.161 456.69C362.578 455.33 363.388 454.091 364.497 452.4C366.572 452.005 368.164 452.005 369.719 452.005C369.719 464.265 369.719 476 369.719 487.727C345.053 487.727 320.669 487.727 296.235 487.727C296.235 475.701 296.235 463.947 296.235 452.046C298.281 452.046 300.094 452.046 301.908 452.046Z\" fill=\"white\"><\/path><path d=\"M328.439 432.713C336.033 432.412 343.21 431.915 351.001 431.375C350.256 438.785 352.827 446.511 348.614 453.847C345.27 459.67 335.295 465.387 329.775 463.816C321.2 461.376 314.486 455.026 314.957 445.728C315.199 440.958 315 436.166 315 431.066C319.669 431.587 323.845 432.052 328.439 432.713Z\" fill=\"white\"><\/path><path d=\"M414.999 501C414.999 488.67 414.999 476.841 414.999 464.307C420.548 466.521 423.142 471.321 425.488 475.506C428.709 481.257 431.423 487.647 432.542 494.078C433.159 497.624 430.583 502.111 428.539 505.65C424.642 512.4 420.095 518.776 414.999 526.558C414.999 517.431 414.999 509.465 414.999 501Z\" fill=\"white\"><\/path><path d=\"M241.208 341.453C235.979 330.598 240.232 317.805 250.732 314.688C250.732 325.736 250.732 336.726 250.732 349.579C246.904 346.404 244.133 344.106 241.208 341.453Z\" fill=\"white\"><\/path><path d=\"M414.999 344.527C414.999 334.298 414.999 324.516 414.999 314.623C422.124 317.181 426.968 323.935 426.998 331.023C427.029 338.377 422.339 345.247 415.217 347.837C415.139 346.811 415.07 345.894 414.999 344.527Z\" fill=\"white\"><\/path><path d=\"M301.731 451.68C300.094 452.046 298.281 452.046 296.235 452.046C296.235 463.947 296.235 475.701 296.235 487.727C320.669 487.727 345.053 487.727 369.719 487.727C369.719 476 369.719 464.265 369.719 452.005C368.164 452.005 366.572 452.005 364.54 452.021C366.171 451.63 368.241 451.222 370.714 450.735C370.714 463.845 370.714 476.083 370.714 488.659C345.557 488.659 320.664 488.659 295.385 488.659C295.385 476.315 295.385 464.086 295.385 451.314C297.434 451.314 299.494 451.314 301.731 451.68Z\" fill=\"#BFE8E8\"><\/path><path d=\"M263.811 455.3C264.087 495.354 264.049 535.686 264.039 576.481C263.713 575.558 263.051 574.173 263.049 572.787C262.994 534.688 263.003 496.589 263.028 458.491C263.028 457.52 263.334 456.549 263.811 455.3Z\" fill=\"#4EBEC0\"><\/path><path d=\"M250.367 576.668C249.985 539.524 249.974 502.178 249.789 464.379C250.075 464.402 250.935 464.878 250.935 465.354C250.912 502.392 250.822 539.429 250.367 576.668Z\" fill=\"#BFE8E8\"><\/path><path d=\"M402.256 548.62C401.98 517.937 401.984 486.959 401.96 455.519C402.286 456.273 402.948 457.489 402.95 458.706C403.007 487.773 402.996 516.84 402.973 545.907C402.972 546.713 402.689 547.518 402.256 548.62Z\" fill=\"#4EBEC0\"><\/path><path d=\"M371.71 501.588C345.988 501.912 319.948 501.964 293.439 501.938C294.05 501.574 295.128 501.04 296.207 501.038C320.616 500.996 345.025 501.009 369.434 501.028C370.087 501.029 370.739 501.217 371.71 501.588Z\" fill=\"#4FBFC1\"><\/path><path d=\"M232.599 495.275C232.894 518.964 232.929 542.986 232.905 567.47C232.564 566.854 232.04 565.777 232.038 564.699C231.994 542.488 232.006 520.277 232.027 498.066C232.028 497.246 232.23 496.426 232.599 495.275Z\" fill=\"#BEE7E7\"><\/path><path d=\"M383.726 452.22C384.001 465.217 383.92 478.449 383.448 491.885C383.161 478.877 383.265 465.667 383.726 452.22Z\" fill=\"#8ED5D7\"><\/path><path d=\"M282.411 490.625C282.104 478.307 282.047 465.663 281.96 452.558C282.284 452.462 282.948 452.829 282.947 453.194C282.89 465.562 282.77 477.931 282.411 490.625Z\" fill=\"#4EBEC0\"><\/path><path d=\"M402.415 352.565C402.058 341.089 401.939 329.287 401.419 317.331C401.258 316.629 401.497 316.082 401.736 315.534C402.042 315.568 402.347 315.602 402.653 315.636C402.653 327.837 402.653 340.038 402.415 352.565Z\" fill=\"#4CBDC0\"><\/path><path d=\"M264.028 316.811C264.065 325.737 264.021 334.397 263.911 343.522C263.627 334.775 263.407 325.563 263.207 316.35C263.206 316.295 263.495 316.159 263.606 316.194C263.743 316.237 263.835 316.421 264.028 316.811Z\" fill=\"#4EBEC0\"><\/path><path d=\"M288.969 550.588C288.613 548.256 288.093 545.457 288.048 542.651C287.95 536.557 288.095 530.46 288.526 524.158C288.948 532.675 288.985 541.396 288.969 550.588Z\" fill=\"#C3E9E9\"><\/path><path d=\"M390.488 451.61C388.81 451.898 386.834 451.98 384.431 452.073C386.065 451.857 388.127 451.63 390.488 451.61Z\" fill=\"#8ED5D7\"><\/path><path d=\"M399.957 318.115C399.97 318.298 399.758 318.578 399.277 318.856C399.179 318.559 399.42 318.345 399.957 318.115Z\" fill=\"#4CBDC0\"><\/path><path d=\"M469.303 534.28C474.729 532.108 478.477 534.074 480.595 540.457C486.742 531.941 492.605 523.819 498.973 514.998C493.471 514.998 488.431 514.834 483.407 515.046C478.703 515.245 474.745 513.592 472.433 509.764C470.005 505.745 470.527 501.35 473.238 497.281C479.083 488.509 484.802 479.653 490.609 470.855C493.059 467.143 497.208 465.733 500.077 467.533C503.424 469.633 504.531 474.562 502.29 478.162C498.25 484.652 494.088 491.065 490.004 497.528C489.249 498.722 488.624 499.999 487.516 502.002C494.307 502.002 500.381 501.994 506.456 502.004C513.782 502.017 518.543 509.084 514.98 515.557C511.545 521.796 507.141 527.507 503.074 533.388C500.125 537.653 497.032 541.818 493.944 546.11C496.409 547.062 499.176 547.405 500.883 548.932C505.291 552.874 503.223 559.369 497.232 560.856C491.099 562.379 484.946 564.034 478.701 564.779C476.59 565.031 472.663 563.133 472.15 561.437C469.914 554.033 468.504 546.364 467.123 538.731C466.896 537.479 468.313 535.928 469.303 534.28Z\" fill=\"#F1A72A\"><\/path><path d=\"M363.379 386.187C356.831 395.785 347.983 400.389 336.821 401.029C324.616 401.728 313.533 399.557 305.183 389.671C304.135 388.43 303.136 387.131 302.261 385.765C300.237 382.607 300.543 377.272 303.185 376.509C306.48 375.557 310.379 374.711 313.074 378.182C322.42 390.219 331.131 389.258 341.486 386.462C345.541 385.368 349.004 381.321 352.225 378.107C355.424 374.916 358.677 374.215 362.145 376.767C365.323 379.105 365.869 382.403 363.379 386.187Z\" fill=\"#16A9AB\"><\/path><path d=\"M320.914 554.966C319.639 549.13 321.53 545.877 326.622 545.452C330.848 545.099 335.144 545.138 339.377 545.449C343.074 545.72 345.623 547.928 345.683 551.822C345.743 555.665 343.594 558.326 339.644 558.2C333.362 557.999 326.477 561.152 320.914 554.966Z\" fill=\"#1DA8A5\"><\/path><\/g><defs><clipPath id=\"clip0_1427_3668\"><rect width=\"800\" height=\"800\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tGestion :\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<span style=\"font-family: &quot;Open Sans&quot;, sans-serif;font-size: 16px;font-style: normal;font-weight: 600\">Nous proposons une aide \u00e0 la gestion et \u00e0 la supervision de vos bornes de recharge via une plateforme d\u00e9di\u00e9e. Cette plateforme vous offre un acc\u00e8s facilit\u00e9 \u00e0 la facturation, \u00e0 votre suivi de consommation. Sans oublier votre r\u00e9f\u00e9rencement en ligne, l'optimisation \u00e9nerg\u00e9tique, ainsi que la gestion des acc\u00e8s.<\/span>\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-02dd39b elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"02dd39b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"800\" height=\"800\" viewBox=\"0 0 800 800\" fill=\"none\"><g clip-path=\"url(#clip0_1427_3798)\"><path d=\"M801 288C801 459.333 801 630.167 801 801C534.333 801 267.667 801 1 801C1 534.333 1 267.667 1 1C267.667 1 534.333 1 801 1C801 96.5 801 192 801 288ZM381.043 361.474C357.234 337.679 333.745 313.548 309.429 290.281C301.57 282.761 297.063 275.202 299.016 264.405C299.96 259.183 296.709 256.284 293.014 254.037C276.899 244.235 260.785 234.413 244.333 225.203C241.742 223.752 236.403 224.091 234.074 225.875C227.271 231.086 221.265 237.362 215.107 243.384C210.533 247.857 210.157 252.559 213.412 257.921C221.282 270.887 229.698 283.569 236.769 296.96C242.234 307.308 249.003 313.382 261.235 311.014C261.877 310.889 262.637 310.808 263.219 311.03C265.687 311.972 268.716 312.423 270.457 314.147C298.042 341.47 325.461 368.961 352.908 396.423C354.045 397.56 355.086 398.793 356.164 399.974C353.452 402.432 350.939 404.531 348.627 406.832C335.163 420.233 321.424 433.382 308.474 447.265C303.498 452.599 298.251 452.266 292.324 451.651C290.696 451.483 289.084 451.141 287.454 451.015C273.051 449.899 259.981 453.891 247.434 460.775C234.49 467.879 224.745 478.138 218.599 491.156C210.395 508.535 208.393 526.797 214.735 545.54C217.491 553.686 223.079 555.395 229.177 549.318C237.676 540.849 246.288 532.488 254.575 523.817C257.35 520.913 260.178 519.988 264.108 519.836C269.34 519.632 273.341 520.882 276.613 525.083C278.645 527.692 280.963 530.301 283.686 532.105C290.218 536.432 289.062 542.849 288.921 549.037C288.904 549.759 288.046 550.547 287.432 551.16C277.765 560.807 267.984 570.343 258.427 580.097C253.664 584.958 255.277 591.902 261.815 593.766C267.583 595.411 273.65 596.697 279.61 596.809C286.779 596.944 294.001 595.876 301.153 594.96C313.522 593.377 323.923 587.327 333.067 579.309C343.196 570.428 350.318 559.546 354.458 546.44C357.971 535.315 359.279 524.279 356.965 512.972C355.901 507.774 356.83 504.311 360.824 500.519C373.571 488.417 385.821 475.791 398.279 463.35C400.952 466.232 403.834 469.338 406.718 472.443C400.098 480.024 399.35 483.652 403.51 488.007C406.462 491.098 411.469 490.106 418.505 484.786C420.672 487.379 422.762 490.08 425.058 492.592C436.427 505.032 447.792 517.477 459.274 529.813C469.992 541.328 480.884 552.681 491.638 564.163C495.814 568.622 500.327 572.882 503.81 577.848C514.754 593.451 536.382 601.452 554.544 595.718C585.598 585.915 596.816 546.557 572.756 522.404C563.116 512.727 552.463 504.063 542.369 494.831C532.855 486.13 523.51 477.245 514.015 468.524C507.695 462.718 501.16 457.145 494.871 451.306C487.39 444.361 480.07 437.243 472.709 430.226C478.707 423.286 479.51 418.775 475.71 415.207C471.772 411.51 467.772 412.421 460.156 418.92C458.458 417.463 456.795 415.889 454.983 414.512C451.561 411.91 451.514 409.807 454.79 406.633C466.996 394.808 478.932 382.703 490.886 370.62C493.066 368.416 495.09 368.193 498.265 368.439C507.227 369.132 516.419 369.824 525.244 368.569C536.548 366.962 546.893 362.006 556.322 355.251C570.939 344.778 579.057 330.001 583.838 313.319C587.383 300.951 586.48 288.226 582.787 275.961C581.883 272.96 578.945 269.831 576.111 268.35C572.887 266.665 569.581 268.754 566.926 271.468C558.42 280.162 549.784 288.731 541.133 297.282C540.018 298.384 538.61 299.652 537.178 299.894C529.853 301.132 522.613 301.745 518.205 293.705C517.591 292.585 516.452 291.67 515.383 290.899C510.047 287.051 508.44 282.024 508.78 275.441C509.04 270.404 511.464 267.165 514.519 264.033C522.316 256.044 530.326 248.262 538.148 240.296C542.606 235.755 541.341 228.632 535.807 227.056C525.943 224.246 515.755 222.257 505.606 223.325C488.478 225.128 473.161 231.571 460.54 243.865C451.897 252.283 445.892 262.283 442.338 273.579C438.917 284.453 437.463 295.726 439.948 307.133C441.019 312.045 440.184 315.718 436.116 319.586C421.629 333.361 407.722 347.744 393.553 361.855C386.665 368.714 388.409 368.732 381.043 361.474ZM605.307 685.932C595.521 692.148 586.05 698.947 575.875 704.442C560.488 712.753 544.932 720.914 528.854 727.741C510.908 735.361 492.155 740.941 472.906 744.534C461.214 746.717 449.572 749.362 437.785 750.791C426.231 752.191 414.529 752.697 402.881 752.883C391.993 753.058 381.059 752.695 370.205 751.827C361.389 751.121 352.585 749.687 343.909 747.919C328.274 744.733 312.498 741.878 297.215 737.404C269.137 729.185 242.507 717.373 217.588 701.887C197.433 689.362 178.048 675.686 160.987 659.206C148.173 646.829 136.195 633.505 124.652 619.916C110.358 603.089 98.7155 584.342 88.4309 564.82C77.0759 543.266 68.338 520.673 61.5373 497.246C52.929 467.592 48.7289 437.323 48.1513 406.577C47.9005 393.223 49.0482 379.815 50.0884 366.473C50.8132 357.177 52.0887 347.889 53.7312 338.707C56.9769 320.563 60.9783 302.585 67.8316 285.377C72.8201 272.851 76.7589 259.78 82.9844 247.905C91.8778 230.942 101.706 214.357 112.456 198.507C127.197 176.772 144.751 157.358 164.496 139.858C180.219 125.923 196.693 113.158 214.477 101.995C232.172 90.8892 250.581 81.2621 270.16 73.9356C278.855 70.6819 287.493 67.2218 296.341 64.4426C306.376 61.2906 316.532 58.4083 326.797 56.1439C334.436 54.4589 342.319 53.8299 350.117 52.9352C362.347 51.532 374.57 49.756 386.845 49.1665C397.075 48.6753 407.424 49.1515 417.634 50.1095C434.276 51.6711 450.938 53.4225 467.431 56.0878C495.805 60.6734 522.815 70.1096 548.613 82.5068C564.491 90.1368 579.542 99.5308 594.723 108.539C598.404 110.724 601.693 109.677 603.353 107.585C605.227 105.222 604.279 102.098 600.851 99.8237C582.59 87.7045 563.452 77.1982 543.248 68.8033C529.298 63.0067 515.157 57.4169 500.67 53.2246C481.253 47.6059 461.487 43.093 441.19 41.6344C429.849 40.8193 418.527 39.3749 407.177 39.138C394.562 38.8747 381.909 39.3697 369.304 40.0864C359.482 40.645 349.525 41.2027 339.951 43.2633C323.122 46.8854 306.318 50.9556 289.919 56.1486C274.275 61.1025 258.865 67.0697 243.884 73.779C223.262 83.0151 203.794 94.4752 185.994 108.526C173.775 118.171 161.205 127.466 149.774 137.984C139.268 147.651 129.368 158.182 120.485 169.353C109.623 183.013 99.4901 197.351 90.1465 212.096C78.3361 230.734 68.8556 250.636 61.1282 271.385C48.6844 304.798 40.8636 339.23 38.1545 374.731C37.2159 387.032 38.1525 399.467 37.9647 411.836C37.6684 431.355 39.8452 450.693 44.175 469.59C48.7823 489.699 53.8941 509.867 61.0635 529.163C67.8443 547.413 76.9577 564.898 86.1631 582.122C99.9803 607.975 118.335 630.653 138.429 651.882C152.505 666.753 168.089 679.917 184.529 692.165C209.22 710.561 235.845 725.446 264.322 736.93C285.995 745.671 308.405 751.992 331.435 756.395C351.372 760.207 371.444 762.575 391.624 762.76C408.753 762.917 425.949 761.495 443.026 759.849C455.825 758.616 468.607 756.476 481.169 753.71C493.129 751.076 505.142 747.992 516.511 743.526C535.685 735.993 554.695 727.871 573.14 718.718C585.053 712.807 596.309 705.253 607.008 697.293C621.575 686.456 635.958 675.203 649.249 662.867C661.074 651.891 671.912 639.687 682.068 627.122C691.778 615.107 700.441 602.182 708.816 589.175C714.523 580.311 718.865 570.575 723.953 561.303C733.225 544.408 740.069 526.445 745.663 508.137C750.172 493.38 753.493 478.139 755.873 462.884C758.728 444.583 760.801 426.078 761.737 407.587C762.411 394.283 761.177 380.807 759.863 367.499C758.483 353.516 757.101 339.368 753.728 325.787C748.678 305.458 743.234 285.02 735.456 265.632C727.77 246.471 717.777 228.085 707.286 210.247C699.474 196.964 689.256 185.096 680.103 172.603C678.053 169.804 674.5 168.589 672.478 170.677C671.083 172.117 671.279 176.826 672.611 178.871C677.761 186.782 683.852 194.072 689.231 201.844C707.062 227.611 721.75 255.129 731.674 284.829C737.335 301.773 741.041 319.409 744.972 336.881C749.578 357.351 751.241 378.219 750.916 399.177C750.724 411.555 749.996 423.949 748.914 436.283C747.971 447.042 746.871 457.871 744.643 468.416C740.206 489.414 735.223 510.307 726.069 529.931C720.316 542.264 715.521 555.086 709.132 567.068C702.808 578.931 695.753 590.562 687.699 601.306C676.836 615.798 664.941 629.545 653.036 643.218C646.709 650.486 639.712 657.243 632.504 663.653C623.934 671.275 614.812 678.276 605.307 685.932Z\" fill=\"white\"><\/path><path d=\"M381.296 361.724C388.409 368.732 386.665 368.714 393.552 361.855C407.721 347.744 421.629 333.361 436.116 319.586C440.183 315.718 441.018 312.045 439.948 307.133C437.462 295.726 438.917 284.453 442.338 273.579C445.892 262.283 451.897 252.283 460.539 243.865C473.161 231.571 488.477 225.128 505.605 223.325C515.754 222.257 525.943 224.247 535.806 227.056C541.34 228.632 542.606 235.755 538.147 240.296C530.326 248.262 522.316 256.044 514.519 264.033C511.463 267.165 509.04 270.404 508.78 275.441C508.44 282.024 510.047 287.051 515.382 290.899C516.451 291.67 517.591 292.585 518.205 293.705C522.613 301.745 529.853 301.132 537.177 299.894C538.61 299.652 540.018 298.384 541.133 297.282C549.784 288.731 558.419 280.163 566.925 271.468C569.581 268.754 572.887 266.665 576.111 268.35C578.944 269.831 581.883 272.961 582.786 275.961C586.48 288.226 587.382 300.952 583.838 313.319C579.056 330.001 570.938 344.778 556.321 355.251C546.893 362.006 536.548 366.962 525.244 368.57C516.419 369.824 507.227 369.132 498.265 368.439C495.09 368.193 493.066 368.416 490.886 370.62C478.932 382.703 466.996 394.808 454.79 406.633C451.513 409.807 451.561 411.91 454.983 414.512C456.794 415.889 458.457 417.463 460.156 418.921C467.772 412.421 471.772 411.51 475.709 415.207C479.509 418.775 478.706 423.286 472.708 430.226C480.07 437.243 487.39 444.361 494.871 451.306C501.159 457.145 507.695 462.718 514.015 468.524C523.509 477.245 532.855 486.13 542.368 494.831C552.463 504.063 563.115 512.727 572.755 522.405C596.815 546.557 585.597 585.915 554.544 595.718C536.381 601.452 514.753 593.451 503.81 577.848C500.327 572.882 495.813 568.622 491.638 564.163C480.884 552.681 469.992 541.328 459.274 529.813C447.792 517.477 436.427 505.032 425.057 492.592C422.761 490.08 420.672 487.379 418.505 484.786C411.468 490.106 406.461 491.098 403.509 488.007C399.35 483.652 400.098 480.024 406.716 472.444C403.833 469.338 400.952 466.232 398.279 463.35C385.82 475.791 373.571 488.417 360.824 500.519C356.83 504.311 355.9 507.774 356.964 512.972C359.278 524.279 357.971 535.315 354.457 546.44C350.318 559.546 343.196 570.429 333.067 579.309C323.922 587.327 313.522 593.377 301.152 594.961C294 595.876 286.779 596.944 279.61 596.809C273.649 596.697 267.583 595.411 261.814 593.766C255.277 591.902 253.664 584.958 258.426 580.097C267.984 570.343 277.765 560.807 287.432 551.16C288.045 550.548 288.904 549.76 288.92 549.037C289.062 542.849 290.217 536.432 283.685 532.105C280.962 530.301 278.644 527.692 276.612 525.083C273.341 520.882 269.339 519.632 264.107 519.836C260.177 519.988 257.349 520.913 254.574 523.817C246.288 532.489 237.675 540.849 229.177 549.318C223.079 555.395 217.491 553.686 214.735 545.54C208.392 526.797 210.395 508.536 218.599 491.156C224.744 478.138 234.489 467.879 247.434 460.775C259.98 453.891 273.05 449.899 287.454 451.015C289.084 451.141 290.696 451.483 292.324 451.651C298.251 452.266 303.498 452.599 308.473 447.265C321.424 433.382 335.162 420.233 348.627 406.832C350.939 404.531 353.451 402.432 356.164 399.975C355.085 398.793 354.045 397.56 352.908 396.423C325.461 368.961 298.041 341.47 270.456 314.147C268.716 312.423 265.687 311.972 263.218 311.031C262.637 310.809 261.877 310.889 261.234 311.014C249.002 313.382 242.233 307.308 236.769 296.96C229.698 283.569 221.282 270.887 213.411 257.921C210.157 252.559 210.532 247.857 215.106 243.384C221.265 237.362 227.27 231.086 234.073 225.875C236.402 224.092 241.741 223.752 244.333 225.203C260.785 234.413 276.898 244.236 293.013 254.037C296.708 256.284 299.96 259.183 299.015 264.405C297.063 275.202 301.569 282.761 309.429 290.282C333.744 313.548 357.233 337.679 381.296 361.724ZM302.897 530.727C302.907 539.622 302.918 548.516 302.976 558.066C295.452 565.859 287.928 573.653 279.334 582.556C284.808 581.924 288.705 581.333 292.625 581.046C310.091 579.766 322.767 569.783 332.369 556.644C343.222 541.794 345.522 524.528 339.955 506.702C338.555 502.219 339.501 498.94 342.74 495.707C388.975 449.558 435.226 403.425 481.239 357.055C486.271 351.985 490.916 350.255 497.646 352.745C507.748 356.482 518.244 355.105 528.041 352.192C542.664 347.845 554.279 338.924 562.162 325.401C568.282 314.904 570.874 303.849 569.791 291.737C562.504 299.017 555.514 306.1 548.372 313.027C547.28 314.087 545.491 314.428 543.087 315.028C535.05 315.061 527.013 315.095 518.283 315.005C513.705 310.696 509.094 306.423 504.557 302.072C497.225 295.044 491.506 287.438 493.892 276.24C494.605 272.893 493.738 269.238 494.101 265.778C494.304 263.846 495.088 261.579 496.398 260.226C503.093 253.311 510.044 246.645 517.549 239.259C509.176 236.485 501.795 238.797 495.168 240.816C486.72 243.391 478.431 247.637 472.65 254.894C467.511 261.343 461.487 267.627 458.39 275.043C453.286 287.267 452.284 300.427 457.051 313.344C458.868 318.27 457.042 321.586 453.548 325.068C406.926 371.522 360.364 418.036 313.964 464.711C309.752 468.948 305.775 469.801 300.298 468.2C290.832 465.432 280.967 464.624 271.51 467.392C249.441 473.851 234.307 487.876 228.384 510.521C226.907 516.164 227.162 522.261 226.553 528.898C234.32 521.152 240.982 514.168 248.082 507.66C249.893 505.999 253.056 505.264 255.655 505.118C261.966 504.762 268.321 504.809 274.638 505.112C276.753 505.213 279.328 506.039 280.803 507.458C288.351 514.725 295.608 522.293 302.897 530.727ZM497.011 547.519C505.095 556.243 513.025 565.115 521.304 573.649C529.654 582.256 539.608 584.559 550.944 580.053C571.026 572.073 576.83 547.512 561.628 533.22C550.332 522.598 538.686 512.35 527.294 501.83C512.969 488.601 498.768 475.239 484.464 461.987C476.886 454.967 469.204 448.058 461.418 440.961C451.651 450.775 442.238 460.435 432.574 469.836C429.226 473.092 429.674 475.235 432.762 478.408C440.125 485.974 447.042 493.972 454.232 501.71C468.293 516.841 482.418 531.915 497.011 547.519ZM304.536 325.964C325.168 347.115 345.799 368.266 366.936 389.935C370.418 385.911 373.37 382.501 376.846 378.485C375.001 376.989 373.462 375.952 372.172 374.664C346.598 349.136 321.331 323.291 295.343 298.192C286.797 289.937 280.982 281.689 282.818 269.317C283.056 267.713 281.211 265.174 279.632 264.047C275.396 261.022 270.795 258.504 266.312 255.831C257.82 250.768 249.309 245.737 241.542 241.13C236.969 245.405 232.984 249.129 228.734 253.102C235.027 263.471 242.207 273.336 247.252 284.193C251.854 294.095 258.111 297.996 268.563 296.032C272.877 295.222 276.042 297.274 279.007 300.335C287.232 308.826 295.678 317.103 304.536 325.964ZM422.513 439.052C421.097 440.147 419.715 441.288 418.261 442.328C408.059 449.626 407.933 452.749 417.566 460.779C417.67 460.866 417.88 460.825 417.421 460.772C427.986 450.21 438.276 439.922 448.942 429.259C446.162 426.947 443.08 424.386 439.683 421.563C433.951 427.409 428.486 432.983 422.513 439.052Z\" fill=\"#04A9AC\"><\/path><path d=\"M605.619 685.739C614.812 678.276 623.934 671.275 632.504 663.654C639.712 657.243 646.709 650.486 653.036 643.218C664.941 629.545 676.836 615.798 687.699 601.306C695.753 590.562 702.808 578.931 709.133 567.068C715.521 555.086 720.316 542.264 726.069 529.931C735.223 510.307 740.206 489.414 744.643 468.416C746.871 457.871 747.971 447.042 748.914 436.283C749.996 423.949 750.724 411.555 750.916 399.177C751.241 378.219 749.578 357.351 744.972 336.881C741.041 319.409 737.335 301.773 731.674 284.829C721.75 255.129 707.062 227.611 689.231 201.844C683.853 194.072 677.761 186.782 672.611 178.872C671.279 176.826 671.083 172.117 672.478 170.677C674.5 168.589 678.053 169.804 680.103 172.603C689.256 185.096 699.474 196.964 707.286 210.247C717.777 228.085 727.77 246.471 735.457 265.632C743.234 285.02 748.678 305.458 753.728 325.787C757.101 339.368 758.483 353.517 759.863 367.499C761.177 380.807 762.411 394.283 761.737 407.587C760.801 426.078 758.728 444.583 755.873 462.884C753.493 478.139 750.172 493.38 745.663 508.137C740.069 526.445 733.225 544.408 723.953 561.304C718.865 570.575 714.523 580.311 708.816 589.175C700.441 602.182 691.778 615.108 682.068 627.122C671.912 639.687 661.074 651.891 649.249 662.867C635.958 675.203 621.576 686.456 607.008 697.293C596.309 705.254 585.053 712.807 573.14 718.718C554.695 727.871 535.685 735.993 516.511 743.526C505.142 747.992 493.129 751.076 481.169 753.71C468.607 756.476 455.825 758.616 443.026 759.85C425.949 761.495 408.753 762.917 391.624 762.76C371.444 762.575 351.372 760.207 331.435 756.395C308.405 751.992 285.995 745.671 264.322 736.931C235.845 725.446 209.22 710.561 184.529 692.165C168.089 679.917 152.505 666.753 138.429 651.882C118.335 630.653 99.9803 607.975 86.1632 582.122C76.9578 564.898 67.8443 547.413 61.0635 529.163C53.8942 509.867 48.7824 489.699 44.175 469.59C39.8453 450.693 37.6685 431.355 37.9648 411.836C38.1525 399.467 37.2159 387.032 38.1546 374.731C40.8636 339.23 48.6845 304.798 61.1282 271.385C68.8556 250.636 78.3362 230.734 90.1465 212.096C99.4902 197.351 109.623 183.013 120.485 169.353C129.369 158.182 139.268 147.651 149.774 137.984C161.205 127.466 173.775 118.171 185.994 108.526C203.794 94.4753 223.262 83.0152 243.884 73.7791C258.865 67.0698 274.275 61.1026 289.919 56.1487C306.318 50.9557 323.122 46.8855 339.951 43.2634C349.525 41.2028 359.482 40.6451 369.304 40.0865C381.909 39.3698 394.562 38.8748 407.177 39.1381C418.527 39.375 429.849 40.8194 441.19 41.6345C461.487 43.0931 481.253 47.606 500.67 53.2247C515.157 57.4169 529.298 63.0068 543.248 68.8034C563.452 77.1983 582.59 87.7046 600.851 99.8237C604.279 102.098 605.227 105.222 603.353 107.585C601.693 109.678 598.404 110.724 594.723 108.539C579.542 99.5309 564.491 90.1369 548.613 82.5069C522.815 70.1097 495.805 60.6735 467.431 56.0879C450.938 53.4226 434.276 51.6712 417.634 50.1096C407.424 49.1516 397.075 48.6754 386.845 49.1666C374.57 49.7561 362.347 51.5321 350.117 52.9353C342.319 53.83 334.436 54.459 326.797 56.144C316.532 58.4084 306.376 61.2907 296.341 64.4427C287.493 67.2219 278.855 70.682 270.16 73.9357C250.581 81.2622 232.172 90.8893 214.477 101.995C196.693 113.158 180.219 125.923 164.496 139.858C144.751 157.359 127.197 176.772 112.456 198.507C101.706 214.357 91.8778 230.942 82.9844 247.905C76.7589 259.78 72.8202 272.851 67.8317 285.377C60.9783 302.585 56.977 320.563 53.7312 338.707C52.0887 347.889 50.8132 357.177 50.0885 366.473C49.0482 379.815 47.9005 393.223 48.1514 406.577C48.7289 437.323 52.9291 467.592 61.5374 497.246C68.338 520.673 77.0759 543.267 88.431 564.82C98.7156 584.343 110.358 603.089 124.652 619.917C136.195 633.505 148.174 646.829 160.987 659.206C178.048 675.686 197.433 689.362 217.588 701.888C242.507 717.373 269.137 729.185 297.215 737.404C312.498 741.878 328.274 744.733 343.909 747.92C352.585 749.688 361.389 751.121 370.205 751.827C381.059 752.695 391.994 753.058 402.881 752.884C414.529 752.697 426.231 752.191 437.785 750.791C449.572 749.362 461.214 746.717 472.906 744.534C492.155 740.941 510.908 735.361 528.854 727.741C544.932 720.914 560.488 712.753 575.875 704.442C586.05 698.947 595.521 692.148 605.619 685.739Z\" fill=\"#04A9AC\"><\/path><path d=\"M544.026 315.102C545.492 314.428 547.281 314.087 548.373 313.027C555.514 306.1 562.505 299.017 569.792 291.737C570.875 303.849 568.283 314.904 562.163 325.401C554.28 338.924 542.665 347.845 528.042 352.192C518.244 355.105 507.749 356.482 497.647 352.745C490.916 350.255 486.272 351.985 481.24 357.055C435.227 403.425 388.976 449.558 342.741 495.707C339.502 498.94 338.556 502.219 339.956 506.702C345.523 524.528 343.223 541.794 332.37 556.644C322.768 569.783 310.092 579.766 292.625 581.046C288.706 581.333 284.809 581.924 279.334 582.556C287.929 573.653 295.453 565.859 303.346 557.482C303.809 548.829 303.937 540.761 303.947 532.692C303.948 531.714 303.31 530.735 302.968 529.756C295.609 522.293 288.352 514.725 280.803 507.458C279.329 506.039 276.754 505.213 274.639 505.112C268.322 504.809 261.967 504.762 255.656 505.118C253.057 505.264 249.894 505.999 248.082 507.66C240.983 514.168 234.32 521.152 226.554 528.898C227.163 522.261 226.908 516.164 228.384 510.52C234.308 487.876 249.442 473.851 271.511 467.392C280.968 464.624 290.833 465.432 300.299 468.2C305.776 469.801 309.753 468.948 313.965 464.711C360.365 418.036 406.927 371.522 453.549 325.068C457.043 321.586 458.869 318.27 457.052 313.344C452.285 300.427 453.287 287.267 458.391 275.043C461.488 267.627 467.512 261.343 472.651 254.894C478.432 247.637 486.721 243.391 495.169 240.816C501.796 238.797 509.177 236.485 517.55 239.259C510.044 246.645 503.093 253.311 496.399 260.226C495.089 261.579 494.305 263.846 494.102 265.778C493.739 269.238 494.606 272.893 493.893 276.24C491.507 287.438 497.226 295.044 504.558 302.072C509.095 306.423 513.706 310.696 518.842 315.445C523.496 315.923 527.596 316.092 531.687 315.962C535.805 315.83 539.913 315.401 544.026 315.102ZM423.459 373.959C422.047 375.372 420.634 376.785 419.222 378.198C395.679 401.738 372.158 425.3 348.566 448.791C345.768 451.577 343.726 454.86 345.437 458.41C346.494 460.602 349.651 463.032 351.907 463.074C354.631 463.124 358.01 461.376 360.057 459.347C389.618 430.056 419.006 400.59 448.426 371.156C452.375 367.206 453.132 362.814 450.442 359.908C446.721 355.887 441.384 356.058 437.018 360.388C432.645 364.724 428.311 369.1 423.459 373.959ZM335.725 483.751C336.562 482.944 337.674 482.28 338.185 481.302C339.793 478.226 341.168 474.986 338.305 471.859C335.46 468.751 330.027 467.942 327.09 470.422C324.039 472.997 323.362 476.493 325.099 480.073C327.112 484.222 331.04 484.205 335.725 483.751ZM470.403 338.934C465.244 336.034 460.404 336.051 458.432 339.19C456.208 342.73 456.249 346.349 459.125 349.561C461.558 352.278 466.566 352.582 469.595 349.705C472.529 346.919 473.687 343.307 470.403 338.934Z\" fill=\"white\"><\/path><path d=\"M496.764 547.266C482.418 531.914 468.294 516.841 454.233 501.709C447.042 493.972 440.125 485.973 432.762 478.407C429.675 475.235 429.226 473.092 432.574 469.836C442.238 460.435 451.652 450.775 461.418 440.961C469.205 448.058 476.887 454.966 484.465 461.987C498.768 475.238 512.969 488.601 527.294 501.829C538.687 512.349 550.332 522.598 561.628 533.219C576.83 547.512 571.026 572.072 550.944 580.053C539.608 584.558 529.654 582.256 521.304 573.649C513.025 565.115 505.095 556.243 496.764 547.266ZM471.201 475.01C467.632 474.737 464.426 475.549 463.35 479.335C462.262 483.161 463.014 486.643 466.121 489.686C487.601 510.717 508.978 531.853 530.388 552.954C530.743 553.304 531.074 553.683 531.461 553.992C535.885 557.537 541.252 555.684 543.351 550.333C545.311 545.335 542.114 542.608 539.307 539.784C520.071 520.435 500.801 501.118 481.399 481.936C478.667 479.235 475.158 477.321 471.201 475.01Z\" fill=\"white\"><\/path><path d=\"M304.287 325.714C295.678 317.103 287.233 308.826 279.008 300.335C276.043 297.274 272.877 295.222 268.564 296.032C258.112 297.996 251.855 294.095 247.253 284.193C242.208 273.336 235.028 263.471 228.734 253.102C232.985 249.129 236.97 245.405 241.543 241.13C249.309 245.737 257.821 250.768 266.312 255.831C270.796 258.504 275.397 261.022 279.633 264.047C281.212 265.174 283.057 267.713 282.819 269.317C280.983 281.689 286.797 289.937 295.344 298.192C321.332 323.291 346.599 349.136 372.173 374.664C373.463 375.951 375.002 376.989 376.847 378.485C373.371 382.501 370.419 385.911 366.937 389.935C345.8 368.266 325.168 347.115 304.287 325.714Z\" fill=\"white\"><\/path><path d=\"M422.767 438.804C428.486 432.982 433.951 427.409 439.683 421.563C443.08 424.386 446.162 426.947 448.943 429.258C438.277 439.922 427.986 450.209 417.421 460.771C417.881 460.825 417.67 460.866 417.566 460.779C407.934 452.749 408.059 449.625 418.262 442.328C419.716 441.288 421.098 440.146 422.767 438.804Z\" fill=\"white\"><\/path><path d=\"M302.933 530.241C303.31 530.735 303.948 531.714 303.946 532.692C303.937 540.761 303.808 548.829 303.323 557.154C302.918 548.516 302.908 539.621 302.933 530.241Z\" fill=\"#6CC1C3\"><\/path><path d=\"M543.557 315.065C539.913 315.401 535.805 315.83 531.687 315.962C527.596 316.092 523.496 315.923 519.188 315.507C527.014 315.095 535.051 315.061 543.557 315.065Z\" fill=\"#CCE9E9\"><\/path><path d=\"M423.709 373.709C428.311 369.1 432.644 364.724 437.018 360.388C441.384 356.058 446.721 355.887 450.442 359.908C453.132 362.814 452.374 367.206 448.426 371.156C419.006 400.59 389.618 430.056 360.057 459.347C358.01 461.376 354.631 463.124 351.907 463.074C349.651 463.032 346.494 460.602 345.437 458.41C343.726 454.86 345.768 451.577 348.566 448.791C372.158 425.3 395.679 401.738 419.222 378.198C420.634 376.785 422.047 375.372 423.709 373.709Z\" fill=\"#F3AA31\"><\/path><path d=\"M335.329 483.858C331.04 484.205 327.112 484.222 325.099 480.073C323.361 476.493 324.038 472.997 327.089 470.422C330.027 467.942 335.46 468.751 338.304 471.858C341.168 474.986 339.793 478.226 338.185 481.302C337.673 482.28 336.562 482.944 335.329 483.858Z\" fill=\"#F2A82B\"><\/path><path d=\"M470.69 339.202C473.686 343.307 472.528 346.919 469.595 349.705C466.566 352.581 461.557 352.278 459.124 349.561C456.248 346.348 456.208 342.73 458.432 339.19C460.403 336.051 465.243 336.034 470.69 339.202Z\" fill=\"#F2A82A\"><\/path><path d=\"M471.605 475.026C475.158 477.321 478.667 479.235 481.399 481.936C500.801 501.118 520.071 520.435 539.306 539.784C542.113 542.608 545.31 545.335 543.35 550.333C541.252 555.684 535.885 557.537 531.461 553.993C531.074 553.683 530.742 553.304 530.388 552.954C508.978 531.853 487.601 510.717 466.121 489.686C463.014 486.643 462.262 483.161 463.35 479.335C464.426 475.549 467.632 474.737 471.605 475.026Z\" fill=\"#F2A92E\"><\/path><\/g><defs><clipPath id=\"clip0_1427_3798\"><rect width=\"800\" height=\"800\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tMaintenance\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<span style=\"font-family: &quot;Open Sans&quot;, sans-serif;font-size: 16px;font-style: normal;font-weight: 600\">B\u00e9n\u00e9ficiez d'un service support, d'un entretien pr\u00e9ventif annuel et d'un d\u00e9pannage 24\/7.<\/span>\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<aside class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0576f9d\" data-id=\"0576f9d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16c3a82 elementor-hidden-mobile elementor-invisible elementor-widget elementor-widget-image\" data-id=\"16c3a82\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.5,&quot;sizes&quot;:[]},&quot;_animation&quot;:&quot;slideInRight&quot;,&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1384\" height=\"1239\" src=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/04\/Frame-1274.png\" class=\"attachment-2048x2048 size-2048x2048 wp-image-12090\" alt=\"Analyse, Installation et Gestion de borne de recharge\" srcset=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/04\/Frame-1274.png 1384w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/04\/Frame-1274-300x269.png 300w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/04\/Frame-1274-1024x917.png 1024w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/04\/Frame-1274-768x688.png 768w\" sizes=\"(max-width: 1384px) 100vw, 1384px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f55c1fc elementor-hidden-desktop elementor-hidden-tablet elementor-invisible elementor-widget elementor-widget-image\" data-id=\"f55c1fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInRight&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1384\" height=\"1239\" src=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/04\/Frame-1274.png\" class=\"attachment-2048x2048 size-2048x2048 wp-image-12090\" alt=\"Analyse, Installation et Gestion de borne de recharge\" srcset=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/04\/Frame-1274.png 1384w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/04\/Frame-1274-300x269.png 300w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/04\/Frame-1274-1024x917.png 1024w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/04\/Frame-1274-768x688.png 768w\" sizes=\"(max-width: 1384px) 100vw, 1384px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/aside>\n\t\t\t\t\t<\/div>\n\t\t<\/main>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-df549f6 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"df549f6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-323e34e\" data-id=\"323e34e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c780a85 elementor-widget elementor-widget-heading\" data-id=\"c780a85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"color:#061360\">4 bonnes raisons d'installer <\/span>des bornes de recharge dans votre h\u00f4tel<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a93534b elementor-widget elementor-widget-text-editor\" data-id=\"a93534b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Avec une client\u00e8le de plus en plus soucieuse de l&rsquo;environnement, proposer des bornes de recharge pour v\u00e9hicules \u00e9lectriques renforce l&rsquo;image \u00e9cologique de votre h\u00f4tel et r\u00e9pond aux attentes de vos clients. De plus, cela peut vous permettre d&rsquo;attirer une nouvelle client\u00e8le, toujours \u00e0 la recherche d&rsquo;\u00e9tablissements \u00e9co-responsables.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<main class=\"elementor-section elementor-top-section elementor-element elementor-element-6d8d42c elementor-section-content-middle elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"6d8d42c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5702d53\" data-id=\"5702d53\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;animation&quot;:&quot;none&quot;,&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0579387 elementor-widget__width-initial elementor-hidden-mobile elementor-invisible elementor-widget elementor-widget-image\" data-id=\"0579387\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInLeft&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/04\/Style-@workplace-B2B-Corporate-Fleet-LD-1.jpg\" class=\"attachment-large size-large wp-image-12326\" alt=\"Un homme qui passe ca carte Total sur une borne \u00e9lectrique\" srcset=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/04\/Style-@workplace-B2B-Corporate-Fleet-LD-1.jpg 1000w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/04\/Style-@workplace-B2B-Corporate-Fleet-LD-1-300x200.jpg 300w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/04\/Style-@workplace-B2B-Corporate-Fleet-LD-1-768x512.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-11c5b08\" data-id=\"11c5b08\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;animation&quot;:&quot;none&quot;,&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0e895a3 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"0e895a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPermettre \u00e0 vos employ\u00e9s et clients de passer \u00e0 la mobilit\u00e9 verte\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-db1b278 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"db1b278\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tR\u00e9pondre aux besoins de vos employ\u00e9s et clients qui utilisent d\u00e9j\u00e0 des voitures \u00e9lectriques.\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69e6f97 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"69e6f97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tR\u00e9duisez l'empreinte carbone de votre hotel : la recharge \u00e9lectrique co\u00fbte 3 fois moins cher que l\u2019essence et est majoritairement d\u00e9carbon\u00e9e en France.\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-224cd12 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"224cd12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPour respecter la l\u00e9gislation, il est obligatoire que 10% des places de parking soient \u00e9quip\u00e9es d'ici d\u00e9but 2025, comme l'exige <u><a href=\"https:\/\/chargeplus.totalenergies.com\/fr\/conseils-recharge-electrique\/loi-lom-reglemente-utilisation-borne-de-recharge\/\"> la Loi LOM<\/a><\/u>.\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/main>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-342b55d elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default\" data-id=\"342b55d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6870708\" data-id=\"6870708\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-564c8e1 elementor-align-center elementor-widget__width-inherit elementor-widget elementor-widget-button\" data-id=\"564c8e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/solutions-recharge\/parking?type=public\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Demander une simulation<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-195d5b8 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"195d5b8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-36675af\" data-id=\"36675af\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d30585f elementor-widget elementor-widget-heading\" data-id=\"d30585f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"color:#061360\">Pourquoi choisir  <\/span> Time2plug ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<main class=\"elementor-section elementor-top-section elementor-element elementor-element-fa99d42 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"fa99d42\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<article class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-1e1b71b\" data-id=\"1e1b71b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d49cee6 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"d49cee6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eci  fontello-db675071-licence\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tUne communaut\u00e9 d'installateurs certifi\u00e9s IRVE\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-f0337c7\" data-id=\"f0337c7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bcb24f3 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"bcb24f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eci  fontello-8aa67364-charging\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDes \u00e9quipements fiables et de qualit\u00e9\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-be795fe\" data-id=\"be795fe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-081b981 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"081b981\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eci  fontello-8aa67364-electric-car\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tUn outil de gestion et de supervision adapt\u00e9\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-97285c4\" data-id=\"97285c4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c1173a elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"4c1173a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eci  fontello-8aa67364-fast-charge\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tUn service de t\u00e9l\u00e9maintenance 24\/7\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-dc3d8e0\" data-id=\"dc3d8e0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8378122 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"8378122\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eci  fontello-7a022cde-carte-france-time2plug\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tUne couverture  nationale pour \u00e9quiper tous vos sites\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t\t<\/div>\n\t\t<\/main>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-e862690 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e862690\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8223a9d\" data-id=\"8223a9d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d12a537 elementor-widget elementor-widget-heading\" data-id=\"d12a537\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"> <span style=\"color:#061360\">Des partenaires  <\/span>renomm\u00e9s <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<main class=\"elementor-section elementor-top-section elementor-element elementor-element-6680258 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6680258\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8a46bf2\" data-id=\"8a46bf2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-94a4576 elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"94a4576\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;6&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:70,&quot;sizes&quot;:[]},&quot;pause_on_hover&quot;:&quot;no&quot;,&quot;pause_on_interaction&quot;:&quot;no&quot;,&quot;autoplay_speed&quot;:800,&quot;speed&quot;:800,&quot;navigation&quot;:&quot;dots&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel d\u2019images\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2022\/10\/logos-partenaires-time2plug-stationf-couleur-150x150.jpg\" alt=\"logo Station F, incubateur Start up, partenaire Time2plug\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 sur 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2022\/10\/logos-partenaires-time2plug-bpi-couleur-150x150.jpg\" alt=\"BPiFrance, partenaire Time2plug\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 sur 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2022\/10\/logos-partenaires-time2plug-alliances-des-mobilites-couleur-150x150.jpg\" alt=\"Alliance des mobilit\u00e9s, partenaire Time2plug\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 sur 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2022\/10\/logos-partenaires-time2plug-rexel-couleur-150x150.jpg\" alt=\"Rexel, partenaire Time2plug\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 sur 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2022\/10\/logos-partenaires-time2plug-total-couleur-150x150.jpg\" alt=\"Total energies, partenaire Time2plug\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 sur 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2022\/11\/logos-partenaires-time2plug-avere-150x150.jpg\" alt=\"Logo Avere\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 sur 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/03\/greenly-logo-150x150.jpg\" alt=\"Logo de Greenly\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 sur 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/03\/Schneider-logo-150x150.jpg\" alt=\"Logo de Schneider Electric\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 sur 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/03\/logo-sofida-150x150.jpg\" alt=\"Logo du groupe Sofida\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 sur 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/03\/CDC-logo-1-150x150.jpg\" alt=\"Logo CDC\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/main>\n\t\t\t\t<main class=\"elementor-section elementor-top-section elementor-element elementor-element-d09ae9d elementor-section-full_width elementor-section-stretched elementor-hidden-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"d09ae9d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b1cd439\" data-id=\"b1cd439\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ebedb71 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"ebedb71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La r\u00e9glementation pour les h\u00f4tels<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17696c9 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"17696c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00c0 partir de 2035, l&rsquo;Union europ\u00e9enne interdira la vente de voitures neuves \u00e9quip\u00e9es de moteurs thermiques. D\u00e8s lors, seuls les v\u00e9hicules neufs 100 % \u00e9lectriques seront autoris\u00e9s \u00e0 la vente, une d\u00e9cision vot\u00e9e par le Parlement europ\u00e9en le 8 juin 2022. Parall\u00e8lement \u00e0 cette \u00e9volution, la Loi d&rsquo;Orientation des Mobilit\u00e9s (LOM), promulgu\u00e9e le 26 d\u00e9cembre 2019, renforce la transition vers la mobilit\u00e9 \u00e9lectrique.<\/p><p>Selon la LOM, d&rsquo;une part, les b\u00e2timents non r\u00e9sidentiels dot\u00e9s d&rsquo;un parking de plus de vingt places doivent \u00eatre \u00e9quip\u00e9s d&rsquo;au moins un point de recharge pour v\u00e9hicules \u00e9lectriques et hybrides d&rsquo;ici le 1er janvier 2025. D&rsquo;autre part, depuis 2017, l&rsquo;intervention d&rsquo;un technicien certifi\u00e9 IRVE est obligatoire pour l&rsquo;installation de bornes de recharge d\u00e9livrant une puissance sup\u00e9rieure ou \u00e9gale \u00e0 3,7 kW en courant alternatif.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac6c22a elementor-align-left elementor-widget__width-inherit elementor-widget elementor-widget-button\" data-id=\"ac6c22a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.ecologie.gouv.fr\/loi-dorientation-des-mobilites\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">D\u00e9couvrir<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/main>\n\t\t\t\t<main class=\"elementor-section elementor-top-section elementor-element elementor-element-cb945c9 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"cb945c9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e3b3de0\" data-id=\"e3b3de0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b1f78f3 elementor-widget elementor-widget-heading\" data-id=\"b1f78f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FAQ<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e9532d7 elementor-widget elementor-widget-toggle\" data-id=\"e9532d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2441\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2441\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quelles bornes de recharge choisir pour un h\u00f4tel?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2441\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2441\"><p>L&rsquo;installation d&rsquo;une borne de recharge dans un h\u00f4tel attire une fr\u00e9quence d&rsquo;utilisation \u00e9lev\u00e9e. Il est donc essentiel de choisir un mat\u00e9riel de qualit\u00e9, issu de grandes marques reconnues pour garantir fiabilit\u00e9 et durabilit\u00e9. De plus, il est crucial de collaborer avec un op\u00e9rateur capable de g\u00e9rer les acc\u00e8s, la maintenance, ainsi que la consommation et la facturation.<\/p><p>Pour accueillir du public, que ce soit en haute ou en basse saison, il est recommand\u00e9 d&rsquo;opter pour des bornes 22kW. Ces bornes permettent un rechargement rapide, atteignant jusqu&rsquo;\u00e0 130km\/h. De plus, un syst\u00e8me de supervision avanc\u00e9 est n\u00e9cessaire pour g\u00e9rer efficacement les flux \u00e9nerg\u00e9tiques et mon\u00e9tiques.<\/p><h6>Si votre objectif est simplement de proposer la recharge \u00e0 vos clients, une borne 7kW est suffisante. Cette borne offre un rechargement \u00e0 40 km\/h, permettant une recharge compl\u00e8te de la batterie pendant la nuit.<\/h6><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2442\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2442\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Qui peut poser des bornes de recharge?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2442\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2442\"><p>Le professionnel en charge du pr\u00e9-\u00e9quipement ou de l&rsquo;installation de la borne de recharge dans un h\u00f4tel doit poss\u00e9der la qualification IRVE, reconnue par un organisme accr\u00e9dit\u00e9.<\/p><p>Cette qualification est exig\u00e9e par le programme ADVENIR.<\/p><h6>Deux organismes sont habilit\u00e9s \u00e0 d\u00e9livrer cette qualification : Qualifec et l&rsquo;AFNOR (Association Fran\u00e7aise de Normalisation).<\/h6><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2443\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2443\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Comment les bornes de recharge peuvent-elles aider \u00e0 toucher une client\u00e8le plus large ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2443\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2443\"><p>La pr\u00e9sence de bornes de recharge renforce votre visibilit\u00e9 non seulement sur les sites de r\u00e9servation, mais aussi sur les \u00ab\u00a0<span style=\"text-decoration: underline;\"><a href=\"https:\/\/fr.chargemap.com\/map\">charge maps<\/a><\/span>\u00ab\u00a0, fr\u00e9quent\u00e9es par de nombreux utilisateurs de v\u00e9hicules \u00e9lectriques. De plus, cela positionne votre \u00e9tablissement comme \u00e9tant en phase avec les tendances \u00e9cologiques actuelles, attirant ainsi les clients soucieux de l&rsquo;environnement.\u00a0<\/p><h6>C&rsquo;est \u00e9galement un excellent moyen de fid\u00e9liser votre client\u00e8le existante en leur offrant un service pratique et moderne.<\/h6><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2444\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2444\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Comment peut-on mettre en place une refacturation pour la recharge des bornes \u00e9lectriques \u00e0 ses clients ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2444\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2444\"><p>Avec un suivi pr\u00e9cis des charges gr\u00e2ce \u00e0 un outil de supervision, vous pouvez facilement refacturer vos clients. Plusieurs mod\u00e8les de tarification sont envisageables :<\/p><ul><li style=\"list-style-type: none;\"><ul><li><span style=\"text-decoration: underline;\"><strong>Au forfait :<\/strong><\/span> offrez un tarif bas\u00e9 sur la dur\u00e9e de la recharge, que ce soit pour 1 heure, 2 heures ou une recharge nocturne.<\/li><li><span style=\"text-decoration: underline;\"><strong>\u00c0 la consommation :<\/strong><\/span> ajoutez une marge sur l&rsquo;\u00e9nergie fournie au v\u00e9hicule \u00e9lectrique, refl\u00e9tant ainsi la quantit\u00e9 d&rsquo;\u00e9lectricit\u00e9 utilis\u00e9e.<\/li><\/ul><\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2445\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-2445\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Comment peut-on g\u00e9rer l'acc\u00e8s aux bornes de recharge sur son parking ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2445\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-2445\"><p>L&rsquo;acc\u00e8s aux bornes est soigneusement g\u00e9r\u00e9 par un outil de supervision utilisant des <span style=\"text-decoration: underline;\"><a href=\"https:\/\/www.mooncard.co\/fr\/cas-usage\/flotte-auto\/voiture-electrique\/borne-recharge\/rfid\">badges RFID<\/a><\/span>. Ces cartes, configur\u00e9es lors de l&rsquo;installation, activent la charge et permettent de suivre pr\u00e9cis\u00e9ment la recharge de chaque client.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2446\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-2446\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quel est le co\u00fbt d'un contrat de supervision par an ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2446\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-2446\"><p>Le co\u00fbt d&rsquo;un forfait de supervision varie selon l&rsquo;op\u00e9rateur et le niveau de supervision choisi.<\/p><h6>Chez Time2plug, le forfait s&rsquo;\u00e9l\u00e8ve \u00e0 156\u20ac par point de charge pour les bornes priv\u00e9es et \u00e0 192\u20ac pour les bornes publiques.<\/h6><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2447\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-2447\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quel est le co\u00fbt d'un contrat de maintenance par an ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2447\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-2447\"><p>Le co\u00fbt de cette prestation peut varier en fonction de l&rsquo;op\u00e9rateur. Chez Time2plug, la maintenance est factur\u00e9e entre 50 et 100 euros par point de charge annuellement, selon la taille du site.<\/p><p>Un technicien IRVE est un \u00e9lectricien sp\u00e9cialement form\u00e9 en infrastructure de recharge pour v\u00e9hicules \u00e9lectriques. Contrairement \u00e0 d&rsquo;autres \u00e9lectriciens, tous ne suivent pas cette formation et n&rsquo;ont pas les comp\u00e9tences requises pour installer une borne de recharge en entreprise.<\/p><p>En faisant appel \u00e0 un technicien IRVE, vous garantissez une installation s\u00e9curis\u00e9e et une r\u00e9paration ad\u00e9quate en cas de panne.<\/p><h6>Il est \u00e9galement crucial d&rsquo;avoir un syst\u00e8me de supervision dans votre entreprise. Cela permet non seulement de maintenir les bornes \u00e0 jour mais aussi de d\u00e9tecter et r\u00e9soudre les pannes \u00e0 distance.<\/h6><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2448\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-2448\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quelle est la dur\u00e9e du projet, de la d\u00e9finition du besoin \u00e0 l'installation de la borne ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2448\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-2448\"><p>La r\u00e9alisation du projet est assez rapide, de la premi\u00e8re prise de contact \u00e0 la livraison de la solution cl\u00e9 en main.<\/p><p>Chez Time2plug, nous nous engageons \u00e0 vous fournir un devis complet en seulement 5 jours, en fonction de la d\u00e9finition de vos besoins. De plus, une fois l&rsquo;acompte re\u00e7u, l&rsquo;installation est r\u00e9alis\u00e9e en 10 jours.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2449\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"button\" aria-controls=\"elementor-tab-content-2449\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quelle est la dur\u00e9e de vie d'une borne de recharge ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2449\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"region\" aria-labelledby=\"elementor-tab-title-2449\"><p>Les bornes de recharge sont con\u00e7ues pour \u00eatre solides et durables, avec une esp\u00e9rance de vie d&rsquo;environ une dizaine d&rsquo;ann\u00e9es. Ce long\u00e9vit\u00e9 est en grande partie due \u00e0 l&rsquo;absence d&rsquo;obsolescence programm\u00e9e et \u00e0 l&rsquo;absence de composants m\u00e9caniques susceptibles de s&rsquo;user.<\/p><h6>Pour maximiser la dur\u00e9e de vie de vos bornes de recharge, voici quelques mesures recommand\u00e9es :<\/h6><ul><li>Contractez un contrat de maintenance avec votre installateur, m\u00eame au-del\u00e0 des 3 ans exig\u00e9s par Advenir.<\/li><li>Mettez en place un syst\u00e8me de supervision pour effectuer une maintenance pr\u00e9ventive.<\/li><li>Assurez une utilisation cadr\u00e9e de vos bornes gr\u00e2ce \u00e0 un contr\u00f4le d&rsquo;acc\u00e8s rigoureux, pr\u00e9venant ainsi les mauvaises utilisations.<\/li><li>Optez pour un partenaire de confiance comme Time2plug, qui vous propose des bornes de qualit\u00e9 install\u00e9es par des professionnels qualifi\u00e9s.<\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-24410\" class=\"elementor-tab-title\" data-tab=\"10\" role=\"button\" aria-controls=\"elementor-tab-content-24410\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">La technologie va-t-elle \u00e9voluer dans les ann\u00e9es \u00e0 venir ? Est-ce que les bornes que j'ach\u00e8te aujourd'hui deviendront obsol\u00e8tes rapidement ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-24410\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"10\" role=\"region\" aria-labelledby=\"elementor-tab-title-24410\"><p>Rassurez-vous, il ne sera pas n\u00e9cessaire de remplacer vos bornes aussi fr\u00e9quemment que votre t\u00e9l\u00e9phone ! La technologie des bornes de recharge est d\u00e9j\u00e0 mature, et les \u00e9quipements dans lesquels vous investissez aujourd&rsquo;hui resteront pertinents pendant de nombreuses ann\u00e9es. M\u00eame si les voitures \u00e9lectriques continueront d&rsquo;\u00e9voluer, le besoin de recharge demeurera constant. En effet, les bornes de 7kW et 22kW permettent respectivement de recharger 40km et 130km par heure, ce qui assure une recharge rapide et adapt\u00e9e \u00e0 l&rsquo;autonomie quotidienne requise.<\/p><p>Toutefois, certains aspects des bornes de recharge sont susceptibles d&rsquo;\u00e9voluer, notamment la bidirectionnalit\u00e9 de la charge et l&rsquo;exploitation des donn\u00e9es pour optimiser la consommation \u00e9nerg\u00e9tique.<\/p><h6>Dans ces domaines, les bornes communicantes propos\u00e9es par Time2plug sont d\u00e9j\u00e0 \u00e0 la pointe de la technologie !<\/h6><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-24411\" class=\"elementor-tab-title\" data-tab=\"11\" role=\"button\" aria-controls=\"elementor-tab-content-24411\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Est-ce que les bornes tombent souvent en panne ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-24411\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"11\" role=\"region\" aria-labelledby=\"elementor-tab-title-24411\"><p>En moyenne, une borne de recharge affiche un taux de fonctionnement d&rsquo;environ 95% de sa dur\u00e9e de vie. Cette performance est largement attribuable \u00e0 l&rsquo;usage d&rsquo;outils de supervision qui facilitent une maintenance \u00e0 distance. De plus, gr\u00e2ce \u00e0 un r\u00e9seau d&rsquo;installateurs locaux r\u00e9actifs, les d\u00e9lais d&rsquo;intervention sont minimis\u00e9s, contribuant ainsi \u00e0 r\u00e9duire les p\u00e9riodes d&rsquo;indisponibilit\u00e9.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-24412\" class=\"elementor-tab-title\" data-tab=\"12\" role=\"button\" aria-controls=\"elementor-tab-content-24412\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quelle est la rapidit\u00e9 d\u2019intervention d\u2019un installateur\/op\u00e9rateur en cas de panne ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-24412\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"12\" role=\"region\" aria-labelledby=\"elementor-tab-title-24412\"><p>Le premier sc\u00e9nario concerne les bornes non supervis\u00e9es. Dans ce contexte, Time2plug garantit une intervention sous 48h partout en France, gr\u00e2ce \u00e0 son vaste r\u00e9seau d&rsquo;installateurs locaux.<\/p><p>Le deuxi\u00e8me cas concerne les bornes communicantes dot\u00e9es d&rsquo;un outil de supervision. D\u00e8s qu&rsquo;une anomalie est d\u00e9tect\u00e9e, Time2plug est alert\u00e9 instantan\u00e9ment. Dans 30% des situations, une intervention \u00e0 distance suffit pour r\u00e9tablir le bon fonctionnement de la borne. Pour les cas n\u00e9cessitant une intervention sur site, un technicien est d\u00e9p\u00each\u00e9 dans les 48h.<\/p><h6><strong>Cette r\u00e9activit\u00e9 permet non seulement de r\u00e9duire le temps d&rsquo;indisponibilit\u00e9, mais aussi d&rsquo;\u00e9viter tout d\u00e9sagr\u00e9ment avec les clients ou le personnel du site.<\/strong><\/h6><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-24413\" class=\"elementor-tab-title\" data-tab=\"13\" role=\"button\" aria-controls=\"elementor-tab-content-24413\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quels sont les modes de facturation que je peux mettre en place ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-24413\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"13\" role=\"region\" aria-labelledby=\"elementor-tab-title-24413\"><p>Les bornes de recharge offrent la possibilit\u00e9 de diversifier vos sources de revenus en refacturant la charge \u00e0 vos clients. Plusieurs m\u00e9thodes de facturation sont envisageables :<\/p><ol><li><p><span style=\"text-decoration: underline;\"><strong>Forfait simple<\/strong> :<\/span> Vous pouvez \u00e9tablir un tarif fixe pour une session de charge, par exemple 8 euros.<\/p><\/li><li><p><span style=\"text-decoration: underline;\"><strong>Facturation \u00e0 la consommation<\/strong> :<\/span> Gr\u00e2ce \u00e0 un outil de supervision, vous acc\u00e9dez aux donn\u00e9es de charge de vos bornes. Ainsi, \u00e0 la fin de chaque session, vous pouvez facturer la consommation r\u00e9elle de vos clients en y ajoutant une marge sur l&rsquo;\u00e9nergie fournie.<\/p><\/li><li><p><span style=\"text-decoration: underline;\"><strong>eMSP (Energy Management Service Provider)<\/strong> :<\/span> Vous pouvez confier la facturation \u00e0 un eMSP, un tiers sp\u00e9cialis\u00e9. L&rsquo;eMSP prend en charge la facturation de vos clients, puis vous reverse les b\u00e9n\u00e9fices apr\u00e8s avoir pr\u00e9lev\u00e9 une commission sur l&rsquo;\u00e9nergie consomm\u00e9e. La recharge est activ\u00e9e par un QR code ou une carte RFID propre \u00e0 l&rsquo;eMSP.<\/p><\/li><li><p><span style=\"text-decoration: underline;\"><strong>Gestion externalis\u00e9e<\/strong> :<\/span> Vous pouvez aussi confier la gestion de vos bornes \u00e0 un prestataire externe. Dans ce cas, cet acteur tiers loue vos emplacements de parking, installe les bornes et assure la gestion du parc. Cependant, cette option limite votre contr\u00f4le sur la gestion et peut entra\u00eener des probl\u00e8mes relationnels avec vos clients.<\/p><\/li><\/ol><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-24414\" class=\"elementor-tab-title\" data-tab=\"14\" role=\"button\" aria-controls=\"elementor-tab-content-24414\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Comment les bornes me permettent-elles de communiquer sur mes engagements RSE ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-24414\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"14\" role=\"region\" aria-labelledby=\"elementor-tab-title-24414\"><h6>Gr\u00e2ce \u00e0 des outils de supervision avanc\u00e9s comme evAdvisor, que Time2plug utilise, vous pouvez mesurer l&rsquo;autonomie recharg\u00e9e par vos bornes.<\/h6><p>\u00a0Ces donn\u00e9es vous permettent de quantifier la r\u00e9duction des \u00e9missions de CO2 en \u00e9vitant la combustion d&rsquo;essence. Vous disposez ainsi d&rsquo;une information pr\u00e9cieuse pour valoriser vos actions \u00e9cologiques dans votre communication.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-24415\" class=\"elementor-tab-title\" data-tab=\"15\" role=\"button\" aria-controls=\"elementor-tab-content-24415\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Comment \u00e9viter les voitures ventouses ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-24415\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"15\" role=\"region\" aria-labelledby=\"elementor-tab-title-24415\"><div data-index=\"1\"><p>Les voitures ventouses repr\u00e9sentent un enjeu financier pour les propri\u00e9taires de bornes de recharge. Plusieurs solutions peuvent \u00eatre envisag\u00e9es pour contrer ce probl\u00e8me. Toutefois, la plus efficace demeure la tarification dissuasive.\u00a0<\/p><h6>Avec un outil de supervision, vous pouvez mettre en place une facturation pour les utilisateurs de v\u00e9hicules \u00e9lectriques qui occupent une place sans se charger, incitant ainsi une rotation plus rapide des emplacements.<\/h6><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-24416\" class=\"elementor-tab-title\" data-tab=\"16\" role=\"button\" aria-controls=\"elementor-tab-content-24416\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quels sont les \u00e9l\u00e9ments techniques n\u00e9cessaires pour que T2P puisse vous envoyer une offre ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-24416\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"16\" role=\"region\" aria-labelledby=\"elementor-tab-title-24416\"><div data-index=\"1\"><h6>Pour r\u00e9aliser une \u00e9tude et \u00e9tablir un chiffrage pr\u00e9cis, Time2plug requiert plusieurs informations de votre part :<\/h6><ul><li>Des photos de votre TGBT, des places de parking \u00e0 \u00e9quiper, ainsi que du passage des c\u00e2bles.<\/li><li>Votre consommation \u00e9lectrique, incluant la puissance souscrite et les pics de consommation. Ces donn\u00e9es sont disponibles sur votre facture ou directement sur votre compteur.<\/li><li>Les sp\u00e9cifications des bornes souhait\u00e9es, que ce soit en termes de puissance (7kW ou 22kW) et de fonctionnalit\u00e9s (communicantes ou non).<\/li><\/ul><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-24417\" class=\"elementor-tab-title\" data-tab=\"17\" role=\"button\" aria-controls=\"elementor-tab-content-24417\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Si je r\u00e9nove mon site, que dois-je pr\u00e9voir pour installer des bornes par la suite ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-24417\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"17\" role=\"region\" aria-labelledby=\"elementor-tab-title-24417\"><p>Lors d&rsquo;une r\u00e9novation en cours, il est judicieux d&rsquo;anticiper l&rsquo;installation future de bornes de recharge. Une \u00e9tape cl\u00e9 consiste \u00e0 poser un fourreau entre votre TGBT (Tableau G\u00e9n\u00e9ral Basse Tension) et votre parking.\u00a0<\/p><h6>Cette d\u00e9marche facilitera le passage des c\u00e2bles n\u00e9cessaires \u00e0 l&rsquo;alimentation des bornes plus tard.<\/h6><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"Quelles bornes de recharge choisir pour un h\\u00f4tel?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>L&rsquo;installation d&rsquo;une borne de recharge dans un h\\u00f4tel attire une fr\\u00e9quence d&rsquo;utilisation \\u00e9lev\\u00e9e. Il est donc essentiel de choisir un mat\\u00e9riel de qualit\\u00e9, issu de grandes marques reconnues pour garantir fiabilit\\u00e9 et durabilit\\u00e9. De plus, il est crucial de collaborer avec un op\\u00e9rateur capable de g\\u00e9rer les acc\\u00e8s, la maintenance, ainsi que la consommation et la facturation.<\\\/p><p>Pour accueillir du public, que ce soit en haute ou en basse saison, il est recommand\\u00e9 d&rsquo;opter pour des bornes 22kW. Ces bornes permettent un rechargement rapide, atteignant jusqu&rsquo;\\u00e0 130km\\\/h. De plus, un syst\\u00e8me de supervision avanc\\u00e9 est n\\u00e9cessaire pour g\\u00e9rer efficacement les flux \\u00e9nerg\\u00e9tiques et mon\\u00e9tiques.<\\\/p><h6>Si votre objectif est simplement de proposer la recharge \\u00e0 vos clients, une borne 7kW est suffisante. Cette borne offre un rechargement \\u00e0 40 km\\\/h, permettant une recharge compl\\u00e8te de la batterie pendant la nuit.<\\\/h6>\"}},{\"@type\":\"Question\",\"name\":\"Qui peut poser des bornes de recharge?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Le professionnel en charge du pr\\u00e9-\\u00e9quipement ou de l&rsquo;installation de la borne de recharge dans un h\\u00f4tel doit poss\\u00e9der la qualification IRVE, reconnue par un organisme accr\\u00e9dit\\u00e9.<\\\/p><p>Cette qualification est exig\\u00e9e par le programme ADVENIR.<\\\/p><h6>Deux organismes sont habilit\\u00e9s \\u00e0 d\\u00e9livrer cette qualification : Qualifec et l&rsquo;AFNOR (Association Fran\\u00e7aise de Normalisation).<\\\/h6>\"}},{\"@type\":\"Question\",\"name\":\"Comment les bornes de recharge peuvent-elles aider \\u00e0 toucher une client\\u00e8le plus large ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>La pr\\u00e9sence de bornes de recharge renforce votre visibilit\\u00e9 non seulement sur les sites de r\\u00e9servation, mais aussi sur les \\u00ab\\u00a0<span style=\\\"text-decoration: underline;\\\"><a href=\\\"https:\\\/\\\/fr.chargemap.com\\\/map\\\">charge maps<\\\/a><\\\/span>\\u00ab\\u00a0, fr\\u00e9quent\\u00e9es par de nombreux utilisateurs de v\\u00e9hicules \\u00e9lectriques. De plus, cela positionne votre \\u00e9tablissement comme \\u00e9tant en phase avec les tendances \\u00e9cologiques actuelles, attirant ainsi les clients soucieux de l&rsquo;environnement.\\u00a0<\\\/p><h6>C&rsquo;est \\u00e9galement un excellent moyen de fid\\u00e9liser votre client\\u00e8le existante en leur offrant un service pratique et moderne.<\\\/h6>\"}},{\"@type\":\"Question\",\"name\":\"Comment peut-on mettre en place une refacturation pour la recharge des bornes \\u00e9lectriques \\u00e0 ses clients ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Avec un suivi pr\\u00e9cis des charges gr\\u00e2ce \\u00e0 un outil de supervision, vous pouvez facilement refacturer vos clients. Plusieurs mod\\u00e8les de tarification sont envisageables :<\\\/p><ul><li style=\\\"list-style-type: none;\\\"><ul><li><span style=\\\"text-decoration: underline;\\\"><strong>Au forfait :<\\\/strong><\\\/span> offrez un tarif bas\\u00e9 sur la dur\\u00e9e de la recharge, que ce soit pour 1 heure, 2 heures ou une recharge nocturne.<\\\/li><li><span style=\\\"text-decoration: underline;\\\"><strong>\\u00c0 la consommation :<\\\/strong><\\\/span> ajoutez une marge sur l&rsquo;\\u00e9nergie fournie au v\\u00e9hicule \\u00e9lectrique, refl\\u00e9tant ainsi la quantit\\u00e9 d&rsquo;\\u00e9lectricit\\u00e9 utilis\\u00e9e.<\\\/li><\\\/ul><\\\/li><\\\/ul>\"}},{\"@type\":\"Question\",\"name\":\"Comment peut-on g\\u00e9rer l'acc\\u00e8s aux bornes de recharge sur son parking ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>L&rsquo;acc\\u00e8s aux bornes est soigneusement g\\u00e9r\\u00e9 par un outil de supervision utilisant des <span style=\\\"text-decoration: underline;\\\"><a href=\\\"https:\\\/\\\/www.mooncard.co\\\/fr\\\/cas-usage\\\/flotte-auto\\\/voiture-electrique\\\/borne-recharge\\\/rfid\\\">badges RFID<\\\/a><\\\/span>. Ces cartes, configur\\u00e9es lors de l&rsquo;installation, activent la charge et permettent de suivre pr\\u00e9cis\\u00e9ment la recharge de chaque client.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Quel est le co\\u00fbt d'un contrat de supervision par an ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Le co\\u00fbt d&rsquo;un forfait de supervision varie selon l&rsquo;op\\u00e9rateur et le niveau de supervision choisi.<\\\/p><h6>Chez Time2plug, le forfait s&rsquo;\\u00e9l\\u00e8ve \\u00e0 156\\u20ac par point de charge pour les bornes priv\\u00e9es et \\u00e0 192\\u20ac pour les bornes publiques.<\\\/h6>\"}},{\"@type\":\"Question\",\"name\":\"Quel est le co\\u00fbt d'un contrat de maintenance par an ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Le co\\u00fbt de cette prestation peut varier en fonction de l&rsquo;op\\u00e9rateur. Chez Time2plug, la maintenance est factur\\u00e9e entre 50 et 100 euros par point de charge annuellement, selon la taille du site.<\\\/p><p>Un technicien IRVE est un \\u00e9lectricien sp\\u00e9cialement form\\u00e9 en infrastructure de recharge pour v\\u00e9hicules \\u00e9lectriques. Contrairement \\u00e0 d&rsquo;autres \\u00e9lectriciens, tous ne suivent pas cette formation et n&rsquo;ont pas les comp\\u00e9tences requises pour installer une borne de recharge en entreprise.<\\\/p><p>En faisant appel \\u00e0 un technicien IRVE, vous garantissez une installation s\\u00e9curis\\u00e9e et une r\\u00e9paration ad\\u00e9quate en cas de panne.<\\\/p><h6>Il est \\u00e9galement crucial d&rsquo;avoir un syst\\u00e8me de supervision dans votre entreprise. Cela permet non seulement de maintenir les bornes \\u00e0 jour mais aussi de d\\u00e9tecter et r\\u00e9soudre les pannes \\u00e0 distance.<\\\/h6>\"}},{\"@type\":\"Question\",\"name\":\"Quelle est la dur\\u00e9e du projet, de la d\\u00e9finition du besoin \\u00e0 l'installation de la borne ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>La r\\u00e9alisation du projet est assez rapide, de la premi\\u00e8re prise de contact \\u00e0 la livraison de la solution cl\\u00e9 en main.<\\\/p><p>Chez Time2plug, nous nous engageons \\u00e0 vous fournir un devis complet en seulement 5 jours, en fonction de la d\\u00e9finition de vos besoins. De plus, une fois l&rsquo;acompte re\\u00e7u, l&rsquo;installation est r\\u00e9alis\\u00e9e en 10 jours.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Quelle est la dur\\u00e9e de vie d'une borne de recharge ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Les bornes de recharge sont con\\u00e7ues pour \\u00eatre solides et durables, avec une esp\\u00e9rance de vie d&rsquo;environ une dizaine d&rsquo;ann\\u00e9es. Ce long\\u00e9vit\\u00e9 est en grande partie due \\u00e0 l&rsquo;absence d&rsquo;obsolescence programm\\u00e9e et \\u00e0 l&rsquo;absence de composants m\\u00e9caniques susceptibles de s&rsquo;user.<\\\/p><h6>Pour maximiser la dur\\u00e9e de vie de vos bornes de recharge, voici quelques mesures recommand\\u00e9es :<\\\/h6><ul><li>Contractez un contrat de maintenance avec votre installateur, m\\u00eame au-del\\u00e0 des 3 ans exig\\u00e9s par Advenir.<\\\/li><li>Mettez en place un syst\\u00e8me de supervision pour effectuer une maintenance pr\\u00e9ventive.<\\\/li><li>Assurez une utilisation cadr\\u00e9e de vos bornes gr\\u00e2ce \\u00e0 un contr\\u00f4le d&rsquo;acc\\u00e8s rigoureux, pr\\u00e9venant ainsi les mauvaises utilisations.<\\\/li><li>Optez pour un partenaire de confiance comme Time2plug, qui vous propose des bornes de qualit\\u00e9 install\\u00e9es par des professionnels qualifi\\u00e9s.<\\\/li><\\\/ul>\"}},{\"@type\":\"Question\",\"name\":\"La technologie va-t-elle \\u00e9voluer dans les ann\\u00e9es \\u00e0 venir ? Est-ce que les bornes que j'ach\\u00e8te aujourd'hui deviendront obsol\\u00e8tes rapidement ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Rassurez-vous, il ne sera pas n\\u00e9cessaire de remplacer vos bornes aussi fr\\u00e9quemment que votre t\\u00e9l\\u00e9phone ! La technologie des bornes de recharge est d\\u00e9j\\u00e0 mature, et les \\u00e9quipements dans lesquels vous investissez aujourd&rsquo;hui resteront pertinents pendant de nombreuses ann\\u00e9es. M\\u00eame si les voitures \\u00e9lectriques continueront d&rsquo;\\u00e9voluer, le besoin de recharge demeurera constant. En effet, les bornes de 7kW et 22kW permettent respectivement de recharger 40km et 130km par heure, ce qui assure une recharge rapide et adapt\\u00e9e \\u00e0 l&rsquo;autonomie quotidienne requise.<\\\/p><p>Toutefois, certains aspects des bornes de recharge sont susceptibles d&rsquo;\\u00e9voluer, notamment la bidirectionnalit\\u00e9 de la charge et l&rsquo;exploitation des donn\\u00e9es pour optimiser la consommation \\u00e9nerg\\u00e9tique.<\\\/p><h6>Dans ces domaines, les bornes communicantes propos\\u00e9es par Time2plug sont d\\u00e9j\\u00e0 \\u00e0 la pointe de la technologie !<\\\/h6>\"}},{\"@type\":\"Question\",\"name\":\"Est-ce que les bornes tombent souvent en panne ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>En moyenne, une borne de recharge affiche un taux de fonctionnement d&rsquo;environ 95% de sa dur\\u00e9e de vie. Cette performance est largement attribuable \\u00e0 l&rsquo;usage d&rsquo;outils de supervision qui facilitent une maintenance \\u00e0 distance. De plus, gr\\u00e2ce \\u00e0 un r\\u00e9seau d&rsquo;installateurs locaux r\\u00e9actifs, les d\\u00e9lais d&rsquo;intervention sont minimis\\u00e9s, contribuant ainsi \\u00e0 r\\u00e9duire les p\\u00e9riodes d&rsquo;indisponibilit\\u00e9.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Quelle est la rapidit\\u00e9 d\\u2019intervention d\\u2019un installateur\\\/op\\u00e9rateur en cas de panne ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Le premier sc\\u00e9nario concerne les bornes non supervis\\u00e9es. Dans ce contexte, Time2plug garantit une intervention sous 48h partout en France, gr\\u00e2ce \\u00e0 son vaste r\\u00e9seau d&rsquo;installateurs locaux.<\\\/p><p>Le deuxi\\u00e8me cas concerne les bornes communicantes dot\\u00e9es d&rsquo;un outil de supervision. D\\u00e8s qu&rsquo;une anomalie est d\\u00e9tect\\u00e9e, Time2plug est alert\\u00e9 instantan\\u00e9ment. Dans 30% des situations, une intervention \\u00e0 distance suffit pour r\\u00e9tablir le bon fonctionnement de la borne. Pour les cas n\\u00e9cessitant une intervention sur site, un technicien est d\\u00e9p\\u00each\\u00e9 dans les 48h.<\\\/p><h6><strong>Cette r\\u00e9activit\\u00e9 permet non seulement de r\\u00e9duire le temps d&rsquo;indisponibilit\\u00e9, mais aussi d&rsquo;\\u00e9viter tout d\\u00e9sagr\\u00e9ment avec les clients ou le personnel du site.<\\\/strong><\\\/h6>\"}},{\"@type\":\"Question\",\"name\":\"Quels sont les modes de facturation que je peux mettre en place ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Les bornes de recharge offrent la possibilit\\u00e9 de diversifier vos sources de revenus en refacturant la charge \\u00e0 vos clients. Plusieurs m\\u00e9thodes de facturation sont envisageables :<\\\/p><ol><li><p><span style=\\\"text-decoration: underline;\\\"><strong>Forfait simple<\\\/strong> :<\\\/span> Vous pouvez \\u00e9tablir un tarif fixe pour une session de charge, par exemple 8 euros.<\\\/p><\\\/li><li><p><span style=\\\"text-decoration: underline;\\\"><strong>Facturation \\u00e0 la consommation<\\\/strong> :<\\\/span> Gr\\u00e2ce \\u00e0 un outil de supervision, vous acc\\u00e9dez aux donn\\u00e9es de charge de vos bornes. Ainsi, \\u00e0 la fin de chaque session, vous pouvez facturer la consommation r\\u00e9elle de vos clients en y ajoutant une marge sur l&rsquo;\\u00e9nergie fournie.<\\\/p><\\\/li><li><p><span style=\\\"text-decoration: underline;\\\"><strong>eMSP (Energy Management Service Provider)<\\\/strong> :<\\\/span> Vous pouvez confier la facturation \\u00e0 un eMSP, un tiers sp\\u00e9cialis\\u00e9. L&rsquo;eMSP prend en charge la facturation de vos clients, puis vous reverse les b\\u00e9n\\u00e9fices apr\\u00e8s avoir pr\\u00e9lev\\u00e9 une commission sur l&rsquo;\\u00e9nergie consomm\\u00e9e. La recharge est activ\\u00e9e par un QR code ou une carte RFID propre \\u00e0 l&rsquo;eMSP.<\\\/p><\\\/li><li><p><span style=\\\"text-decoration: underline;\\\"><strong>Gestion externalis\\u00e9e<\\\/strong> :<\\\/span> Vous pouvez aussi confier la gestion de vos bornes \\u00e0 un prestataire externe. Dans ce cas, cet acteur tiers loue vos emplacements de parking, installe les bornes et assure la gestion du parc. Cependant, cette option limite votre contr\\u00f4le sur la gestion et peut entra\\u00eener des probl\\u00e8mes relationnels avec vos clients.<\\\/p><\\\/li><\\\/ol>\"}},{\"@type\":\"Question\",\"name\":\"Comment les bornes me permettent-elles de communiquer sur mes engagements RSE ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<h6>Gr\\u00e2ce \\u00e0 des outils de supervision avanc\\u00e9s comme evAdvisor, que Time2plug utilise, vous pouvez mesurer l&rsquo;autonomie recharg\\u00e9e par vos bornes.<\\\/h6><p>\\u00a0Ces donn\\u00e9es vous permettent de quantifier la r\\u00e9duction des \\u00e9missions de CO2 en \\u00e9vitant la combustion d&rsquo;essence. Vous disposez ainsi d&rsquo;une information pr\\u00e9cieuse pour valoriser vos actions \\u00e9cologiques dans votre communication.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Comment \\u00e9viter les voitures ventouses ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<div data-index=\\\"1\\\"><p>Les voitures ventouses repr\\u00e9sentent un enjeu financier pour les propri\\u00e9taires de bornes de recharge. Plusieurs solutions peuvent \\u00eatre envisag\\u00e9es pour contrer ce probl\\u00e8me. Toutefois, la plus efficace demeure la tarification dissuasive.\\u00a0<\\\/p><h6>Avec un outil de supervision, vous pouvez mettre en place une facturation pour les utilisateurs de v\\u00e9hicules \\u00e9lectriques qui occupent une place sans se charger, incitant ainsi une rotation plus rapide des emplacements.<\\\/h6><\\\/div>\"}},{\"@type\":\"Question\",\"name\":\"Quels sont les \\u00e9l\\u00e9ments techniques n\\u00e9cessaires pour que T2P puisse vous envoyer une offre ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<div data-index=\\\"1\\\"><h6>Pour r\\u00e9aliser une \\u00e9tude et \\u00e9tablir un chiffrage pr\\u00e9cis, Time2plug requiert plusieurs informations de votre part :<\\\/h6><ul><li>Des photos de votre TGBT, des places de parking \\u00e0 \\u00e9quiper, ainsi que du passage des c\\u00e2bles.<\\\/li><li>Votre consommation \\u00e9lectrique, incluant la puissance souscrite et les pics de consommation. Ces donn\\u00e9es sont disponibles sur votre facture ou directement sur votre compteur.<\\\/li><li>Les sp\\u00e9cifications des bornes souhait\\u00e9es, que ce soit en termes de puissance (7kW ou 22kW) et de fonctionnalit\\u00e9s (communicantes ou non).<\\\/li><\\\/ul><\\\/div>\"}},{\"@type\":\"Question\",\"name\":\"Si je r\\u00e9nove mon site, que dois-je pr\\u00e9voir pour installer des bornes par la suite ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Lors d&rsquo;une r\\u00e9novation en cours, il est judicieux d&rsquo;anticiper l&rsquo;installation future de bornes de recharge. Une \\u00e9tape cl\\u00e9 consiste \\u00e0 poser un fourreau entre votre TGBT (Tableau G\\u00e9n\\u00e9ral Basse Tension) et votre parking.\\u00a0<\\\/p><h6>Cette d\\u00e9marche facilitera le passage des c\\u00e2bles n\\u00e9cessaires \\u00e0 l&rsquo;alimentation des bornes plus tard.<\\\/h6>\"}}]}<\/script>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/main>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4977c90 elementor-hidden-mobile elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4977c90\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f999244\" data-id=\"f999244\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a9693e3 elementor-widget elementor-widget-heading\" data-id=\"a9693e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"color: #061360\">Exemples<\/span>  d'installations<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-352d5b8 elementor-section-full_width elementor-section-stretched elementor-hidden-mobile elementor-hidden-desktop elementor-hidden-tablet elementor-section-height-default elementor-section-height-default\" data-id=\"352d5b8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8f7f17c\" data-id=\"8f7f17c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e1b45c elementor-widget__width-inherit elementor-pagination-type-bullets elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-loop-carousel\" data-id=\"5e1b45c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;template_id&quot;:12367,&quot;slides_to_show&quot;:&quot;1&quot;,&quot;slides_to_scroll&quot;:&quot;2&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:24,&quot;sizes&quot;:[]},&quot;_skin&quot;:&quot;post&quot;,&quot;slides_to_show_tablet&quot;:&quot;2&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;edit_handle_selector&quot;:&quot;.elementor-loop-container&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;offset_sides&quot;:&quot;none&quot;,&quot;arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"loop-carousel.post\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"swiper elementor-loop-container elementor-grid\" role=\"list\" dir=\"ltr\">\n\t\t\t\t<div class=\"swiper-wrapper\" aria-live=\"off\">\n\t\t<style id=\"loop-12367\">.elementor-12367 .elementor-element.elementor-element-53f9619 > .elementor-widget-wrap > .elementor-widget:not(.elementor-widget__width-auto):not(.elementor-widget__width-initial):not(:last-child):not(.elementor-absolute){margin-block-end:24px;}.elementor-12367 .elementor-element.elementor-element-53f9619 > .elementor-element-populated, .elementor-12367 .elementor-element.elementor-element-53f9619 > .elementor-element-populated > .elementor-background-overlay, .elementor-12367 .elementor-element.elementor-element-53f9619 > .elementor-background-slideshow{border-radius:16px 16px 16px 16px;}.elementor-12367 .elementor-element.elementor-element-53f9619 > .elementor-element-populated{box-shadow:0px 0px 5px 0px rgba(0, 0, 0, 0.15);margin:0px 0px 0px 0px;--e-column-margin-right:0px;--e-column-margin-left:0px;padding:24px 24px 24px 24px;}.elementor-12367 .elementor-element.elementor-element-e9d0952 img{border-radius:16px 16px 16px 16px;}.elementor-12367 .elementor-element.elementor-element-7e24dab{text-align:center;}.elementor-12367 .elementor-element.elementor-element-7e24dab .elementor-heading-title{font-family:\"Poppins\", Sans-serif;font-size:24px;font-weight:600;color:var( --e-global-color-c66035d );}.elementor-12367 .elementor-element.elementor-element-7e24dab > .elementor-widget-container{margin:0px 0px 0px 0px;padding:0px 0px 0px 0px;}.elementor-12367 .elementor-element.elementor-element-33d97fa .elementor-button-content-wrapper{flex-direction:row-reverse;}.elementor-12367 .elementor-element.elementor-element-33d97fa .elementor-button .elementor-button-content-wrapper{gap:8px;}.elementor-12367 .elementor-element.elementor-element-33d97fa .elementor-button{font-weight:600;background-color:var( --e-global-color-c66035d );}@media(max-width:1024px){.elementor-12367 .elementor-element.elementor-element-53f9619 > .elementor-element-populated{margin:0px 0px 0px 0px;--e-column-margin-right:0px;--e-column-margin-left:0px;padding:20px 20px 20px 20px;}}@media(min-width:768px){.elementor-12367 .elementor-element.elementor-element-53f9619{width:100%;}}<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"12367\" class=\"elementor elementor-12367 swiper-slide e-loop-item e-loop-item-16679 post-16679 post type-post status-publish format-standard has-post-thumbnail hentry category-cas-client entry has-media\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-efb23e1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"efb23e1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-53f9619\" data-id=\"53f9619\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e9d0952 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"e9d0952\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/06\/PICS-ETUDE-DE-CAS-300x300.png\" class=\"attachment-medium size-medium wp-image-16708\" alt=\"\" srcset=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/06\/PICS-ETUDE-DE-CAS-300x300.png 300w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/06\/PICS-ETUDE-DE-CAS-1024x1024.png 1024w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/06\/PICS-ETUDE-DE-CAS-150x150.png 150w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/06\/PICS-ETUDE-DE-CAS-768x768.png 768w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/06\/PICS-ETUDE-DE-CAS-600x600.png 600w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/06\/PICS-ETUDE-DE-CAS.png 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6dcb521 elementor-widget elementor-widget-theme-post-excerpt\" data-id=\"6dcb521\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-excerpt.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\tPasser d\u2019une installation brute \u00e0 une supervision intelligente des bornes : le pari r\u00e9ussi de SCAB. \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33d97fa elementor-align-right elementor-widget elementor-widget-button\" data-id=\"33d97fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.time2plug.com\/page\/de-linstallation-brute-a-une-supervision-intelligente-avec-time2plug-scab-prend-en-main-ses-infrastructures-de-recharge\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En savoir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"12367\" class=\"elementor elementor-12367 swiper-slide e-loop-item e-loop-item-16596 post-16596 post type-post status-publish format-standard has-post-thumbnail hentry category-cas-client entry has-media\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-efb23e1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"efb23e1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-53f9619\" data-id=\"53f9619\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e9d0952 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"e9d0952\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/05\/PICS-ETUDE-DE-CAS-300x300.jpg\" class=\"attachment-medium size-medium wp-image-16604\" alt=\"Borne de recharge Schneider Electric supervis\u00e9e par Time2plug sur le parking d\u2019un site industriel.\" srcset=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/05\/PICS-ETUDE-DE-CAS-300x300.jpg 300w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/05\/PICS-ETUDE-DE-CAS-1024x1024.jpg 1024w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/05\/PICS-ETUDE-DE-CAS-150x150.jpg 150w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/05\/PICS-ETUDE-DE-CAS-768x768.jpg 768w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/05\/PICS-ETUDE-DE-CAS-600x600.jpg 600w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/05\/PICS-ETUDE-DE-CAS.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6dcb521 elementor-widget elementor-widget-theme-post-excerpt\" data-id=\"6dcb521\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-excerpt.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\tModerniser sans tout changer : un site industriel fait confiance \u00e0 Time2plug pour sa supervision.\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33d97fa elementor-align-right elementor-widget elementor-widget-button\" data-id=\"33d97fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.time2plug.com\/page\/pilotage-bornes-de-recharge-site-industriel-sans-tout-changer-le-pari-reussi-dun-site-industriel-francais\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En savoir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"12367\" class=\"elementor elementor-12367 swiper-slide e-loop-item e-loop-item-16454 post-16454 post type-post status-publish format-standard has-post-thumbnail hentry category-cas-client entry has-media\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-efb23e1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"efb23e1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-53f9619\" data-id=\"53f9619\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e9d0952 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"e9d0952\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/04\/PICS-ETUDE-DE-CAS-1-300x300.jpg\" class=\"attachment-medium size-medium wp-image-16621\" alt=\"Borne de recharge \u00e9lectrique install\u00e9e sur un site industriel, avec marquage au sol et panneau de signalisation pour v\u00e9hicules \u00e9lectriques.\" srcset=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/04\/PICS-ETUDE-DE-CAS-1-300x300.jpg 300w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/04\/PICS-ETUDE-DE-CAS-1-1024x1024.jpg 1024w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/04\/PICS-ETUDE-DE-CAS-1-150x150.jpg 150w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/04\/PICS-ETUDE-DE-CAS-1-768x768.jpg 768w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/04\/PICS-ETUDE-DE-CAS-1-600x600.jpg 600w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/04\/PICS-ETUDE-DE-CAS-1.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6dcb521 elementor-widget elementor-widget-theme-post-excerpt\" data-id=\"6dcb521\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-excerpt.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\tUn tournant strat\u00e9gique : GSK opte pour la supervision et la facturation des recharges avec Time2plug.\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33d97fa elementor-align-right elementor-widget elementor-widget-button\" data-id=\"33d97fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.time2plug.com\/page\/passer-dun-acces-libre-a-une-supervision-irve-pour-bornes-existantes-gsk-adapte-son-reseau-de-bornes\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En savoir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"12367\" class=\"elementor elementor-12367 swiper-slide e-loop-item e-loop-item-16141 post-16141 post type-post status-publish format-standard has-post-thumbnail hentry category-campings category-entreprises category-hotels category-installation-borne-de-recharge category-restaurants entry has-media\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-efb23e1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"efb23e1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-53f9619\" data-id=\"53f9619\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e9d0952 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"e9d0952\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/03\/parking-souterrain-moderne-300x200.jpg\" class=\"attachment-medium size-medium wp-image-16143\" alt=\"parking souterrain moderne, spacieux et bien \u00e9clair\u00e9, avec une ambiance futuriste accentu\u00e9e par des lumi\u00e8res bleut\u00e9es.\" srcset=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/03\/parking-souterrain-moderne-300x200.jpg 300w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/03\/parking-souterrain-moderne-768x513.jpg 768w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/03\/parking-souterrain-moderne.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6dcb521 elementor-widget elementor-widget-theme-post-excerpt\" data-id=\"6dcb521\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-excerpt.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p>L\u2019expansion de la mobilit\u00e9 \u00e9lectrique d\u00e9pend g\u00e9n\u00e9ralement de l\u2019efficacit\u00e9 et de l\u2019accessibilit\u00e9 du r\u00e9seau de recharge. N\u00e9anmoins, les r\u00e9gions rurales doivent faire face \u00e0 certains d\u00e9fis majeurs lorsqu\u2019il s\u2019agit de leur surveillance et d&rsquo;une mise en \u0153uvre rentable. Bornes de recharge en sous-sol : un d\u00e9fi technique \u00e0 relever. Alors bornes de recharge en sous-sol [&hellip;]<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33d97fa elementor-align-right elementor-widget elementor-widget-button\" data-id=\"33d97fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.time2plug.com\/page\/bornes-de-recharge-en-sous-sol-un-defi-technique-a-relever\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En savoir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Pr\u00e9c\u00e9dent\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t<\/div>\n\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Suivant\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t<\/div>\n\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e83454f elementor-section-full_width elementor-section-content-middle elementor-hidden-mobile elementor-hidden-desktop elementor-hidden-tablet elementor-section-height-default elementor-section-height-default\" data-id=\"e83454f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-55fe46e\" data-id=\"55fe46e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c2b25e elementor-align-center elementor-widget__width-inherit elementor-widget elementor-widget-button\" data-id=\"4c2b25e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"\/solutions-recharge\/parking?type=public\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">D\u00e9couvrir<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<main class=\"elementor-section elementor-top-section elementor-element elementor-element-22e624d elementor-section-full_width elementor-hidden-tablet elementor-section-height-default elementor-section-height-default\" data-id=\"22e624d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9f8f5d7\" data-id=\"9f8f5d7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8e850e6 elementor-widget elementor-widget-heading\" data-id=\"8e850e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"color:#061360\">  Derni\u00e8res actus<\/span> pour les h\u00f4tels :<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b8214f6 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"b8214f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.time2plug.com\/page\/category\/actualites\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae4c851 elementor-widget__width-auto elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-card-shadow-yes elementor-posts__hover-gradient elementor-widget elementor-widget-posts\" data-id=\"ae4c851\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;cards_columns&quot;:&quot;3&quot;,&quot;cards_columns_tablet&quot;:&quot;2&quot;,&quot;cards_columns_mobile&quot;:&quot;1&quot;,&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;cards_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cards_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-16113 post type-post status-publish format-standard has-post-thumbnail hentry category-campings category-entreprises category-hotels category-installation-borne-de-recharge category-restaurants entry has-media\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.time2plug.com\/page\/supervision-des-infrastructures-de-recharge-dans-les-zones-rurales\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/03\/bornes-de-recharge-installees-le-long-dune-route-rurale-300x169.png\" class=\"attachment-medium size-medium wp-image-16116\" alt=\"Bornes de recharge pour v\u00e9hicules \u00e9lectriques install\u00e9es le long d&#039;une route rurale bord\u00e9e de maisons en pierre, illustrant le d\u00e9veloppement des infrastructures de recharge en milieu rural.\" srcset=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/03\/bornes-de-recharge-installees-le-long-dune-route-rurale-300x169.png 300w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/03\/bornes-de-recharge-installees-le-long-dune-route-rurale-768x432.png 768w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/03\/bornes-de-recharge-installees-le-long-dune-route-rurale-800x450.png 800w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/03\/bornes-de-recharge-installees-le-long-dune-route-rurale.png 896w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Campings<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.time2plug.com\/page\/supervision-des-infrastructures-de-recharge-dans-les-zones-rurales\/\" >\n\t\t\t\tSupervision des infrastructures de recharge dans les zones rurales\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Alors l\u2019expansion de la mobilit\u00e9 \u00e9lectrique d\u00e9pend g\u00e9n\u00e9ralement de l\u2019efficacit\u00e9 et de l\u2019accessibilit\u00e9 du r\u00e9seau de recharge. N\u00e9anmoins, les r\u00e9gions rurales doivent faire face \u00e0 certains d\u00e9fis majeurs lorsqu\u2019il s\u2019agit<\/p>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.time2plug.com\/page\/supervision-des-infrastructures-de-recharge-dans-les-zones-rurales\/\" aria-label=\"En savoir plus sur Supervision des infrastructures de recharge dans les zones rurales\" tabindex=\"-1\" >\n\t\t\tLire la suite \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t17 mars 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-16069 post type-post status-publish format-standard has-post-thumbnail hentry category-campings category-entreprises category-hotels category-installation-borne-de-recharge category-restaurants entry has-media\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.time2plug.com\/page\/comment-les-avantages-en-nature-evoluent-ils-en-2025\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/03\/une-personne-en-costume-300x169.jpg\" class=\"attachment-medium size-medium wp-image-16078\" alt=\"Une personne en costume analysant des donn\u00e9es financi\u00e8res avec une calculatrice, un carnet de notes, des graphiques et des billets en euros sur un bureau, illustrant une gestion budg\u00e9taire ou comptable.\" srcset=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/03\/une-personne-en-costume-300x169.jpg 300w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/03\/une-personne-en-costume-768x432.jpg 768w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/03\/une-personne-en-costume-800x450.jpg 800w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/03\/une-personne-en-costume.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Campings<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.time2plug.com\/page\/comment-les-avantages-en-nature-evoluent-ils-en-2025\/\" >\n\t\t\t\tComment les avantages en nature \u00e9voluent-ils en 2025 ?\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Les avantages en nature li\u00e9s aux v\u00e9hicules de fonction ont connu une importante \u00e9volution avec l\u2019arr\u00eat\u00e9 du 25 f\u00e9vrier 2025, paru au Journal officiel. Ce texte modifie les modalit\u00e9s d&rsquo;\u00e9valuation<\/p>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.time2plug.com\/page\/comment-les-avantages-en-nature-evoluent-ils-en-2025\/\" aria-label=\"En savoir plus sur Comment les avantages en nature \u00e9voluent-ils en 2025 ?\" tabindex=\"-1\" >\n\t\t\tLire la suite \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t13 mars 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-16057 post type-post status-publish format-standard has-post-thumbnail hentry category-campings category-entreprises category-hotels category-installation-borne-de-recharge category-restaurants entry has-media\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.time2plug.com\/page\/nos-conseils-pour-une-transition-vers-une-flotte-electrique-comment-preparer-votre-entreprise\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/03\/Une-femme-utilise-son-smartphone-en-attendant-que-sa-voiture-electrique-se-recharge-avec-le-cable-branche-sur-la-borne-de-recharge-300x169.jpg\" class=\"attachment-medium size-medium wp-image-16058\" alt=\"Une femme utilise son smartphone en attendant que sa voiture \u00e9lectrique se recharge, avec le c\u00e2ble branch\u00e9 sur la borne de recharge.\" srcset=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/03\/Une-femme-utilise-son-smartphone-en-attendant-que-sa-voiture-electrique-se-recharge-avec-le-cable-branche-sur-la-borne-de-recharge-300x169.jpg 300w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/03\/Une-femme-utilise-son-smartphone-en-attendant-que-sa-voiture-electrique-se-recharge-avec-le-cable-branche-sur-la-borne-de-recharge-768x432.jpg 768w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/03\/Une-femme-utilise-son-smartphone-en-attendant-que-sa-voiture-electrique-se-recharge-avec-le-cable-branche-sur-la-borne-de-recharge-800x450.jpg 800w, https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/03\/Une-femme-utilise-son-smartphone-en-attendant-que-sa-voiture-electrique-se-recharge-avec-le-cable-branche-sur-la-borne-de-recharge.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Campings<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.time2plug.com\/page\/nos-conseils-pour-une-transition-vers-une-flotte-electrique-comment-preparer-votre-entreprise\/\" >\n\t\t\t\tNos conseils pour une transition vers une flotte \u00e9lectrique : comment pr\u00e9parer votre entreprise ?\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Avec la mont\u00e9e en puissance des r\u00e9glementations environnementales et la volont\u00e9 croissante des entreprises de r\u00e9duire leur empreinte carbone de leur flotte de v\u00e9hicules, la transition vers une flotte de<\/p>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.time2plug.com\/page\/nos-conseils-pour-une-transition-vers-une-flotte-electrique-comment-preparer-votre-entreprise\/\" aria-label=\"En savoir plus sur Nos conseils pour une transition vers une flotte \u00e9lectrique : comment pr\u00e9parer votre entreprise ?\" tabindex=\"-1\" >\n\t\t\tLire la suite \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t11 mars 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/main>\n\t\t\t\t<main class=\"elementor-section elementor-top-section elementor-element elementor-element-f853f03 elementor-section-full_width elementor-section-content-middle elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"f853f03\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d6ce8ae\" data-id=\"d6ce8ae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42b030d elementor-widget elementor-widget-heading\" data-id=\"42b030d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Un projet pour votre h\u00f4tel?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c7737d elementor-widget elementor-widget-text-editor\" data-id=\"7c7737d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Time2Plug se positionne comme votre partenaire de confiance pour concr\u00e9tiser vos projets futurs de bornes de recharge, en vous offrant un accompagnement personnalis\u00e9.<\/p><p>Avec Time2Plug, vous avez la libert\u00e9 de choisir votre organisme et d&rsquo;acc\u00e9der \u00e0 une page d\u00e9di\u00e9e sp\u00e9cifiquement \u00e0 celui-ci. Cette page regroupe toutes les informations essentielles pour vous aider \u00e0 prendre une d\u00e9cision \u00e9clair\u00e9e. En vous rendant sur cette page, vous avez la possibilit\u00e9 de renseigner directement vos informations client ou d&rsquo;explorer notre offre \u00e0 travers notre pr\u00e9sentation d\u00e9taill\u00e9e.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bed6790 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"bed6790\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/solutions-recharge\/parking?type=public\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ma solution personnalis\u00e9e<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/main>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Bornes de recharge pour h\u00f4tels Ma solution personnalis\u00e9e Bornes de recharge pour h\u00f4tels Ma solution personnalis\u00e9e L&rsquo;offre Time2plug pour les h\u00f4tels Sur mesure, simple, rapide, et cl\u00e9 en main.\u00a0 Etude de votre besoin : Remplissez notre questionnaire en ligne et b\u00e9n\u00e9ficier ainsi d&rsquo;un suivi personnalis\u00e9 par un de nos conseillers Time2plug. Incluant une \u00e9tude approfondie [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"ocean_front_end_style_editor":"no","ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"on","ocean_disable_heading":"default","ocean_post_title":"Bornes de recharge pour h\u00f4tels","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","footnotes":""},"class_list":["post-463","page","type-page","status-publish","hentry","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bornes de recharge pour les h\u00f4tels : installation et gestion<\/title>\n<meta name=\"description\" content=\"Equipez votre h\u00f4tel de bornes de recharge pour voitures \u00e9lectriques et augmentez vos revenus, votre visibilit\u00e9 et la satisfaction de vos clients.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.time2plug.com\/page\/borne-de-recharge-pour-hotels\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bornes de recharge pour les h\u00f4tels : installation et gestion\" \/>\n<meta property=\"og:description\" content=\"Equipez votre h\u00f4tel de bornes de recharge pour voitures \u00e9lectriques et augmentez vos revenus, votre visibilit\u00e9 et la satisfaction de vos clients.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.time2plug.com\/page\/borne-de-recharge-pour-hotels\/\" \/>\n<meta property=\"og:site_name\" content=\"Time2plug\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-05T08:09:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/04\/Frame-1274.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1384\" \/>\n\t<meta property=\"og:image:height\" content=\"1239\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"26 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/borne-de-recharge-pour-hotels\\\/\",\"url\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/borne-de-recharge-pour-hotels\\\/\",\"name\":\"Bornes de recharge pour les h\u00f4tels : installation et gestion\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/borne-de-recharge-pour-hotels\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/borne-de-recharge-pour-hotels\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Frame-1274.png\",\"datePublished\":\"2022-09-27T14:07:30+00:00\",\"dateModified\":\"2025-05-05T08:09:45+00:00\",\"description\":\"Equipez votre h\u00f4tel de bornes de recharge pour voitures \u00e9lectriques et augmentez vos revenus, votre visibilit\u00e9 et la satisfaction de vos clients.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/borne-de-recharge-pour-hotels\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.time2plug.com\\\/page\\\/borne-de-recharge-pour-hotels\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/borne-de-recharge-pour-hotels\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Frame-1274.png\",\"contentUrl\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Frame-1274.png\",\"width\":1384,\"height\":1239,\"caption\":\"Analyse, Installation et Gestion de borne de recharge\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/borne-de-recharge-pour-hotels\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"H\u00f4tels\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/#website\",\"url\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/\",\"name\":\"Time2plug\",\"description\":\"Installation et gestion de bornes recharge pour voitures \u00e9lectriques\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/#organization\"},\"alternateName\":\"Bornes de recharge pour voitures \u00e9lectriques\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/#organization\",\"name\":\"Time2plug\",\"alternateName\":\"Bornes de recharge pour voitures \u00e9lectriques\",\"url\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/T2P-Blanc_Background-Orange.png\",\"contentUrl\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/T2P-Blanc_Background-Orange.png\",\"width\":300,\"height\":300,\"caption\":\"Time2plug\"},\"image\":{\"@id\":\"https:\\\/\\\/www.time2plug.com\\\/page\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/time2plug\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bornes de recharge pour les h\u00f4tels : installation et gestion","description":"Equipez votre h\u00f4tel de bornes de recharge pour voitures \u00e9lectriques et augmentez vos revenus, votre visibilit\u00e9 et la satisfaction de vos clients.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.time2plug.com\/page\/borne-de-recharge-pour-hotels\/","og_locale":"fr_FR","og_type":"article","og_title":"Bornes de recharge pour les h\u00f4tels : installation et gestion","og_description":"Equipez votre h\u00f4tel de bornes de recharge pour voitures \u00e9lectriques et augmentez vos revenus, votre visibilit\u00e9 et la satisfaction de vos clients.","og_url":"https:\/\/www.time2plug.com\/page\/borne-de-recharge-pour-hotels\/","og_site_name":"Time2plug","article_modified_time":"2025-05-05T08:09:45+00:00","og_image":[{"width":1384,"height":1239,"url":"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/04\/Frame-1274.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"26 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.time2plug.com\/page\/borne-de-recharge-pour-hotels\/","url":"https:\/\/www.time2plug.com\/page\/borne-de-recharge-pour-hotels\/","name":"Bornes de recharge pour les h\u00f4tels : installation et gestion","isPartOf":{"@id":"https:\/\/www.time2plug.com\/page\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.time2plug.com\/page\/borne-de-recharge-pour-hotels\/#primaryimage"},"image":{"@id":"https:\/\/www.time2plug.com\/page\/borne-de-recharge-pour-hotels\/#primaryimage"},"thumbnailUrl":"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/04\/Frame-1274.png","datePublished":"2022-09-27T14:07:30+00:00","dateModified":"2025-05-05T08:09:45+00:00","description":"Equipez votre h\u00f4tel de bornes de recharge pour voitures \u00e9lectriques et augmentez vos revenus, votre visibilit\u00e9 et la satisfaction de vos clients.","breadcrumb":{"@id":"https:\/\/www.time2plug.com\/page\/borne-de-recharge-pour-hotels\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.time2plug.com\/page\/borne-de-recharge-pour-hotels\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.time2plug.com\/page\/borne-de-recharge-pour-hotels\/#primaryimage","url":"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/04\/Frame-1274.png","contentUrl":"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2024\/04\/Frame-1274.png","width":1384,"height":1239,"caption":"Analyse, Installation et Gestion de borne de recharge"},{"@type":"BreadcrumbList","@id":"https:\/\/www.time2plug.com\/page\/borne-de-recharge-pour-hotels\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.time2plug.com\/page\/"},{"@type":"ListItem","position":2,"name":"H\u00f4tels"}]},{"@type":"WebSite","@id":"https:\/\/www.time2plug.com\/page\/#website","url":"https:\/\/www.time2plug.com\/page\/","name":"Time2plug","description":"Installation et gestion de bornes recharge pour voitures \u00e9lectriques","publisher":{"@id":"https:\/\/www.time2plug.com\/page\/#organization"},"alternateName":"Bornes de recharge pour voitures \u00e9lectriques","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.time2plug.com\/page\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.time2plug.com\/page\/#organization","name":"Time2plug","alternateName":"Bornes de recharge pour voitures \u00e9lectriques","url":"https:\/\/www.time2plug.com\/page\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.time2plug.com\/page\/#\/schema\/logo\/image\/","url":"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/04\/T2P-Blanc_Background-Orange.png","contentUrl":"https:\/\/www.time2plug.com\/page\/wp-content\/uploads\/2025\/04\/T2P-Blanc_Background-Orange.png","width":300,"height":300,"caption":"Time2plug"},"image":{"@id":"https:\/\/www.time2plug.com\/page\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/time2plug\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.time2plug.com\/page\/wp-json\/wp\/v2\/pages\/463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.time2plug.com\/page\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.time2plug.com\/page\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.time2plug.com\/page\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.time2plug.com\/page\/wp-json\/wp\/v2\/comments?post=463"}],"version-history":[{"count":0,"href":"https:\/\/www.time2plug.com\/page\/wp-json\/wp\/v2\/pages\/463\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.time2plug.com\/page\/wp-json\/wp\/v2\/media?parent=463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}